{"id":32408,"date":"2022-07-08T00:36:02","date_gmt":"2022-07-07T15:36:02","guid":{"rendered":"https:\/\/gamepedia.jp\/mh-rise\/item\/32408"},"modified":"2022-07-31T05:05:54","modified_gmt":"2022-07-30T20:05:54","slug":"item-1312","status":"publish","type":"item","link":"https:\/\/gamepedia.jp\/mh-rise\/item\/32408","title":{"rendered":"\u3010\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u3011\u592a\u53e4\u9f8d\u9aa8\u306e\u4f7f\u3044\u9053\u30fb\u5165\u624b\u65b9\u6cd5\u3010\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011"},"content":{"rendered":"<p>\u300e\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30e9\u30a4\u30ba\u300f\u306b\u767b\u5834\u3059\u308b\u30a2\u30a4\u30c6\u30e0\u300c\u592a\u53e4\u9f8d\u9aa8\u300d\u306e\u653b\u7565\u60c5\u5831\u3092\u4ee5\u4e0b\u3067\u89e3\u8aac\u3057\u3066\u3044\u307e\u3059\u3002<\/p><div style=\"max-width:600px; margin:0 auto;\"><h2>\u300c\u592a\u53e4\u9f8d\u9aa8\u300d\u306e\u8a73\u7d30<\/h2><table style=\"margin-bottom:0;\"><thead><th>\u540d\u524d<\/th><th>\u6982\u8981<\/th><\/thead><tr><td style=\"text-align:center; width:30%;\">\u592a\u53e4\u9f8d\u9aa8<\/td><td>\u5927\u578b\u9f8d\u306e\u4e0a\u8cea\u306a\u9aa8\u3002\u8352\u3005\u3057\u304f\u3082\u3001\u53b3\u304b\u306a\u305d\u306e\u5f62\u306f\u60a0\u4e45\u306e\u6642\u3092\u611f\u3058\u3055\u305b\u308b\u3002<\/td><\/tr><\/table><table style=\"text-align:center; margin-top:-1px;\"><thead><th style=\"width:33%\">\u58f2\u5374\u4fa1\u683c<\/th><th style=\"width:33%\">\u6240\u6301\u6700\u5927\u6570<\/th><\/thead><tr><td>4000 z<\/td><td>99<\/td><\/tr><\/table><h2>\u6b66\u5668\u751f\u7523\u30fb\u5f37\u5316\u306b\u4f7f\u7528<\/h2><div class=\"text-s\">\u25bc \u30ec\u30a2\u30ea\u30c6\u30a3\u9806<\/div><table class=\"mhrise-table pc-font-material\" style=\"max-width:600px; margin:0 auto;\"><thead>\n                <th>\u540d\u524d <small>(\u653b\u6483\u529b\/\u5c5e\u6027)<\/small><\/th>\n                <th style=\"width:55%;\">\u751f\u7523\u7d20\u6750<\/th>\n            <\/thead><tbody><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u7247\u624b\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3162>\u30c7\u30e5\u30a2\u30eb\u30ab\u30e9\u30da\u30a4\u30b9\u6539<\/a><small> (310 \/ \u6c34 26)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_4.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1000\">\u53e4\u3073\u305f\u771f\u7d05\u306e\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1003\">\u938c\u87f9\u306e\u91cd\u811a<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u76fe\u87f9MR\u7d20\u6750<\/p><p class=\"table-weapon-right\">10 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30d8\u30d3\u30a3\u30dc\u30a6\u30ac\u30f3<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2761>\u91cd\u89d2\u7832\u30c7\u30a3\u30e2\u30cb\u30a2\u30fc\u30ab<\/a><small> (400)<\/small><br><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; margin:0 auto; width:80%;\"><p style=\"width:48%; padding:2px 0;\">\u30d6\u30ec<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u5de6\/\u5927<\/p><p style=\"width:48%; padding:2px 0;\">\u53cd\u52d5<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u4e2d<\/p><p style=\"width:48%; padding:2px 0;\">\u30ea\u30ed\u30fc\u30c9<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u9045\u3044<\/p><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1330\">\u5927\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u89d2\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">12 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u72e9\u731f\u7b1b<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2901>\u89d2\u738b\u7b1b\u30d6\u30ed\u30b9\u30d0\u30eb\u30c9\u30f3<\/a><small> (340)<\/small><br><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1330\">\u5927\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u89d2\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">12 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u64cd\u866b\u68cd<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3702>\u89d2\u738b\u621f\u30b9\u30bf\u30eb\u30ed\u30fc\u30ac<\/a><small> (350)<\/small><br><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:35%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:35%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-996\">\u5805\u7262\u306a\u306d\u3058\u308c\u305f\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1330\">\u5927\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u89d2\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">12 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30e9\u30f3\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3572>\u8f5f\u69cd\u3010\u5927\u72ec\u864e\u3011<\/a><small> (340)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1037\">\u8f5f\u7adc\u306e\u5929\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u8f5f\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">15 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30c1\u30e3\u30fc\u30b8\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2097>\u89d2\u738b\u76fe\u65a7\u30b8\u30aa\u30d6\u30ed\u30b9<\/a><small> (350)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:40%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:40%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1330\">\u5927\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u89d2\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">15 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5f13<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1937>\u30b0\u30ed\u30ba\u30cc\u30a3<\/a><small> (370)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><p>\u66f2\u5c04 : \u8010\u885d\u578b<\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap;\"><p style=\"width:50%; padding:2px 0;\"\">\u63a5\u6483\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u6e1b\u6c17\u30d3\u30f3<\/p><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1330\">\u5927\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u89d2\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">15 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30ac\u30f3\u30e9\u30f3\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2455>\u89d2\u738b\u9283\u69cd\u30a4\u30fc\u30e9\u30db\u30fc\u30f3<\/a><small> (340)<\/small><br><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1330\">\u5927\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u89d2\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">15 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30e9\u30f3\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3594>\u89d2\u738b\u69cd\u30b0\u30ec\u30aa\u30b9\u30db\u30fc\u30f3<\/a><small> (360)<\/small><br><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-996\">\u5805\u7262\u306a\u306d\u3058\u308c\u305f\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1330\">\u5927\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u89d2\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">10 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30d8\u30d3\u30a3\u30dc\u30a6\u30ac\u30f3<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2698>\u8f5f\u7832\u3010\u5927\u864e\u982d\u3011<\/a><small> (360)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; margin:0 auto; width:80%;\"><p style=\"width:48%; padding:2px 0;\">\u30d6\u30ec<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u53f3\/\u5927<\/p><p style=\"width:48%; padding:2px 0;\">\u53cd\u52d5<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u4e2d<\/p><p style=\"width:48%; padding:2px 0;\">\u30ea\u30ed\u30fc\u30c9<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u3084\u3084\u9045\u3044<\/p><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1037\">\u8f5f\u7adc\u306e\u5929\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u8f5f\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">15 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u53cc\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2210>\u30d6\u30ed\u30b9=\u30f4\u30a1\u30f3\u30c0\u30ed\u30b9<\/a><small> (350)<\/small><br><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1330\">\u5927\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u89d2\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">12 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u64cd\u866b\u68cd<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3646>\u3059\u304c\u306e\u306d\u306e\u9577\u591c\u83ef\u5c71\u8599<\/a><small> (310 \/ \u6c34 28)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#885AEC; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1116\">\u6ce1\u72d0\u7adc\u306e\u5929\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u6ce1\u72d0\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">10 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5927\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2291>\u8f5f\u5927\u5263\u3010\u5927\u738b\u864e\u3011<\/a><small> (340)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#885AEC; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1037\">\u8f5f\u7adc\u306e\u5929\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u8f5f\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">12 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5927\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2360>\u525b\u89d2\u5263\u30c7\u30a3\u30a2\u30d6\u30ed\u30b9<\/a><small> (360)<\/small><br><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1330\">\u5927\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u89d2\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">12 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u592a\u5200<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3254>D=\u30a4\u30a2\u30f3\u30ba\u6539<\/a><small> (300 \/ \u6c34 63)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1186\">\u6ce5\u7fc1\u7adc\u306e\u5929\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u6ce5\u7fc1\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">10 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5f13<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1904>D=\u30d0\u30eb\u30e9\u6539<\/a><small> (290 \/ \u6c34 46)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><p>\u66f2\u5c04 : \u8010\u885d\u578b<\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap;\"><p style=\"width:50%; padding:2px 0;\"\">\u63a5\u6483\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u7761\u7720\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u7206\u7834\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u6e1b\u6c17\u30d3\u30f3<\/p><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1186\">\u6ce5\u7fc1\u7adc\u306e\u5929\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u6ce5\u7fc1\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">10 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30e9\u30a4\u30c8\u30dc\u30a6\u30ac\u30f3<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3419>D=\u30c8\u30e9\u30af\u30bf\u6539<\/a><small> (310)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; margin:0 auto; width:80%;\"><p style=\"width:48%; padding:2px 0;\">\u30d6\u30ec<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u306a\u3057<\/p><p style=\"width:48%; padding:2px 0;\">\u53cd\u52d5<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u3084\u3084\u5c0f<\/p><p style=\"width:48%; padding:2px 0;\">\u30ea\u30ed\u30fc\u30c9<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u3084\u3084\u9045\u3044<\/p><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1186\">\u6ce5\u7fc1\u7adc\u306e\u5929\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u6ce5\u7fc1\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">10 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u53cc\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2144>D=\u30b9\u30e9\u30a4\u30b5\u30fc\u6539<\/a><small> (290 \/ \u6c34 59)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1186\">\u6ce5\u7fc1\u7adc\u306e\u5929\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u6ce5\u7fc1\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">10 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30c1\u30e3\u30fc\u30b8\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2063>\u591c\u8d70\u76fe\u65a7\u3010\u4e94\u6708\u95c7\u3011\u6539<\/a><small> (280)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#885AEC; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1044\">\u8fc5\u7adc\u306e\u5929\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u8fc5\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">15 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30cf\u30f3\u30de\u30fc<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2563>D=\u30d0\u30fc\u30b9\u30c8\u6539<\/a><small> (300 \/ \u6c34 69)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1186\">\u6ce5\u7fc1\u7adc\u306e\u5929\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1182\">\u6ce5\u7fc1\u7adc\u306e\u8c6a\u6bdb\u30d2\u30ec<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u6ce5\u7fc1\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">10 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u7247\u624b\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3211>\u30c6\u30aa=\u30a8\u30f3\u30d6\u30ec\u30e0\u6539<\/a><small> (330 \/ \u7206\u7834 40)<\/small><br><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1026\">\u708e\u738b\u9f8d\u306e\u91cd\u6bbb<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1030\">\u708e\u9f8d\u306e\u525b\u722a<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1031\">\u708e\u9f8d\u306e\u525b\u7ffc<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5f13<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1976>\u9b54\u5c0e\u5f13\u30a2\u30eb\u30de\u30c7\u30fc\u30eb\u6539<\/a><small> (350)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><p>\u66f2\u5c04 : \u56de\u5fa9\u578b<\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap;\"><p style=\"width:50%; padding:2px 0;\"\">\u63a5\u6483\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u5f37\u6483\u30d3\u30f3<\/p><p style=\"color:rgb(235, 96, 96); width:50%; padding:2px 0;\"><strong>\u6bd2\u30d3\u30f3<\/strong><\/p><p style=\"width:50%; padding:2px 0;\"\">\u9ebb\u75fa\u30d3\u30f3<\/p><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1025\">\u971e\u9f8d\u306e\u525b\u7ffc<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1022\">\u971e\u9f8d\u306e\u525b\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1021\">\u971e\u9f8d\u306e\u7279\u4e0a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 6<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30ac\u30f3\u30e9\u30f3\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2525>\u30d9\u30ca\u30e0\u30c7\u30c8\u30ef\u30ec\u6539<\/a><small> (320 \/ \u6bd2 36)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#885AEC; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1418\">\u30d4\u30e5\u30a2\u30af\u30ea\u30b9\u30bf\u30eb<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1022\">\u971e\u9f8d\u306e\u525b\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1021\">\u971e\u9f8d\u306e\u7279\u4e0a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30c1\u30e3\u30fc\u30b8\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2108>\u30c0\u30aa\u30e9=\u30b2\u30f3\u30e0\u6539<\/a><small> (310 \/ \u6c37 49)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1016\">\u92fc\u306e\u539a\u9f8d\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1017\">\u92fc\u9f8d\u306e\u525b\u7ffc<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1018\">\u92fc\u9f8d\u306e\u525b\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30e9\u30a4\u30c8\u30dc\u30a6\u30ac\u30f3<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3475>\u30db\u30fc\u30cd\u30b9=\u30c0\u30aa\u30e9\u6539<\/a><small> (320)<\/small><br><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; margin:0 auto; width:80%;\"><p style=\"width:48%; padding:2px 0;\">\u30d6\u30ec<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u5de6\u53f3\/\u5c0f<\/p><p style=\"width:48%; padding:2px 0;\">\u53cd\u52d5<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u6975\u5c0f<\/p><p style=\"width:48%; padding:2px 0;\">\u30ea\u30ed\u30fc\u30c9<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u3084\u3084\u9045\u3044<\/p><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1020\">\u92fc\u9f8d\u306e\u525b\u722a<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1018\">\u92fc\u9f8d\u306e\u525b\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1015\">\u92fc\u9f8d\u306e\u91cd\u6bbb<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30cf\u30f3\u30de\u30fc<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2669>\u5e7b\u60d1\u306e\u30c7\u30a3\u30a2\u30de\u30eb\u30c8\u6539<\/a><small> (310 \/ \u6bd2 37)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#885AEC; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1022\">\u971e\u9f8d\u306e\u525b\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1021\">\u971e\u9f8d\u306e\u7279\u4e0a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1024\">\u971e\u9f8d\u306e\u976d\u5c3e<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u64cd\u866b\u68cd<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3742>\u30af\u30a4\u30c9=\u30c0\u30aa\u30e9\u6539<\/a><small> (310 \/ \u6c37 46)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1016\">\u92fc\u306e\u539a\u9f8d\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1018\">\u92fc\u9f8d\u306e\u525b\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1019\">\u92fc\u9f8d\u306e\u976d\u5c3e<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30d8\u30d3\u30a3\u30dc\u30a6\u30ac\u30f3<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2795>\u30ab\u30fc\u30de\u30d2\u30c8\u30d0\u30fc\u30ec\u6539<\/a><small> (350)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; margin:0 auto; width:80%;\"><p style=\"width:48%; padding:2px 0;\">\u30d6\u30ec<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u5de6\u53f3\/\u5c0f<\/p><p style=\"width:48%; padding:2px 0;\">\u53cd\u52d5<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u4e2d<\/p><p style=\"width:48%; padding:2px 0;\">\u30ea\u30ed\u30fc\u30c9<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u3084\u3084\u901f\u3044<\/p><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1025\">\u971e\u9f8d\u306e\u525b\u7ffc<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1022\">\u971e\u9f8d\u306e\u525b\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1021\">\u971e\u9f8d\u306e\u7279\u4e0a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 6<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5927\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2384>\u30c0\u30aa\u30e9=\u30c7\u30b0\u30cb\u30c0\u30eb\u6539<\/a><small> (310 \/ \u6c37 57)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1016\">\u92fc\u306e\u539a\u9f8d\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1020\">\u92fc\u9f8d\u306e\u525b\u722a<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1017\">\u92fc\u9f8d\u306e\u525b\u7ffc<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u592a\u5200<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3321>\u96ea\u83ef\u306e\u30b9\u30ce\u30a6\u30d1\u30a6\u6539<\/a><small> (300 \/ \u6c37 65)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1330\">\u5927\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u6c37\u4eba\u9b5a\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">10 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30b9\u30e9\u30c3\u30b7\u30e5\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3068>\u30b8\u30e3\u30ca\u30d5=\u30c0\u30aa\u30e9\u6539<\/a><small> (310 \/ \u6c37 50)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#885AEC; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1016\">\u92fc\u306e\u539a\u9f8d\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1020\">\u92fc\u9f8d\u306e\u525b\u722a<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1017\">\u92fc\u9f8d\u306e\u525b\u7ffc<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u72e9\u731f\u7b1b<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2854>\u96ea\u83ef\u306e\u30b9\u30ce\u30a6\u30d5\u30a9\u30ed\u30a6\u6539<\/a><small> (310 \/ \u6c37 60)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1330\">\u5927\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1168\">\u6c37\u4eba\u9b5a\u7adc\u306e\u9aea\u30d2\u30ec<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u6c37\u4eba\u9b5a\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">8 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u53cc\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2228>\u96ea\u83ef\u306e\u30b9\u30ce\u30a6\u30af\u30ed\u30a6\u6539<\/a><small> (290 \/ \u6c37 62)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1330\">\u5927\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1167\">\u6c37\u4eba\u9b5a\u7adc\u306e\u51cd\u722a<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u6c37\u4eba\u9b5a\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">8 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30b9\u30e9\u30c3\u30b7\u30e5\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3070>\u30c6\u30aa=\u30ad\u30e3\u30c3\u30b9\u30eb\u6539<\/a><small> (320 \/ \u7206\u7834 45)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1030\">\u708e\u9f8d\u306e\u525b\u722a<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1031\">\u708e\u9f8d\u306e\u525b\u7ffc<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1029\">\u7344\u708e\u306e\u539a\u9f8d\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u72e9\u731f\u7b1b<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2935>\u30de\u30b8\u30ca\u30a4\u30aa\u30ab\u30ea\u30ca\u6539<\/a><small> (300 \/ \u6bd2 44)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:37.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:37.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1025\">\u971e\u9f8d\u306e\u525b\u7ffc<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1021\">\u971e\u9f8d\u306e\u7279\u4e0a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1024\">\u971e\u9f8d\u306e\u976d\u5c3e<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u7247\u624b\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3209>\u30a8\u30b9\u30c8\u30ec\u30e2=\u30c0\u30aa\u30e9\u6539<\/a><small> (300 \/ \u6c37 49)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#885AEC; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1016\">\u92fc\u306e\u539a\u9f8d\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1020\">\u92fc\u9f8d\u306e\u525b\u722a<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1015\">\u92fc\u9f8d\u306e\u91cd\u6bbb<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30b9\u30e9\u30c3\u30b7\u30e5\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3072>\u5e7b\u8996\u306e\u30d0\u30ed\u30fc\u30eb\u6539<\/a><small> (320 \/ \u6bd2 34)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#885AEC; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#885AEC;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1023\">\u971e\u9f8d\u306e\u525b\u722a<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1022\">\u971e\u9f8d\u306e\u525b\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1021\">\u971e\u9f8d\u306e\u7279\u4e0a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30cf\u30f3\u30de\u30fc<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2659>\u5375\u69cc\u30ac\u30fc\u30b0\u30a1\u6539<\/a><small> (360)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:45%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:45%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1300\">\u4e38\u9ce5\u306e\u7279\u4e0a\u7fbd<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1329\">\u5e7b\u9ce5\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><\/td><\/tr><\/tbody><\/table><style>\n    .table-weapon-cell{\n        display:flex;\n        flex-wrap:nowrap;\n        width:90%;\n        margin:0 auto;\n    }\n    .table-weapon-left{\n        margin:0px;\n        padding:2px;\n        width:80%;\n    }\n    .table-weapon-right{\n        margin:0px;\n        padding:2px;\n        text-align:left;\n        width:10%;\n        white-space:nowrap;\n    }\n    <\/style><h2>\u9632\u5177\u751f\u7523\u30fb\u5f37\u5316\u306b\u4f7f\u7528<\/h2><table class=\"mhrise-table\" style=\"max-width:600px; margin:0 auto;\"><thead>\n                <th style=\"width:50%;\">\u540d\u524d <small>(\u9632\u5fa1\u529b)<\/small><\/th>\n                <th style=\"width:50%;\">\u751f\u7523\u7d20\u6750<\/th>\n            <\/thead><tbody><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-1045><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #CC2C3F);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/head.png\" \/>\u62e0\u70b9\u53f8\u4ee4\u3010\u8033\u98fe\u3011<\/a> <small>(130)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-29>\u96c6\u4e2d<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 3<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-87>\u5e83\u57df\u5316<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 3<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1088\">\u5929\u5efb\u9f8d\u306e\u539a\u9c57<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1512\">\u738b\u56fd\u9a0e\u58eb\u56e3\u306e\u8a3c\u2162<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1421\">\u771f\u7d05\u84ee\u77f3<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-1052><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #F17427);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/head.png\" \/>\u30ae\u30eb\u30c9\u30d1\u30ec\u30b9\u30d8\u30eb\u30e0<\/a> <small>(132)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-2>\u6311\u6226\u8005<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-36>\u653b\u3081\u306e\u5b88\u52e2<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1538\">\u30eb\u30ca\u30ac\u30ed\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1540\">\u6fc0\u6602\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1542\">\u82f1\u96c4\u738b\u306e\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-917><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #CC2C3F);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/chest.png\" \/>\u62e0\u70b9\u53f8\u4ee4\u3010\u93a7\u3011<\/a> <small>(130)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-37>\u629c\u5200\u8853\u3010\u6280\u3011<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-120>\u30c1\u30e3\u30fc\u30b8\u30de\u30b9\u30bf\u30fc<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1479\">\u30e1\u30e9\u30f3\u30b8\u30a7\u9271\u77f3<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1512\">\u738b\u56fd\u9a0e\u58eb\u56e3\u306e\u8a3c\u2162<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1016\">\u92fc\u306e\u539a\u9f8d\u9c57<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-923><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #F17427);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/chest.png\" \/>\u30ae\u30eb\u30c9\u30d1\u30ec\u30b9\u30e1\u30a4\u30eb<\/a> <small>(132)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_4.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-2>\u6311\u6226\u8005<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-89>\u706b\u4e8b\u5834\u529b<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1538\">\u30eb\u30ca\u30ac\u30ed\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1540\">\u6fc0\u6602\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1542\">\u82f1\u96c4\u738b\u306e\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-731><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #F17427);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/arm.png\" \/>\u30df\u30c5\u30cf\u771f\u3010\u5927\u8896\u3011<\/a> <small>(134)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-17>\u6bd2\u5c5e\u6027\u5f37\u5316<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-64>\u56de\u907f\u6027\u80fd<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-107>\u971e\u76ae\u306e\u6069\u6075<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 3<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1228\">\u6bd2\u5996\u9ce5\u306e\u7279\u5927\u5589\u888b<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1021\">\u971e\u9f8d\u306e\u7279\u4e0a\u76ae<\/a><\/p><p class=\"table-armor-right\">x 5<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1024\">\u971e\u9f8d\u306e\u976d\u5c3e<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-796><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #CC2C3F);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/arm.png\" \/>\u62e0\u70b9\u53f8\u4ee4\u3010\u624b\u7532\u3011<\/a> <small>(130)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_4.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-39>\u7d0d\u5200\u8853<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-120>\u30c1\u30e3\u30fc\u30b8\u30de\u30b9\u30bf\u30fc<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1420\">\u30b4\u30eb\u30c9\u30e9\u30a4\u30c8\u9271\u77f3<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1246\">\u7206\u9c57\u7adc\u306e\u539a\u9c57<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1512\">\u738b\u56fd\u9a0e\u58eb\u56e3\u306e\u8a3c\u2162<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-802><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #F17427);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/arm.png\" \/>\u30ae\u30eb\u30c9\u30d1\u30ec\u30b9\u30a2\u30fc\u30e0<\/a> <small>(132)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_4.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-2>\u6311\u6226\u8005<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-116>\u707d\u798d\u8ee2\u798f<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-125>\u58c1\u9762\u79fb\u52d5\u3010\u7fd4\u3011<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1539\">\u30a8\u30b9\u30d4\u30ca\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1540\">\u6fc0\u6602\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1542\">\u82f1\u96c4\u738b\u306e\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-730><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #F17427);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/arm.png\" \/>\u30af\u30b7\u30e3\u30caX\u30cf\u30c8\u30a5\u30fc<\/a> <small>(134)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-2>\u6311\u6226\u8005<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-108>\u92fc\u6bbb\u306e\u6069\u6075<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1418\">\u30d4\u30e5\u30a2\u30af\u30ea\u30b9\u30bf\u30eb<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 3<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1016\">\u92fc\u306e\u539a\u9f8d\u9c57<\/a><\/p><p class=\"table-armor-right\">x 5<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1020\">\u92fc\u9f8d\u306e\u525b\u722a<\/a><\/p><p class=\"table-armor-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-1294><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #CC2C3F);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/waist.png\" \/>\u62e0\u70b9\u53f8\u4ee4\u3010\u5e2f\u7532\u3011<\/a> <small>(130)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_4.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-38>\u629c\u5200\u8853\u3010\u529b\u3011<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 3<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-39>\u7d0d\u5200\u8853<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1331\">\u53e4\u9f8d\u306e\u5927\u5b9d\u7389<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1512\">\u738b\u56fd\u9a0e\u58eb\u56e3\u306e\u8a3c\u2162<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1021\">\u971e\u9f8d\u306e\u7279\u4e0a\u76ae<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-1300><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #F17427);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/waist.png\" \/>\u30ae\u30eb\u30c9\u30d1\u30ec\u30b9\u30b3\u30a4\u30eb<\/a> <small>(132)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-36>\u653b\u3081\u306e\u5b88\u52e2<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-89>\u706b\u4e8b\u5834\u529b<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1539\">\u30a8\u30b9\u30d4\u30ca\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1538\">\u30eb\u30ca\u30ac\u30ed\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1542\">\u82f1\u96c4\u738b\u306e\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-1228><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #F17427);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/waist.png\" \/>\u30ab\u30a4\u30b6\u30fcX\u30b3\u30a4\u30eb<\/a> <small>(134)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-6>\u898b\u5207\u308a<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-109>\u708e\u9c57\u306e\u6069\u6075<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 3<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1028\">\u708e\u738b\u9f8d\u306e\u525b\u89d2<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1031\">\u708e\u9f8d\u306e\u525b\u7ffc<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1029\">\u7344\u708e\u306e\u539a\u9f8d\u9c57<\/a><\/p><p class=\"table-armor-right\">x 5<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-1265><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #CC2C3F);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/waist.png\" \/>\u6012\u5929\u30ce\u5e2f<\/a> <small>(134)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-11>\u4f1a\u5fc3\u6483\u3010\u5c5e\u6027\u3011<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-22>\u696d\u7269<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-23>\u5f3e\u4e38\u7bc0\u7d04<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-126>\u9023\u6483<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1010\">\u91d1\u7345\u5b50\u306e\u525b\u722a<\/a><\/p><p class=\"table-armor-right\">x 3<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1012\">\u91d1\u7345\u5b50\u306e\u6012\u9aea\u5929<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1008\">\u91d1\u7345\u5b50\u306e\u91cd\u7259<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-1172><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #CC2C3F);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/leg.png\" \/>\u62e0\u70b9\u53f8\u4ee4\u3010\u811a\u7532\u3011<\/a> <small>(130)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-37>\u629c\u5200\u8853\u3010\u6280\u3011<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-39>\u7d0d\u5200\u8853<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1481\">\u30b5\u30d5\u30a1\u30a4\u30a2\u30f3\u9271\u77f3<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1512\">\u738b\u56fd\u9a0e\u58eb\u56e3\u306e\u8a3c\u2162<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1009\">\u91d1\u7345\u5b50\u306e\u9ed2\u8352\u6bdb<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-1178><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #F17427);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/leg.png\" \/>\u30ae\u30eb\u30c9\u30d1\u30ec\u30b9\u30b0\u30ea\u30fc\u30f4<\/a> <small>(132)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-89>\u706b\u4e8b\u5834\u529b<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-116>\u707d\u798d\u8ee2\u798f<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1539\">\u30a8\u30b9\u30d4\u30ca\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1538\">\u30eb\u30ca\u30ac\u30ed\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1312\">\u592a\u53e4\u9f8d\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1542\">\u82f1\u96c4\u738b\u306e\u30b3\u30a4\u30f3<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><\/td><\/tr><\/tbody><\/table><style>\n    .table-armor-cell{\n        display:flex;\n        flex-wrap:nowrap;\n        width:90%;\n        margin:0 auto;\n    }\n    .table-armor-left{\n        margin:0px;\n        padding:2px;\n        width:80%;\n    }\n    .table-armor-right{\n        margin:0px;\n        padding:2px;\n        text-align:left;\n        width:10%;\n        white-space:nowrap;\n    }\n    <\/style><h2>\u88c5\u98fe\u54c1\u306e\u751f\u7523\u306b\u4f7f\u7528<\/h2><table class=\"mhrise-table\" style=\"text-align:center; margin-bottom:-1px; width:100%;\"><thead><tr><th>\u540d\u524d<\/th><th>\u30b9\u30ad\u30eb<\/th><\/tr><\/thead><tbody><tr><td style=\"width:50%;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/decoration\/decoration-125>\u9632\u5fa1\u73e0\u2164\u3010\uff14\u3011<\/a><\/td><td><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-55>\u9632\u5fa1<small style=\"padding-left:5px;\">Lv 1<\/small><\/td><\/tr><\/tbody><\/table>\n<h2  class=\"\">\u592a\u53e4\u9f8d\u9aa8\u306e\u52d5\u753b<\/h2>\n\n<ul class=\"media-list image-grid row\">\n  <div>\n\n<div>\n  <a class=\"\" data-video-id=\"PJ5D1ZhbhFo\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=PJ5D1ZhbhFo\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/PJ5D1ZhbhFo\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \uff3bMONSTER HUNTER RISE SUNBREAK\uff3d\u592a\u53e4\u9f8d\u9aa8\u304c\u307b\u3057\u3044\u306e\uff01\uff01\uff01        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"AJRtLE34kFw\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=AJRtLE34kFw\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/AJRtLE34kFw\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010MHR\u3011\u7121\u4e8b\u304b\u3010\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30bamod #monsterhunter #\u30b5\u30f3\u30d6\u30ec\u30a4\u30af#play #hinoa #\u30b5\u30f3\u30d6\u30ec\u30a4\u30af #\u30e2\u30f3\u30cf\u30f3        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"S7Afr67zYoE\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=S7Afr67zYoE\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/S7Afr67zYoE\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010MHR:SB\u3011\u30d5\u30f3\u30bf\uff5e\u304c\u697d\u306b\u91cd\u9f8d\u9aa8\u96c6\u3081\u3000\u6709\u52b9\u5c5e\u6027\u5206\u304b\u308c\u3070\u826f\u30e2\u30f3\u30b9\uff01\u3000\u5080\u7570\u8a0e\u7a76 \u30c6\u30aa\u30fb\u30c6\u30b9\u30ab\u30c8\u30eb \u7de8\u3010\u3086\u3063\u304f\u308a\u5b9f\u6cc1\u3011\u3010\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011#43        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"ETnNC8ZMfVM\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=ETnNC8ZMfVM\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/ETnNC8ZMfVM\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u9271\u77f3\u30fb\u9aa8\u63a1\u53d6\u30de\u30b9\u30bf\u30fc\u30af\u30e9\u30b9\u5834\u6240\u4e00\u89a7\u307e\u3068\u3081\u3000\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30baMHRise        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n    <\/div>\n    <div class=\"nav-more\" style=\"margin-top:10px;\">\n        <a class=\"btn btn-nav-more hide-me\" data-toggle=\"collapse\" href=\"#collapse-video-list-555923586\">\u3082\u3063\u3068\u898b\u308b<\/a>\n    <\/div>\n    <div id=\"collapse-video-list-555923586\" class=\"collapse\">\n\n<div>\n  <a class=\"\" data-video-id=\"ilhLzE9h8Ns\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=ilhLzE9h8Ns\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/ilhLzE9h8Ns\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3000\u3044\u306b\u3057\u3048\u306e\u9f8d\u9aa8\u306e\u5165\u624b\u65b9\u6cd5\u306f\uff1f\u3000\u3010MHRISE\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"-xZt0lt0UxQ\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=-xZt0lt0UxQ\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/-xZt0lt0UxQ\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u3011\u6b20\u3051\u305f\u9f8d\u9aa8\u306e\u5834\u6240\u300a\u5bd2\u51b7\u7fa4\u5cf6\u300b        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"RGFt0YfhQnk\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=RGFt0YfhQnk\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/RGFt0YfhQnk\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3000\u91cd\u539a\u306a\u7adc\u9aa8\u306e\u5165\u624b\u65b9\u6cd5\u306f\uff1f\u5834\u6240\u306f\uff1f\u3000\u3010MHRISE\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"36rXYTsc7Zk\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=36rXYTsc7Zk\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/36rXYTsc7Zk\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u306e\u6700\u5f37\u64cd\u7adc\u30e2\u30f3\u30b9\u30bf\u30fc3\u9078        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"T8d86M8ibU0\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=T8d86M8ibU0\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/T8d86M8ibU0\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30e2\u30f3\u30b9\u30bf\u30fc\u306e\u4f53\u529b\u30e9\u30f3\u30ad\u30f3\u30b0\uff01\uff01\uff1c\u30e2\u30f3\u30cf\u30f3\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\uff1e #shorts        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"-AjV8_jNYZg\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=-AjV8_jNYZg\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/-AjV8_jNYZg\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba1000\u6642\u9593\u3084\u3063\u3066\u521d\u3081\u3066\u6c17\u3065\u3044\u305f\u4ed5\u69d8 #shorts        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"mTXpgcJLHb0\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=mTXpgcJLHb0\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/mTXpgcJLHb0\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          MonsterHunter SUNBREAK\u3010PS5\u3011#06 MR10 \u306a\u3093\u3060\u3051\u3069\u3001\u88c5\u5099\u3068\u6b66\u5668\u88fd\u4f5c\u306e\u305f\u3081\u306e\u653e\u6d6a\u4e2d\u30fb\u30fb\u30fb\u592a\u53e4\u7adc\u9aa8\u3063\u3066\u306a\u3093\u3060\u30fb\u30fb\u30fb        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"s7y_yS2Ex34\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=s7y_yS2Ex34\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/s7y_yS2Ex34\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3000\u6b20\u3051\u305f\u9f8d\u9aa8\u306e\u5165\u624b\u65b9\u6cd5\u306f\uff1f\u3000\u3010MHRISE\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"_JALaZWfTvg\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=_JALaZWfTvg\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/_JALaZWfTvg\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u9aa8\u306b\u306a\u3063\u3066\u3082\u7372\u7269\u3092\u63a2\u3057\u7d9a\u3051\u308b\u30c6\u30a3\u30ac\u30ec\u30c3\u30af\u30b9\uff57\u3010\u30e2\u30f3\u30cf\u30f3\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"b5w7UO-XnUc\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=b5w7UO-XnUc\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/b5w7UO-XnUc\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u306e1\u5ea6\u4f7f\u3063\u305f\u3089\u5916\u305b\u306a\u3044\u512a\u79c0\u3059\u304e\u308b\u3076\u3063\u58ca\u308c\u88c5\u5099 12\u9078        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"hhs_jdatyoA\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=hhs_jdatyoA\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/hhs_jdatyoA\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u30e2\u30f3\u30cf\u30f3\u3011\u7686\u304c\u601d\u3046\u6700\u5f37\u306e\u5080\u7570\u514b\u670d\u30e2\u30f3\u30b9\u30bf\u30fcTOP3\u3010\u30a2\u30f3\u30b1\u30fc\u30c8\u3011\u3010\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"PmEWAvWUXIQ\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=PmEWAvWUXIQ\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/PmEWAvWUXIQ\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u653b\u7565\u3011\u6700\u7d42\u30a2\u30d7\u30c7\u7248\uff01\u6700\u512a\u5148\u3067\u7a4d\u3080\u3079\u304d\u6700\u5f37\uff06\u5feb\u9069\u30b9\u30ad\u30eb\u3092\u307e\u3068\u3081\u3066\u3054\u7d39\u4ecb        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"FdG0zNZ-VzM\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=FdG0zNZ-VzM\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/FdG0zNZ-VzM\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u307e\u3068\u3082\u306b\u899a\u3048\u3089\u308c\u3066\u306a\u3044\u30ab\u30bf\u30ab\u30ca\u30e2\u30f3\u30b9\u30bf\u30fc\u9054 #shorts #\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"Y_mZS4pB2Y0\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=Y_mZS4pB2Y0\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/Y_mZS4pB2Y0\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30ab\u30e0\u30e9\u306e\u91cc\u304b\u3089\u6765\u305f\u5909\u614b#Shorts \u3010\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30e9\u30a4\u30ba:\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"izf8khhGb4A\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=izf8khhGb4A\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/izf8khhGb4A\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u592a\u5200\u3011\u6642\u4ee3\u306b\u53d6\u308a\u6b8b\u3055\u308c\u3059\u304e\u305f\u592a\u5200\u3092\u7d39\u4ecb\u3010\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\uff1a\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011\u3010\u592a\u5200\u3011#\u30e2\u30f3\u30cf\u30f3 #\u30b5\u30f3\u30d6\u30ec\u30a4\u30af #shorts        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"2ODJKx3d9RU\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=2ODJKx3d9RU\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/2ODJKx3d9RU\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u30e2\u30f3\u30cf\u30f3\u3011\u540d\u524d\u304c\u30d1\u30c3\u3068\u51fa\u3066\u3053\u306a\u3044\u30e2\u30f3\u30b9\u30bf\u30fcTOP3\u3010\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n<\/div>\n<\/ul>\n\n<p class=\"text-center text-ss text-weak\">YouTube DATA API\u3067\u81ea\u52d5\u53d6\u5f97\u3057\u305f\u52d5\u753b\u3092\u8868\u793a\u3057\u3066\u3044\u307e\u3059<\/p><p>Twitter\u306e\u691c\u7d22\u7d50\u679c\u306f\u4ee5\u4e0b\u306eURL\u304b\u3089\u3054\u89a7\u304f\u3060\u3055\u3044\u3002<br><div class=\"nav-more\">\n<a class=\"btn btn-nav-more \" href=\"https:\/\/twitter.com\/search?q=%E3%83%A2%E3%83%B3%E3%83%8F%E3%83%B3%E3%83%A9%E3%82%A4%E3%82%BA+%E5%A4%AA%E5%8F%A4%E9%BE%8D%E9%AA%A8\" target=\"\" >\n    \u30c4\u30a4\u30fc\u30c8\u691c\u7d22\u7d50\u679c\u3078<\/a>\n<\/div>\n\n<\/p>\n<div  class=\"cv-link cv-event cv-regist-btn reg-btn-red\"  data-cv_category=\"cv-link\"  data-cv_action=\"click\"  data-cv_url=\"https:\/\/gamepedia.jp\/mh-rise\/items\"  data-cv_label=\"\u30a2\u30a4\u30c6\u30e0\u30fb\u7d20\u6750\u691c\u7d22\u30c4\u30fc\u30eb\u3078\"  >\n  <a href=\"https:\/\/gamepedia.jp\/mh-rise\/items\" rel=\"\" target=\"\" >\n  <img loading=\"lazy\" decoding=\"async\" style=\"width:0; height:1px;\" src=\"https:\/\/images.gamepedia.jp\/common\/beacon.png?url=https%3A%2F%2Fgamepedia.jp%2Fmh-rise%2Fitems\" border=\"0\" width=\"0\" height=\"1\" \/>  \u30a2\u30a4\u30c6\u30e0\u30fb\u7d20\u6750\u691c\u7d22\u30c4\u30fc\u30eb\u3078  <\/a>\n<\/div>\n<\/div>","protected":false},"author":37,"featured_media":0,"menu_order":1312,"comment_status":"open","ping_status":"closed","template":"","meta":{"event_start_date":[],"event_end_date":[],"external_thumbnail_url":"","redirect":"","last_comment_date":"","footnotes":""},"item_maps":"","item_category":"\u7d20\u6750","class_list":["post-32408","item","type-item","status-publish","hentry","item_category-290"],"long_title":"\u3010\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u3011\u592a\u53e4\u9f8d\u9aa8\u306e\u4f7f\u3044\u9053\u30fb\u5165\u624b\u65b9\u6cd5\u3010\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011","user":"qaasession","str_count":0,"category_name":"","tag_name":"","is_pr":false,"pr_mode":null,"hide_ad":false,"comment_count":0,"original_content":"","site_name":"\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30e9\u30a4\u30ba","is_valid_post_type":true,"is_password_required":false,"thumbnail_url":"https:\/\/i0.wp.com\/s3-ap-northeast-1.amazonaws.com\/media.gamepedia\/gamepedia\/wp-content\/uploads\/2019\/12\/29124928\/no_img-480x267.png?resize=200%2C200&ssl=1","_links":{"self":[{"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/items\/32408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/items"}],"about":[{"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/types\/item"}],"author":[{"embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/comments?post=32408"}],"version-history":[{"count":1,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/items\/32408\/revisions"}],"predecessor-version":[{"id":40771,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/items\/32408\/revisions\/40771"}],"wp:attachment":[{"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/media?parent=32408"}],"wp:term":[{"taxonomy":"item_maps","embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/item_maps?post=32408"},{"taxonomy":"item_category","embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/item_category?post=32408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}