{"id":9874,"date":"2021-04-02T22:53:01","date_gmt":"2021-04-02T13:53:01","guid":{"rendered":"https:\/\/gamepedia.jp\/mh-rise\/item\/9874"},"modified":"2022-07-31T04:30:50","modified_gmt":"2022-07-30T19:30:50","slug":"item-194","status":"publish","type":"item","link":"https:\/\/gamepedia.jp\/mh-rise\/item\/9874","title":{"rendered":"\u3010\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u3011\u5805\u7262\u306a\u5de8\u9aa8\u306e\u4f7f\u3044\u9053\u30fb\u5165\u624b\u65b9\u6cd5\u3010\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011"},"content":{"rendered":"<p>\u300e\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30e9\u30a4\u30ba\u300f\u306b\u767b\u5834\u3059\u308b\u30a2\u30a4\u30c6\u30e0\u300c\u5805\u7262\u306a\u5de8\u9aa8\u300d\u306e\u653b\u7565\u60c5\u5831\u3092\u4ee5\u4e0b\u3067\u89e3\u8aac\u3057\u3066\u3044\u307e\u3059\u3002<\/p><div style=\"max-width:600px; margin:0 auto;\"><h2>\u300c\u5805\u7262\u306a\u5de8\u9aa8\u300d\u306e\u8a73\u7d30<\/h2><table style=\"margin-bottom:0;\"><thead><th>\u540d\u524d<\/th><th>\u6982\u8981<\/th><\/thead><tr><td style=\"text-align:center; width:30%;\">\u5805\u7262\u306a\u5de8\u9aa8<\/td><td>\u3088\u308a\u5805\u7262\u3067\u5927\u304d\u306a\u7363\u306e\u9aa8\u3002\u8010\u4e45\u6027\u3001\u5f37\u5ea6\u5171\u306b\u512a\u308c\u305f\u3001\u4e00\u7d1a\u54c1\u306e\u6027\u8cea\u3092\u6301\u3064\u9aa8\u7d20\u6750\u3002<\/td><\/tr><\/table><table style=\"text-align:center; margin-top:-1px;\"><thead><th style=\"width:33%\">\u58f2\u5374\u4fa1\u683c<\/th><th style=\"width:33%\">\u6240\u6301\u6700\u5927\u6570<\/th><\/thead><tr><td>1300 z<\/td><td>99<\/td><\/tr><\/table><h2>\u5805\u7262\u306a\u5de8\u9aa8\u306e\u5165\u624b\u65b9\u6cd5<\/h2><div class=\"text-ss-xs\" style=\"max-width:600px; margin:0 auto;\">\u25bc \u30c9\u30ed\u30c3\u30d7\u78ba\u7387\u9806<table class=\"text-s-xs search-table\" style=\"text-align:center;\"><thead><tr><th>\u30e2\u30f3\u30b9\u30bf\u30fc<\/th><th>\u30e9\u30f3\u30af<\/th><th>\u5165\u624b\u65b9\u6cd5<\/th><th>\u500b\u6570<\/th><th>\u78ba\u7387<\/th><\/tr><\/thead><tbody><tr><td><a href=\"https:\/\/gamepedia.jp\/mh-rise\/monster\/4391\">\u30e9\u30fc\u30b8\u30e3\u30f3<\/a><\/td><td><span class=\"label\" style=\"background-color:rgba(171, 32, 58, 0.7);\">\u4e0a\u4f4d<\/span><\/td><td style=\"width:35%;\">\u30bf\u30fc\u30b2\u30c3\u30c8\u5831\u916c<\/td><td style=\"width:12%;\">2<\/td><td style=\"width:16%;\">10 %<\/td><\/tr><\/tbody><\/table><\/div><a class=\"btn btn-block btn-feedback\" href=\"https:\/\/gamepedia.jp\/mh-rise\/item_search\">\u7d20\u6750\u9006\u5f15\u304d\u30c4\u30fc\u30eb\u3078<\/a><h3>\u8a72\u5f53\u30e2\u30f3\u30b9\u30bf\u30fc<\/h3><table style=\"max-width:600px; text-align:center; margin:0 auto; border:none;\"><tbody><tr style=\"border:none;\"><td style=\"width:33%; border:none;\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/monster\/monster-30\"><div style=\"max-width:100px; height:100px; margin:0 auto;\"><img decoding=\"async\" class=\"img-thumbnail\" style=\"width:100%; height:100%;  object-fit: cover;\" src=\"https:\/\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/icon\/monster\/monster-30.png\"\/><\/div>\u30e9\u30fc\u30b8\u30e3\u30f3<\/a><\/td><\/tbody><\/table><h2>\u6b66\u5668\u751f\u7523\u30fb\u5f37\u5316\u306b\u4f7f\u7528<\/h2><div class=\"text-s\">\u25bc \u30ec\u30a2\u30ea\u30c6\u30a3\u9806<\/div><table class=\"mhrise-table pc-font-material\" style=\"max-width:600px; margin:0 auto;\"><thead>\n                <th>\u540d\u524d <small>(\u653b\u6483\u529b\/\u5c5e\u6027)<\/small><\/th>\n                <th style=\"width:55%;\">\u751f\u7523\u7d20\u6750<\/th>\n            <\/thead><tbody><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30d8\u30d3\u30a3\u30dc\u30a6\u30ac\u30f3<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1484><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%83%8A%E3%83%8A%E3%83%9B%E3%82%B7%E5%A4%A7%E7%A0%B2%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30ca\u30ca\u30db\u30b7\u5929\u7832<\/a><small> (200)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; margin:0 auto; width:80%;\"><p style=\"width:48%; padding:2px 0;\">\u30d6\u30ec<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u306a\u3057<\/p><p style=\"width:48%; padding:2px 0;\">\u53cd\u52d5<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u3084\u3084\u5c0f<\/p><p style=\"width:48%; padding:2px 0;\">\u30ea\u30ed\u30fc\u30c9<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u9045\u3044<\/p><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-598\">\u30ae\u30eb\u30c9\u30c1\u30b1\u30c3\u30c8<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-256\">\u81e3\u8718\u86db\u306e\u7d79\u7cf8<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u7532\u866b\u7a2e\u4e0a\u4f4d\u7d20\u6750<\/p><p class=\"table-weapon-right\">30 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u592a\u5200<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-411><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E9%AA%A8%E5%88%80%E3%80%90%E7%8A%AC%E7%89%99%E3%80%91%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u9aa8\u5200\u30b0\u30a2\u30eb\u30ac<\/a><small> (230)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:37.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:37.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-549\">\u8f5f\u7adc\u306e\u92ed\u7259<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u5c0f\u578b\u30e2\u30f3\u30b9\u30bf\u30fc\u4e0a\u4f4d\u7d20\u6750<\/p><p class=\"table-weapon-right\">10 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30d8\u30d3\u30a3\u30dc\u30a6\u30ac\u30f3<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1404><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E6%92%83%E3%83%83%E3%83%81%E3%83%A3%E3%83%AA%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u86d9\u5f0f\u30fb\u6483\u30c3\u30c1\u30e3\u30ea<\/a><small> (220)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; margin:0 auto; width:80%;\"><p style=\"width:48%; padding:2px 0;\">\u30d6\u30ec<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u53f3\/\u5c0f<\/p><p style=\"width:48%; padding:2px 0;\">\u53cd\u52d5<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u5927<\/p><p style=\"width:48%; padding:2px 0;\">\u30ea\u30ed\u30fc\u30c9<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u3084\u3084\u9045\u3044<\/p><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-367\">\u6cb3\u7ae5\u86d9\u306e\u5927\u76bf<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-488\">\u6ce1\u7acb\u3064\u4e0a\u6ed1\u6db2<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-525\">\u9ec4\u91d1\u8272\u306e\u7c98\u6ce5\u571f<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30ac\u30f3\u30e9\u30f3\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-881><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%83%92%E3%83%89%E3%82%A5%E3%83%B3%E3%82%AC%E3%83%B3%E3%83%A9%E3%83%B3%E3%82%B9%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30d2\u30c9\u30a5\u30f3\u30ac\u30f3\u30e9\u30f3\u30b9\u2161<\/a><small> (170)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-560\">\u4e0a\u8cea\u306a\u306d\u3058\u308c\u305f\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-475\">\u8fc5\u7adc\u306e\u92ed\u7259<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-476\">\u8fc5\u7adc\u306e\u9aa8\u9ac4<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30b9\u30e9\u30c3\u30b7\u30e5\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-975><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%82%B8%E3%82%A7%E3%83%8D%E3%83%A9%E3%83%AB%E3%82%A2%E3%83%BC%E3%83%A0%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30b3\u30f3\u30af\u30a8\u30b9\u30bf<\/a><small> (210)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-564\">\u5983\u8718\u86db\u306e\u5805\u6bbb<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-167\">\u7344\u708e\u77f3<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-573\">\u9ec4\u91d1\u306e\u6bdb<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30c1\u30e3\u30fc\u30b8\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1120><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%83%89%E3%83%A9%E3%82%B0%E3%83%99%E3%82%A4%E3%83%AB%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30c9\u30e9\u30b0\u30eb\u30d2\u30fc\u30eb<\/a><small> (200 \/ \u9f8d 36)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:42.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:42.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-183\">\u3044\u306b\u3057\u3048\u306e\u9f8d\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-452\">\u6028\u864e\u7adc\u306e\u9b42\u7d50\u6676<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-576\">\u98a8\u795e\u9f8d\u306e\u5c16\u722a<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u64cd\u866b\u68cd<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1205><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%82%B9%E3%82%AB%E3%82%A4%E3%83%8F%E3%82%A4%E3%82%B0%E3%83%AC%E3%82%A4%E3%83%96%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30cf\u30a4\u30a8\u30b9\u30c8\u30b0\u30ec\u30a4\u30d6<\/a><small> (170 \/ \u9ebb\u75fa 25)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-167\">\u7344\u708e\u77f3<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-549\">\u8f5f\u7adc\u306e\u92ed\u7259<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30cf\u30f3\u30de\u30fc<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-538><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%82%B5%E3%82%A4%E3%82%AF%E3%83%AD%E3%83%97%E3%82%B9%E3%83%8F%E3%83%B3%E3%83%9E%E3%83%BC%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30a2\u30c8\u30e9\u30b9\u30cf\u30f3\u30de\u30fc<\/a><small> (230)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:37.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:40%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-167\">\u7344\u708e\u77f3<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-496\">\u96ea\u9b3c\u7363\u306e\u5c16\u62f3\u722a<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30cf\u30f3\u30de\u30fc<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-549><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%82%B4%E3%82%B7%E3%83%A3%E3%83%99%E3%83%81%E3%83%A3%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30b4\u30b7\u30e3\u30d9\u30c1\u30e3\u2162<\/a><small> (220 \/ \u6c37 17)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-502\">\u3057\u3083\u3063\u3053\u3044\u5805\u6c37\u584a<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-498\">\u96ea\u9b3c\u7363\u306e\u5805\u8155\u7532<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-500\">\u96ea\u9b3c\u7363\u306e\u5c16\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u7247\u624b\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-185><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%83%9C%E3%83%BC%E3%83%B3%E3%82%BF%E3%83%90%E3%83%BC%E3%83%AB%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30e9\u30b0\u30c9\u30b9\u30bf\u30d0\u30fc\u30eb<\/a><small> (230)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-554\">\u89d2\u7adc\u306e\u5805\u6bbb<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-19\">\u9b3c\u4eba\u85ac\u30b0\u30ec\u30fc\u30c8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30c1\u30e3\u30fc\u30b8\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1128><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%83%A9%E3%82%A6%E3%83%B3%E3%83%89%E3%83%9B%E3%82%A4%E3%83%BC%E3%83%A9%E3%83%BC%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u7532\u76fe\u65a7\u30ed\u30bf\u30b7\u30aa\u30f3<\/a><small> (200 \/ \u9ebb\u75fa 19)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-207\">\u7363\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-326\">\u8d64\u7532\u7363\u306e\u5c16\u722a<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u8d64\u7532\u7363\u4e0a\u4f4d\u7d20\u6750<\/p><p class=\"table-weapon-right\">10 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u64cd\u866b\u68cd<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1212><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%82%B4%E3%82%B7%E3%83%A3%E3%83%9C%E3%82%B3%E3%82%A9%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30b4\u30b7\u30e3\u30dc\u30b3\u30a9\u2161<\/a><small> (210 \/ \u6c37 12)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-221\">\u51cd\u7d50\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-492\">\u96ea\u9b3c\u7363\u306e\u525b\u6bdb<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-498\">\u96ea\u9b3c\u7363\u306e\u5805\u8155\u7532<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5927\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-64><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%82%B4%E3%83%BC%E3%83%AC%E3%83%A0%E3%83%96%E3%83%AC%E3%82%A4%E3%83%89%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u525b\u5263\u30bf\u30fc\u30ed\u30b9<\/a><small> (200)<\/small><br><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-208\">\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u30e2\u30f3\u30b9\u30bf\u30fc\u4e0a\u4f4d\u7d20\u6750<\/p><p class=\"table-weapon-right\">12 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30d8\u30d3\u30a3\u30dc\u30a6\u30ac\u30f3<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1472><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E9%87%91%E7%8D%85%E5%AD%90%E7%A0%B2%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u91d1\u7345\u5b50\u7832\u2161<\/a><small> (210)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; margin:0 auto; width:80%;\"><p style=\"width:48%; padding:2px 0;\">\u30d6\u30ec<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u5de6\u53f3\/\u5927<\/p><p style=\"width:48%; padding:2px 0;\">\u53cd\u52d5<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u4e2d<\/p><p style=\"width:48%; padding:2px 0;\">\u30ea\u30ed\u30fc\u30c9<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u3084\u3084\u901f\u3044<\/p><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-595\">\u52c7\u6c17\u306e\u8a3cG<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-572\">\u91d1\u7345\u5b50\u306e\u5c3b\u5c3e<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30cf\u30f3\u30de\u30fc<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-576><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E6%80%92%E9%AB%AA%E9%8E%9A%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u6012\u9aea\u939a\u2161<\/a><small> (220 \/ \u96f7 13)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-595\">\u52c7\u6c17\u306e\u8a3cG<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-573\">\u9ec4\u91d1\u306e\u6bdb<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u91d1\u7345\u5b50\u4e0a\u4f4d\u7d20\u6750<\/p><p class=\"table-weapon-right\">10 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30e9\u30a4\u30c8\u30dc\u30a6\u30ac\u30f3<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1573><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%83%A9%E3%83%BC%E3%82%B8%E3%83%A3%E3%83%B3%E3%83%87%E3%82%B0%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30e9\u30fc\u30b8\u30e3\u30f3\u30c7\u30b0\u2161<\/a><small> (190)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; margin:0 auto; width:80%;\"><p style=\"width:48%; padding:2px 0;\">\u30d6\u30ec<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u5de6\u53f3\/\u5927<\/p><p style=\"width:48%; padding:2px 0;\">\u53cd\u52d5<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u4e2d<\/p><p style=\"width:48%; padding:2px 0;\">\u30ea\u30ed\u30fc\u30c9<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u666e\u901a<\/p><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-595\">\u52c7\u6c17\u306e\u8a3cG<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-572\">\u91d1\u7345\u5b50\u306e\u5c3b\u5c3e<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-569\">\u91d1\u7345\u5b50\u306e\u92ed\u7259<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30c1\u30e3\u30fc\u30b8\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1133><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E9%87%91%E5%89%9B%E7%9B%BE%E6%96%A7%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u91d1\u525b\u76fe\u65a7\u2161<\/a><small> (230 \/ \u96f7 14)<\/small><br><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-595\">\u52c7\u6c17\u306e\u8a3cG<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-572\">\u91d1\u7345\u5b50\u306e\u5c3b\u5c3e<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-569\">\u91d1\u7345\u5b50\u306e\u92ed\u7259<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u53cc\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-325><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E9%97%98%E9%AC%BC%E3%80%90%E9%AB%98%E4%B8%B8%E3%80%91%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u95d8\u9b3c\u3010\u9ad8\u4e38\u3011\u2160<\/a><small> (190 \/ \u96f7 16)<\/small><br><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); margin:4px auto;\">\u751f\u7523<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-168\">\u30ab\u30d6\u30ec\u30e9\u30a4\u30c8\u9271\u77f3<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-568\">\u91d1\u7345\u5b50\u306e\u5c16\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-570\">\u91d1\u7345\u5b50\u306e\u9ed2\u6bdb<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u72e9\u731f\u7b1b<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-683><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E9%9B%BB%E9%9B%BB%E5%A4%AA%E9%BC%93%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u96fb\u96fb\u592a\u9f13\u2160<\/a><small> (170 \/ \u96f7 15)<\/small><br><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:37.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:37.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#81B034;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); margin:4px auto;\">\u751f\u7523<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-568\">\u91d1\u7345\u5b50\u306e\u5c16\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-572\">\u91d1\u7345\u5b50\u306e\u5c3b\u5c3e<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-570\">\u91d1\u7345\u5b50\u306e\u9ed2\u6bdb<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u64cd\u866b\u68cd<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1247><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E9%87%91%E7%A0%95%E6%A3%8D%E6%A3%92%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u91d1\u7815\u68cd\u68d2\u2160<\/a><small> (180 \/ \u96f7 18)<\/small><br><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); margin:4px auto;\">\u751f\u7523<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-568\">\u91d1\u7345\u5b50\u306e\u5c16\u89d2<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-569\">\u91d1\u7345\u5b50\u306e\u92ed\u7259<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-570\">\u91d1\u7345\u5b50\u306e\u9ed2\u6bdb<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5f13<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1367><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E9%9B%B7%E5%BC%93%E3%80%90%E7%8D%A3%E7%8E%8B%E3%80%91%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u96f7\u5f13\u3010\u7363\u738b\u3011\u2160<\/a><small> (190 \/ \u96f7 9)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><p>\u66f2\u5c04 : \u8010\u885d\u578b<\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap;\"><p style=\"width:50%; padding:2px 0;\"\">\u63a5\u6483\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u5f37\u6483\u30d3\u30f3<\/p><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); margin:4px auto;\">\u751f\u7523<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-571\">\u91d1\u7345\u5b50\u306e\u5c16\u722a<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-569\">\u91d1\u7345\u5b50\u306e\u92ed\u7259<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-570\">\u91d1\u7345\u5b50\u306e\u9ed2\u6bdb<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><\/td><\/tr><\/tbody><\/table><style>\n    .table-weapon-cell{\n        display:flex;\n        flex-wrap:nowrap;\n        width:90%;\n        margin:0 auto;\n    }\n    .table-weapon-left{\n        margin:0px;\n        padding:2px;\n        width:80%;\n    }\n    .table-weapon-right{\n        margin:0px;\n        padding:2px;\n        text-align:left;\n        width:10%;\n        white-space:nowrap;\n    }\n    <\/style><h2>\u9632\u5177\u751f\u7523\u30fb\u5f37\u5316\u306b\u4f7f\u7528<\/h2><table class=\"mhrise-table\" style=\"max-width:600px; margin:0 auto;\"><thead>\n                <th style=\"width:50%;\">\u540d\u524d <small>(\u9632\u5fa1\u529b)<\/small><\/th>\n                <th style=\"width:50%;\">\u751f\u7523\u7d20\u6750<\/th>\n            <\/thead><tbody><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-371><div style=\"display:flex; flex-wrap:nowrap; justify-content: space-around; width:100%; margin:14px 0px;\"><div style=\"width:45%;\"><img decoding=\"async\" class=\"img-thumbnail\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/armor\/man\/%E3%82%B4%E3%82%B7%E3%83%A3S%E3%83%98%E3%83%AB%E3%83%A0.jpg?crop=54%2C22%2C20%2C24&resize=380%2C250\" \/><\/div><div style=\"width:45%;\"><img decoding=\"async\" class=\"img-thumbnail\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/armor\/woman\/%E3%82%B4%E3%82%B7%E3%83%A3S%E3%83%98%E3%83%AB%E3%83%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div><\/div><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #4293E5);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/head.png\" \/>\u30b4\u30b7\u30e3S\u30d8\u30eb\u30e0<\/a> <small>(64)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-2>\u6311\u6226\u8005<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-37>\u629c\u5200\u8853\u3010\u6280\u3011<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-316\">\u767d\u514e\u7363\u306e\u525b\u6bdb<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-492\">\u96ea\u9b3c\u7363\u306e\u525b\u6bdb<\/a><\/p><p class=\"table-armor-right\">x 4<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-500\">\u96ea\u9b3c\u7363\u306e\u5c16\u89d2<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-373><div style=\"display:flex; flex-wrap:nowrap; justify-content: space-around; width:100%; margin:14px 0px;\"><div style=\"width:45%;\"><img decoding=\"async\" class=\"img-thumbnail\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/armor\/man\/%E3%82%B4%E3%82%B7%E3%83%A3S%E3%82%A2%E3%83%BC%E3%83%A0.jpg?crop=54%2C22%2C20%2C24&resize=380%2C250\" \/><\/div><div style=\"width:45%;\"><img decoding=\"async\" class=\"img-thumbnail\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/armor\/woman\/%E3%82%B4%E3%82%B7%E3%83%A3S%E3%82%A2%E3%83%BC%E3%83%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div><\/div><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #4293E5);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/arm.png\" \/>\u30b4\u30b7\u30e3S\u30a2\u30fc\u30e0<\/a> <small>(64)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-37>\u629c\u5200\u8853\u3010\u6280\u3011<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-38>\u629c\u5200\u8853\u3010\u529b\u3011<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-320\">\u767d\u514e\u7363\u306e\u5805\u8179\u7532<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-494\">\u96ea\u9b3c\u7363\u306e\u4e0a\u76ae<\/a><\/p><p class=\"table-armor-right\">x 4<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-498\">\u96ea\u9b3c\u7363\u306e\u5805\u8155\u7532<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-555><div style=\"display:flex; flex-wrap:nowrap; justify-content: space-around; width:100%; margin:14px 0px;\"><div style=\"width:45%;\"><img decoding=\"async\" class=\"img-thumbnail\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/armor\/man\/%E9%87%91%E8%89%B2%E3%83%8E%E7%AF%AD%E6%89%8B.jpg?crop=54%2C22%2C20%2C24&resize=380%2C250\" \/><\/div><div style=\"width:45%;\"><img decoding=\"async\" class=\"img-thumbnail\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/armor\/woman\/%E9%87%91%E8%89%B2%E3%83%8E%E7%AF%AD%E6%89%8B.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div><\/div><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #B426B4);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/arm.png\" \/>\u91d1\u8272\u30ce\u7bed\u624b<\/a> <small>(70)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-9>\u529b\u306e\u89e3\u653e<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-89>\u706b\u4e8b\u5834\u529b<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-194\">\u5805\u7262\u306a\u5de8\u9aa8<\/a><\/p><p class=\"table-armor-right\">x 3<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-208\">\u7adc\u7389<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-571\">\u91d1\u7345\u5b50\u306e\u5c16\u722a<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-570\">\u91d1\u7345\u5b50\u306e\u9ed2\u6bdb<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><\/td><\/tr><\/tbody><\/table><style>\n    .table-armor-cell{\n        display:flex;\n        flex-wrap:nowrap;\n        width:90%;\n        margin:0 auto;\n    }\n    .table-armor-left{\n        margin:0px;\n        padding:2px;\n        width:80%;\n    }\n    .table-armor-right{\n        margin:0px;\n        padding:2px;\n        text-align:left;\n        width:10%;\n        white-space:nowrap;\n    }\n    <\/style><h2>\u88c5\u98fe\u54c1\u306e\u751f\u7523\u306b\u4f7f\u7528<\/h2><table class=\"mhrise-table\" style=\"text-align:center; margin-bottom:-1px; width:100%;\"><thead><tr><th>\u540d\u524d<\/th><th>\u30b9\u30ad\u30eb<\/th><\/tr><\/thead><tbody><tr><td style=\"width:50%;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/decoration\/decoration-26>\u8010\u9707\u73e0\u3010\uff12\u3011<\/a><\/td><td><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-62>\u8010\u9707<small style=\"padding-left:5px;\">Lv 1<\/small><\/td><\/tr><\/tbody><\/table>\n<h2  class=\"\"><span class=\"hidden-xs\">\u5805\u7262\u306a\u5de8\u9aa8\u306e<\/span>\u95a2\u9023\u8a18\u4e8b<\/h2>\n<ul class=\"media-list image-list \">\n  <div>\n<a href=\"https:\/\/gamepedia.jp\/mh-rise\/archives\/28421\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/wp-content\/uploads\/sites\/98\/2021\/10\/12220607\/kinjisiho-480x293.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u6700\u9ad8\u30ec\u30d9\u30eb\u306e\u5fb9\u7532\u30d8\u30d3\u30a3\uff5c\u91d1\u7345\u5b50\u7832\u3010\u91cd\u96f7\u3011\u306e\u4f5c\u308a\u65b9\u3068\u304a\u3059\u3059\u3081\u88c5\u5099\u30fb\u30b9\u30ad\u30eb      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2021\u5e7410\u670813\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u6b66\u5668\">\u6b66\u5668<\/span>\n                <span class=\"label label-default label-category label-category-\u9632\u5177\u30fb\u30b9\u30ad\u30eb\">\u9632\u5177\u30fb\u30b9\u30ad\u30eb<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u30d8\u30d3\u30a3\u30dc\u30a6\u30ac\u30f3\">\u30d8\u30d3\u30a3\u30dc\u30a6\u30ac\u30f3<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u300c\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30e9\u30a4\u30ba\uff08\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\uff09\u300d\u306e\u30d8\u30d3\u30a3\u30dc\u30a6\u30ac\u30f3\u3067\u3001\u6700\u9ad8\u30ec\u30d9\u30eb...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/gamepedia.jp\/mh-rise\/archives\/23703\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/wp-content\/uploads\/sites\/98\/2021\/05\/21135822\/f5c320089bec998091e2d4f24e63c807-5-480x293.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30de\u30eb\u30c1\u30d7\u30ec\u30a4\u306b\u304a\u3059\u3059\u3081\u306e\u9ebb\u75fa\u64cd\u866b\u68cd\uff5c\u300c\u30cf\u30a4\u30a8\u30b9\u30c8\u30b0\u30ec\u30a4\u30d6\u300d\u306e\u4f5c\u308a\u65b9\u3068\u304a\u3059\u3059\u3081\u88c5\u5099\u30fb\u30b9\u30ad\u30eb      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2021\u5e745\u670821\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u6b66\u5668\">\u6b66\u5668<\/span>\n                <span class=\"label label-default label-category label-category-\u9632\u5177\u30fb\u30b9\u30ad\u30eb\">\u9632\u5177\u30fb\u30b9\u30ad\u30eb<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u64cd\u866b\u68cd\">\u64cd\u866b\u68cd<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u300c\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30e9\u30a4\u30ba\uff08\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\uff09\u300d\u306e\u9ebb\u75fa\u64cd\u866b\u68cd\u300c\u30cf\u30a4\u30a8\u30b9\u30c8\u30b0\u30ec\u30a4...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/gamepedia.jp\/mh-rise\/archives\/21605\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/wp-content\/uploads\/sites\/98\/2021\/04\/22024053\/20210422239-480x293.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30c1\u30e3\u30a2\u30af\u6700\u5f37\u5019\u88dc\uff01\u30e9\u30fc\u30b8\u30e3\u30f3\u30c1\u30e3\u30a2\u30af\uff5c\u91d1\u525b\u76fe\u65a7\u30a4\u30ab\u30c5\u30c1\u306e\u4f5c\u308a\u65b9\u3068\u304a\u3059\u3059\u3081\u88c5\u5099\u30fb\u30b9\u30ad\u30eb      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2021\u5e744\u670822\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u6b66\u5668\">\u6b66\u5668<\/span>\n                <span class=\"label label-default label-category label-category-\u9632\u5177\u30fb\u30b9\u30ad\u30eb\">\u9632\u5177\u30fb\u30b9\u30ad\u30eb<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u30c1\u30e3\u30fc\u30b8\u30a2\u30c3\u30af\u30b9\">\u30c1\u30e3\u30fc\u30b8\u30a2\u30c3\u30af\u30b9<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u300c\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30e9\u30a4\u30ba\uff08\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\uff09\u300d\u306b\u304a\u3051\u308b\u73fe\u6642\u70b9\u3067\u306e\u30c1\u30e3\u30a2\u30af\u6700\u5f37...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n  <\/div>\n<\/ul>\n\n<h2  class=\"\">\u5805\u7262\u306a\u5de8\u9aa8\u306e\u52d5\u753b<\/h2>\n\n<ul class=\"media-list image-grid row\">\n  <div>\n\n<div>\n  <a class=\"\" data-video-id=\"gXgdSF0-ibY\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=gXgdSF0-ibY\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/gXgdSF0-ibY\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3000\u5805\u7262\u306a\u5de8\u9aa8\u306e\u5165\u624b\u65b9\u6cd5\u306f\uff1f\u3000\u3010MHRISE\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"r6nSJhH12ig\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=r6nSJhH12ig\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/r6nSJhH12ig\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3000\u5805\u7262\u306a\u9aa8\u306e\u5165\u624b\u65b9\u6cd5\u306f\uff1f\u3000\u3010MHRISE\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"ozsF61JzbjU\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=ozsF61JzbjU\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/ozsF61JzbjU\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u592a\u5200\u597d\u304d\u3059\u304e\u3066\u73fe\u5b9f\u3067\u4f7f\u3044\u59cb\u3081\u305f\u7537\u3002#\u30e2\u30f3\u30cf\u30f3 #monsterhunter #\u592a\u5200        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"_JALaZWfTvg\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=_JALaZWfTvg\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/_JALaZWfTvg\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u9aa8\u306b\u306a\u3063\u3066\u3082\u7372\u7269\u3092\u63a2\u3057\u7d9a\u3051\u308b\u30c6\u30a3\u30ac\u30ec\u30c3\u30af\u30b9\uff57\u3010\u30e2\u30f3\u30cf\u30f3\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n    <\/div>\n    <div class=\"nav-more\" style=\"margin-top:10px;\">\n        <a class=\"btn btn-nav-more hide-me\" data-toggle=\"collapse\" href=\"#collapse-video-list-249859108\">\u3082\u3063\u3068\u898b\u308b<\/a>\n    <\/div>\n    <div id=\"collapse-video-list-249859108\" class=\"collapse\">\n\n<div>\n  <a class=\"\" data-video-id=\"cq1G6qyhB5Y\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=cq1G6qyhB5Y\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/cq1G6qyhB5Y\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u300e\u7e04\u5f35\u308a\u4e89\u3044\u300f\u898b\u3066\u305f\u3060\u3051\u306a\u306e\u306b...\u3010MHSB:\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30e9\u30a4\u30ba\uff1a\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011#shorts        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"FdG0zNZ-VzM\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=FdG0zNZ-VzM\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/FdG0zNZ-VzM\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u307e\u3068\u3082\u306b\u899a\u3048\u3089\u308c\u3066\u306a\u3044\u30ab\u30bf\u30ab\u30ca\u30e2\u30f3\u30b9\u30bf\u30fc\u9054 #shorts #\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"zylmo9B4FYM\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=zylmo9B4FYM\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/zylmo9B4FYM\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u30e2\u30f3\u30cf\u30f3\u3011\u30d8\u30d3\u30a3\u30dc\u30a6\u30ac\u30f3\u3092\u62c5\u3050\u8005\u305f\u3061\u3010\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u3011\u3010\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30e9\u30a4\u30ba\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"1FSNM4wryzI\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=1FSNM4wryzI\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/1FSNM4wryzI\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u30e2\u30f3\u30cf\u30f3\u3011\u30ca\u30eb\u30ac\u30af\u30eb\u30ac\u592a\u5200\u306e\u5b9f\u5bf8\u5927\u304c\u3084\u3070\u3059\u304e\u305f\uff01\uff01#shorts        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"1ES3yL85BNw\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=1ES3yL85BNw\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/1ES3yL85BNw\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u8a0e\u7a76\u30ec\u30d9\u30eb\u4e0a\u3052\u304c\u3064\u3089\u3059\u304e\u3066\u7981\u53e5\u3092\u8a00\u3063\u3066\u3057\u307e\u3046\u3084\u3064www #shorts  #\u30e2\u30f3\u30cf\u30f3        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"hw7i00XeA4E\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=hw7i00XeA4E\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/hw7i00XeA4E\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u30e2\u30f3\u30cf\u30f3\u3042\u308b\u3042\u308b\u3011\u30d7\u30ed\u30cf\u30f3\u3068\u4e00\u822c\u306e\u9055\u3044\uff1a\u5927\u5263\u521d\u52d5\u7de8        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"7ZYc-n9q2IU\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=7ZYc-n9q2IU\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/7ZYc-n9q2IU\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u304a\u305d\u3089\u304f\u30e9\u30a4\u30ba\u65b0\u898f\u52e2\u306e\uff18\u5272\u304c\u305f\u3069\u308b\u9053 #shorts        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"T8d86M8ibU0\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=T8d86M8ibU0\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/T8d86M8ibU0\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30e2\u30f3\u30b9\u30bf\u30fc\u306e\u4f53\u529b\u30e9\u30f3\u30ad\u30f3\u30b0\uff01\uff01\uff1c\u30e2\u30f3\u30cf\u30f3\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\uff1e #shorts        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"UZzPE7hfNag\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=UZzPE7hfNag\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/UZzPE7hfNag\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30c4\u30a3\u30c4\u30a3\u30e4\u30c3\u30af\u3092\u6551\u3044\u305f\u3044\u3010\u751f\u614b\u89e3\u8aac\u3011#\u30b5\u30f3\u30d6\u30ec\u30a4\u30af#\u30e2\u30f3\u30cf\u30f3\u30a2\u30a4\u30b9\u30dc\u30fc\u30f3        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"_l8tV7Roa2c\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=_l8tV7Roa2c\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/_l8tV7Roa2c\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u30e2\u30f3\u30cf\u30f3\u3011\u67b6\u7a7a\u306e\u6b66\u5668:\u300e\u30ed\u30de\u30f3\u306b\u6ea2\u308c\u305f\u5e7b\u306e\u6b66\u5668\u300f\u9f8d\u9aa8\u7815\u304d#\u306a\u3079\u305e\u30fc #\u30e2\u30f3\u30cf\u30f3 #\u89e3\u8aac #\u96d1\u5b66        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"LkcKLXfaEoo\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=LkcKLXfaEoo\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/LkcKLXfaEoo\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010MHWilds(\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba)\u3011\uff0f\u30b0\u30e9\u30f3\u30c9\u30a8\u30b9\u30ab\u30ca\u30a4\u30c8\u306f\u697d\u52dd\u3001\u30c9\u30b7\u30e3\u30b0\u30de\u3067\u306f\u307e\u3055\u304b\u306e\u82e6\u6226\uff1f\u3010\u307e\u3050\u307e\u3050\u307e\u3050\u308d\u3093\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"K8H61fbSJBU\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=K8H61fbSJBU\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/K8H61fbSJBU\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30af\u30a8\u30b9\u30c8\u3092\u52b9\u7387\u3088\u304f\u56de\u3059\u65b9\u6cd5\u3010\u30e2\u30f3\u30cf\u30f3\u30c0\u30d6\u30eb\u30af\u30ed\u30b9\u3011#Shorts        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"g9wvTbKs5Ow\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=g9wvTbKs5Ow\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/g9wvTbKs5Ow\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010MHWilds(\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba)\u3011\uff0f\u6c37\u8010\u6027\u306e\u88c5\u5099\u306f\u30c9\u30c9\u30d6\u30e9\u30f3\u30b4\u3001\u9632\u5fa1\u529b\u3088\u308a\u30b9\u30ad\u30eb\u3088\u308a\u898b\u305f\u76ee\u304b\u306a\u3010\u307e\u3050\u307e\u3050\u307e\u3050\u308d\u3093\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n<\/div>\n<\/ul>\n\n<p class=\"text-center text-ss text-weak\">YouTube DATA API\u3067\u81ea\u52d5\u53d6\u5f97\u3057\u305f\u52d5\u753b\u3092\u8868\u793a\u3057\u3066\u3044\u307e\u3059<\/p><p>Twitter\u306e\u691c\u7d22\u7d50\u679c\u306f\u4ee5\u4e0b\u306eURL\u304b\u3089\u3054\u89a7\u304f\u3060\u3055\u3044\u3002<br><div class=\"nav-more\">\n<a class=\"btn btn-nav-more \" href=\"https:\/\/twitter.com\/search?q=%E3%83%A2%E3%83%B3%E3%83%8F%E3%83%B3%E3%83%A9%E3%82%A4%E3%82%BA+%E5%A0%85%E7%89%A2%E3%81%AA%E5%B7%A8%E9%AA%A8\" target=\"\" >\n    \u30c4\u30a4\u30fc\u30c8\u691c\u7d22\u7d50\u679c\u3078<\/a>\n<\/div>\n\n<\/p>\n<div  class=\"cv-link cv-event cv-regist-btn reg-btn-red\"  data-cv_category=\"cv-link\"  data-cv_action=\"click\"  data-cv_url=\"https:\/\/gamepedia.jp\/mh-rise\/items\"  data-cv_label=\"\u30a2\u30a4\u30c6\u30e0\u30fb\u7d20\u6750\u691c\u7d22\u30c4\u30fc\u30eb\u3078\"  >\n  <a href=\"https:\/\/gamepedia.jp\/mh-rise\/items\" rel=\"\" target=\"\" >\n  <img loading=\"lazy\" decoding=\"async\" style=\"width:0; height:1px;\" src=\"https:\/\/images.gamepedia.jp\/common\/beacon.png?url=https%3A%2F%2Fgamepedia.jp%2Fmh-rise%2Fitems\" border=\"0\" width=\"0\" height=\"1\" \/>  \u30a2\u30a4\u30c6\u30e0\u30fb\u7d20\u6750\u691c\u7d22\u30c4\u30fc\u30eb\u3078  <\/a>\n<\/div>\n<\/div>","protected":false},"author":2,"featured_media":0,"menu_order":194,"comment_status":"open","ping_status":"closed","template":"","meta":{"event_start_date":[],"event_end_date":[],"external_thumbnail_url":"","redirect":"","last_comment_date":"","footnotes":""},"item_maps":"","item_category":"\u7d20\u6750","class_list":["post-9874","item","type-item","status-publish","hentry","item_category-290"],"long_title":"\u3010\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u3011\u5805\u7262\u306a\u5de8\u9aa8\u306e\u4f7f\u3044\u9053\u30fb\u5165\u624b\u65b9\u6cd5\u3010\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011","user":"hiro","str_count":0,"category_name":"","tag_name":"","is_pr":false,"pr_mode":null,"hide_ad":false,"comment_count":0,"original_content":"","site_name":"\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30e9\u30a4\u30ba","is_valid_post_type":true,"is_password_required":false,"thumbnail_url":"https:\/\/i0.wp.com\/s3-ap-northeast-1.amazonaws.com\/media.gamepedia\/gamepedia\/wp-content\/uploads\/2019\/12\/29124928\/no_img-480x267.png?resize=200%2C200&ssl=1","_links":{"self":[{"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/items\/9874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/items"}],"about":[{"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/types\/item"}],"author":[{"embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/comments?post=9874"}],"version-history":[{"count":1,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/items\/9874\/revisions"}],"predecessor-version":[{"id":12107,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/items\/9874\/revisions\/12107"}],"wp:attachment":[{"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/media?parent=9874"}],"wp:term":[{"taxonomy":"item_maps","embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/item_maps?post=9874"},{"taxonomy":"item_category","embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/item_category?post=9874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}