{"id":9895,"date":"2021-04-02T22:53:20","date_gmt":"2021-04-02T13:53:20","guid":{"rendered":"https:\/\/gamepedia.jp\/mh-rise\/item\/9895"},"modified":"2022-07-31T04:31:30","modified_gmt":"2022-07-30T19:31:30","slug":"item-215","status":"publish","type":"item","link":"https:\/\/gamepedia.jp\/mh-rise\/item\/9895","title":{"rendered":"\u3010\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u3011\u660f\u7761\u888b\u306e\u4f7f\u3044\u9053\u30fb\u5165\u624b\u65b9\u6cd5\u3010\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011"},"content":{"rendered":"<p>\u300e\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30e9\u30a4\u30ba\u300f\u306b\u767b\u5834\u3059\u308b\u30a2\u30a4\u30c6\u30e0\u300c\u660f\u7761\u888b\u300d\u306e\u653b\u7565\u60c5\u5831\u3092\u4ee5\u4e0b\u3067\u89e3\u8aac\u3057\u3066\u3044\u307e\u3059\u3002<\/p><div style=\"max-width:600px; margin:0 auto;\"><h2>\u300c\u660f\u7761\u888b\u300d\u306e\u8a73\u7d30<\/h2><table style=\"margin-bottom:0;\"><thead><th>\u540d\u524d<\/th><th>\u6982\u8981<\/th><\/thead><tr><td style=\"text-align:center; width:30%;\">\u660f\u7761\u888b<\/td><td>\u30e2\u30f3\u30b9\u30bf\u30fc\u306e\u5185\u81d3\u5668\u5b98\u306e1\u3064\u3002\u3053\u3053\u306b\u6e9c\u307e\u308b\u7c89\u5875\u3092\u5fae\u91cf\u3067\u3082\u5438\u3044\u8fbc\u3080\u3068\u3001\u660f\u7761\u72b6\u614b\u306b\u306a\u308b\u3002<\/td><\/tr><\/table><table style=\"text-align:center; margin-top:-1px;\"><thead><th style=\"width:33%\">\u58f2\u5374\u4fa1\u683c<\/th><th style=\"width:33%\">\u6240\u6301\u6700\u5927\u6570<\/th><\/thead><tr><td>850 z<\/td><td>99<\/td><\/tr><\/table><h2>\u660f\u7761\u888b\u306e\u5165\u624b\u65b9\u6cd5<\/h2><div class=\"text-ss-xs\" style=\"max-width:600px; margin:0 auto;\">\u25bc \u30c9\u30ed\u30c3\u30d7\u78ba\u7387\u9806<table class=\"text-s-xs search-table\" style=\"text-align:center;\"><thead><tr><th>\u30e2\u30f3\u30b9\u30bf\u30fc<\/th><th>\u30e9\u30f3\u30af<\/th><th>\u5165\u624b\u65b9\u6cd5<\/th><th>\u500b\u6570<\/th><th>\u78ba\u7387<\/th><\/tr><\/thead><tbody><tr><td><a href=\"https:\/\/gamepedia.jp\/mh-rise\/monster\/4373\">\u30c9\u30b9\u30d0\u30ae\u30a3<\/a><\/td><td><span class=\"label\" style=\"background-color:rgba(171, 32, 58, 0.7);\">\u4e0a\u4f4d<\/span><\/td><td style=\"width:35%;\">\u5265\u304e\u53d6\u308a<\/td><td style=\"width:12%;\">1<\/td><td style=\"width:16%;\">27 %<\/td><\/tr><tr><td><a href=\"https:\/\/gamepedia.jp\/mh-rise\/monster\/4373\">\u30c9\u30b9\u30d0\u30ae\u30a3<\/a><\/td><td><span class=\"label\" style=\"background-color:rgba(171, 32, 58, 0.7);\">\u4e0a\u4f4d<\/span><\/td><td style=\"width:35%;\">\u30aa\u30c8\u30e2\u30a2\u30a4\u30eb\u30fc\u306e\u53ce\u96c6\u7269<\/td><td style=\"width:12%;\">1<\/td><td style=\"width:16%;\">26 %<\/td><\/tr><tr><td><a href=\"https:\/\/gamepedia.jp\/mh-rise\/monster\/4373\">\u30c9\u30b9\u30d0\u30ae\u30a3<\/a><\/td><td><span class=\"label\" style=\"background-color:rgba(171, 32, 58, 0.7);\">\u4e0a\u4f4d<\/span><\/td><td style=\"width:35%;\">\u30bf\u30fc\u30b2\u30c3\u30c8\u5831\u916c<\/td><td style=\"width:12%;\">1<\/td><td style=\"width:16%;\">25 %<\/td><\/tr><tr><td><a href=\"https:\/\/gamepedia.jp\/mh-rise\/monster\/4373\">\u30c9\u30b9\u30d0\u30ae\u30a3<\/a><\/td><td><span class=\"label\" style=\"background-color:rgba(171, 32, 58, 0.7);\">\u4e0a\u4f4d<\/span><\/td><td style=\"width:35%;\">\u982d\u90e8\u7834\u58ca<\/td><td style=\"width:12%;\">1<\/td><td style=\"width:16%;\">20 %<\/td><\/tr><\/tbody><\/table><\/div><a class=\"btn btn-block btn-feedback\" href=\"https:\/\/gamepedia.jp\/mh-rise\/item_search\">\u7d20\u6750\u9006\u5f15\u304d\u30c4\u30fc\u30eb\u3078<\/a><h3>\u8a72\u5f53\u30e2\u30f3\u30b9\u30bf\u30fc<\/h3><table style=\"max-width:600px; text-align:center; margin:0 auto; border:none;\"><tbody><tr style=\"border:none;\"><td style=\"width:33%; border:none;\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/monster\/monster-12\"><div style=\"max-width:100px; height:100px; margin:0 auto;\"><img decoding=\"async\" class=\"img-thumbnail\" style=\"width:100%; height:100%;  object-fit: cover;\" src=\"https:\/\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/icon\/monster\/monster-12.png\"\/><\/div>\u30c9\u30b9\u30d0\u30ae\u30a3<\/a><\/td><\/tbody><\/table><h3>\u8a0e\u4f10\u5bfe\u8c61\u306e\u30af\u30a8\u30b9\u30c8<\/h3><table class=\"mhrise-table\" style=\"\"><thead><th>\u30af\u30a8\u30b9\u30c8\u540d<\/th><th>\u76ee\u7684<\/th><th >\u30d5\u30a3\u30fc\u30eb\u30c9<\/th><th>\u5831\u5968\u91d1<\/th><\/thead><tr>\n                    <td style=\"width:35%\"><span class=\"label label-default label-\u30bb\u30ec\u30af\u30c8\">\u30bb\u30ec\u30af\u30c8<\/span> \u96c6\u4f1a\u6240\u4e0a\u4f4d\u26054<br><a href=https:\/\/gamepedia.jp\/mh-rise\/quest\/quest-119>\u5bd2\u5730\u306b\u3066\u821f\u3092\u6f15\u3050<\/a><\/td>\n                    <td style=\"width:35%\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/monster-12\">\u30c9\u30b9\u30d0\u30ae\u30a3<\/a>2\u982d\u306e\u72e9\u731f<\/td>\n                    <td style=\"width:15%\"><a href=https:\/\/gamepedia.jp\/mh-rise\/field\/field-3>\u5bd2\u51b7\u7fa4\u5cf6<\/a><\/td>\n                    <td style=\"width:15%\">5400<span class=\"weak\">z<\/span><\/td>\n                    <\/tr><tr>\n                    <td style=\"width:35%\">\u96c6\u4f1a\u6240\u4e0a\u4f4d\u26054<br><a href=https:\/\/gamepedia.jp\/mh-rise\/quest\/quest-130>\u5b66\u3079\uff01 \u8efd\u5f29\u306e\u578b<\/a><\/td>\n                    <td style=\"width:35%\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/monster-12\">\u30c9\u30b9\u30d0\u30ae\u30a3<\/a>1\u982d\u3068<a href=\"https:\/\/gamepedia.jp\/mh-rise\/monster-23\">\u30c9\u30b9\u30d5\u30ed\u30ae\u30a3<\/a>1\u982d\u306e\u72e9\u731f<\/td>\n                    <td style=\"width:15%\">\u95d8\u6280\u5834<\/td>\n                    <td style=\"width:15%\">5760<span class=\"weak\">z<\/span><\/td>\n                    <\/tr><\/table><h2>\u6b66\u5668\u751f\u7523\u30fb\u5f37\u5316\u306b\u4f7f\u7528<\/h2><div class=\"text-s\">\u25bc \u30ec\u30a2\u30ea\u30c6\u30a3\u9806<\/div><table class=\"mhrise-table pc-font-material\" style=\"max-width:600px; margin:0 auto;\"><thead>\n                <th>\u540d\u524d <small>(\u653b\u6483\u529b\/\u5c5e\u6027)<\/small><\/th>\n                <th style=\"width:55%;\">\u751f\u7523\u7d20\u6750<\/th>\n            <\/thead><tbody><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5927\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2304>\u5922\u9b58\u5927\u5263\u30e1\u30ed\u30a6\u30c9\u30ed\u30a6<\/a><small> (290 \/ \u7761\u7720 30)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1181\">\u6ce5\u7fc1\u7adc\u306e\u525b\u722a<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u4eba\u9b5a\u7adcMR\u7d20\u6750<\/p><p class=\"table-weapon-right\">8 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u53cc\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2267>\u5fcd\u56e3\u5b50\u3010\u7761\u871c\u7389\u3011\u7d76<\/a><small> (240 \/ \u7761\u7720 11)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1318\">\u30e2\u30f3\u30b9\u30bf\u30fc\u306e\u7279\u6fc3<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1319\">\u67d4\u8edf\u306a\u539a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30ac\u30f3\u30e9\u30f3\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2470>\u7720\u72d7\u9283\u69cd\u30e9\u30e9\u30d0\u30a4\u30c8\u6539<\/a><small> (240 \/ \u7761\u7720 29)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1419\">\u30d5\u30ed\u30b7\u30b9\u30e1\u30bf\u30eb<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1062\">\u5049\u5927\u306a\u30c8\u30b5\u30ab<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30cf\u30f3\u30de\u30fc<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2679>\u30b0\u30fc\u30b0\u30fc\u30d9\u30a2\u6539<\/a><small> (210 \/ \u7761\u7720 39)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:47.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:47.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1317\">\u6975\u4e0a\u306e\u6bdb\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1072\">\u9752\u718a\u7363\u306e\u8c6a\u525b\u6bdb<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30b9\u30e9\u30c3\u30b7\u30e5\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3023>\u96ea\u65cf\u306e\u5263\u65a7\u3010\u9732\u81e5\u3011\u6539<\/a><small> (240 \/ \u7761\u7720 25)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1478\">\u30a8\u30eb\u30c8\u30e9\u30a4\u30c8\u9271\u77f3<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1061\">\u7720\u72d7\u7adc\u306e\u539a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5927\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2400>\u7761\u8c9d\u5927\u5263\u30d4\u30f3\u30af\u30bf\u30fc\u30c0\u6539<\/a><small> (270 \/ \u7761\u7720 18)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1469\">\u30a2\u30f3\u30e2\u30b5\u30ab\u30ac\u30a4<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1164\">\u4eba\u9b5a\u7adc\u306e\u3086\u3081\u307f\u7c89<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1486\">\u51cd\u3066\u3064\u3044\u305f\u91cd\u6c37\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30ac\u30f3\u30e9\u30f3\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-2539>\u7761\u8c9d\u9283\u69cd\u30de\u30a4\u30c8\u30e9\u30b9\u6539<\/a><small> (260 \/ \u7761\u7720 24)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1469\">\u30a2\u30f3\u30e2\u30b5\u30ab\u30ac\u30a4<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1486\">\u51cd\u3066\u3064\u3044\u305f\u91cd\u6c37\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30e9\u30f3\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3626>\u30af\u30e9\u30b7\u30fc\u30d5\u30ec\u30b0\u30e9\u30f3\u30b9\u6539<\/a><small> (260 \/ \u7761\u7720 21)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1473\">\u30f4\u30a1\u30ea\u30a2\u30d3\u30b9\u30ab\u30b9<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1420\">\u30b4\u30eb\u30c9\u30e9\u30a4\u30c8\u9271\u77f3<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u7247\u624b\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3221>\u7761\u8c9d\u5263\u30eb\u30c7\u30c6\u30d7\u30b9\u6539<\/a><small> (270 \/ \u7761\u7720 21)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1469\">\u30a2\u30f3\u30e2\u30b5\u30ab\u30ac\u30a4<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1486\">\u51cd\u3066\u3064\u3044\u305f\u91cd\u6c37\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1075\">\u767d\u514e\u7363\u306e\u8c6a\u525b\u6bdb<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u592a\u5200<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3317>\u5922\u5e7b\u306e\u30e1\u30ed\u30a6\u30d1\u30a6\u6539<\/a><small> (260 \/ \u7761\u7720 22)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:2.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:30%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1162\">\u4eba\u9b5a\u7adc\u306e\u525b\u9264\u722a<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1163\">\u4eba\u9b5a\u7adc\u306e\u8352\u9aea\u30d2\u30ec<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5f13<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1992>\u9e97\u83ef\u306e\u679d\u5f13\u6539<\/a><small> (270)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><p>\u66f2\u5c04 : \u56de\u5fa9\u578b<\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap;\"><p style=\"width:50%; padding:2px 0;\"\">\u63a5\u6483\u30d3\u30f3<\/p><p style=\"color:rgb(235, 96, 96); width:50%; padding:2px 0;\"><strong>\u7761\u7720\u30d3\u30f3<\/strong><\/p><p style=\"width:50%; padding:2px 0;\"\">\u7206\u7834\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u6e1b\u6c17\u30d3\u30f3<\/p><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1478\">\u30a8\u30eb\u30c8\u30e9\u30a4\u30c8\u9271\u77f3<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1465\">\u661f\u623b\u306e\u7a00\u82b1<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1156\">\u6cb3\u7ae5\u86d9\u306e\u82d4\u91cd\u7532<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30b9\u30e9\u30c3\u30b7\u30e5\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3088>\u7761\u8c9d\u5263\u65a7\u30d0\u30c6\u30a3\u30e9\u30b9\u6539<\/a><small> (260 \/ \u7761\u7720 24)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1469\">\u30a2\u30f3\u30e2\u30b5\u30ab\u30ac\u30a4<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1483\">\u91cd\u539a\u306a\u7adc\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u7247\u624b\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-3156>\u30ec\u30e0\u30aa\u30eb\u30cb\u30b9\u30ca\u30a4\u30d5\u6539<\/a><small> (250 \/ \u7761\u7720 28)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1486\">\u51cd\u3066\u3064\u3044\u305f\u91cd\u6c37\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1061\">\u7720\u72d7\u7adc\u306e\u539a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-294\">\u7720\u72d7\u7adc\u306e\u5c16\u722a<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5f13<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1951>\u30c9\u30ed\u30fc\u30ba\u30f4\u30a7\u30ed\u30fc\u30b9\u6539<\/a><small> (290)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><p>\u66f2\u5c04 : \u8010\u885d\u578b<\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap;\"><p style=\"width:50%; padding:2px 0;\"\">\u63a5\u6483\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u5f37\u6483\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u6bd2\u30d3\u30f3<\/p><p style=\"color:rgb(235, 96, 96); width:50%; padding:2px 0;\"><strong>\u7761\u7720\u30d3\u30f3<\/strong><\/p><p style=\"width:50%; padding:2px 0;\"\">\u7206\u7834\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u6e1b\u6c17\u30d3\u30f3<\/p><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1486\">\u51cd\u3066\u3064\u3044\u305f\u91cd\u6c37\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1061\">\u7720\u72d7\u7adc\u306e\u539a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1316\">\u91cd\u539a\u306a\u7259<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30cf\u30f3\u30de\u30fc<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-582><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%81%8A%E3%82%84%E3%81%99%E3%81%BF%E3%83%99%E3%82%A2%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30b0\u30fc\u30b0\u30fc\u30d9\u30a2<\/a><small> (130 \/ \u7761\u7720 38)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:47.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:47.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-165\">\u30ce\u30f4\u30a1\u30af\u30ea\u30b9\u30bf\u30eb<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-159\">\u5927\u5730\u306e\u7d50\u6676<\/a><\/p><p class=\"table-weapon-right\">x 10<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-207\">\u7363\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30e9\u30f3\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-797><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%82%A2%E3%82%BA%E3%83%BC%E3%83%AB%E3%82%AF%E3%83%AC%E3%82%B9%E3%83%88%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30b0\u30ec\u30a4\u30c8\u30a2\u30ba\u30fc\u30eb<\/a><small> (180 \/ \u7761\u7720 29)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#E2E2E2;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-407\">\u4eba\u9b5a\u7adc\u306e\u5fae\u7761\u307f\u7c89<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-294\">\u7720\u72d7\u7adc\u306e\u5c16\u722a<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-206\">\u9ce5\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5f13<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1383><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%83%95%E3%83%AB%E3%83%BC%E3%83%AB%E3%83%BC%E3%82%AF%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u9e97\u83ef\u306e\u679d\u5f13<\/a><small> (170)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><p>\u66f2\u5c04 : \u56de\u5fa9\u578b<\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap;\"><p style=\"width:50%; padding:2px 0;\"\">\u63a5\u6483\u30d3\u30f3<\/p><p style=\"color:rgb(235, 96, 96); width:50%; padding:2px 0;\"><strong>\u7761\u7720\u30d3\u30f3<\/strong><\/p><p style=\"width:50%; padding:2px 0;\"\">\u7206\u7834\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u6e1b\u6c17\u30d3\u30f3<\/p><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-165\">\u30ce\u30f4\u30a1\u30af\u30ea\u30b9\u30bf\u30eb<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-142\">\u661f\u898b\u306e\u9e97\u82b1<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-363\">\u6cb3\u7ae5\u86d9\u306e\u82d4\u5805\u7532<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u7247\u624b\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-230><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E7%9D%A1%E3%82%8A%E3%82%92%E8%AA%98%E3%81%86%E8%B2%9D%E5%89%A3%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u7761\u8c9d\u5263\u30eb\u30c7\u30c6\u30d7\u30b9<\/a><small> (180 \/ \u7761\u7720 19)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-149\">\u30de\u30af\u30e9\u30b5\u30ab\u30ac\u30a4<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-390\">\u6ce5\u9b5a\u7adc\u306e\u4e0a\u30d2\u30ec<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-353\">\u8c4a\u6c83\u306a\u30c9\u30ed<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5927\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-103><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E7%9D%A1%E3%82%8A%E3%82%92%E8%AA%98%E3%81%86%E8%B2%9D%E5%A4%A7%E5%89%A3%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u7761\u8c9d\u5927\u5263\u30d4\u30f3\u30af\u30bf\u30fc\u30c0<\/a><small> (180 \/ \u7761\u7720 15)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:32.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-165\">\u30ce\u30f4\u30a1\u30af\u30ea\u30b9\u30bf\u30eb<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-149\">\u30de\u30af\u30e9\u30b5\u30ab\u30ac\u30a4<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30e9\u30f3\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-815><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%83%95%E3%83%AC%E3%82%B0%E3%83%A9%E3%83%B3%E3%82%B9%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30af\u30e9\u30b7\u30fc\u30d5\u30ec\u30b0\u30e9\u30f3\u30b9<\/a><small> (160 \/ \u7761\u7720 20)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:20%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:20%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-153\">\u30c9\u30b9\u30d3\u30b9\u30ab\u30b9<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-169\">\u30e6\u30cb\u30aa\u30f3\u9271\u77f3<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30b9\u30e9\u30c3\u30b7\u30e5\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1046><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E7%9D%A1%E3%82%8A%E3%82%92%E8%AA%98%E3%81%86%E8%B2%9D%E5%89%A3%E6%96%A7%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u7761\u8c9d\u5263\u65a7\u30d0\u30c6\u30a3\u30e9\u30b9<\/a><small> (170 \/ \u7761\u7720 23)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-149\">\u30de\u30af\u30e9\u30b5\u30ab\u30ac\u30a4<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-397\">\u5ca9\u7adc\u306e\u6d99<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30ac\u30f3\u30e9\u30f3\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-929><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E7%9D%A1%E3%82%8A%E3%82%92%E8%AA%98%E3%81%86%E8%B2%9D%E9%8A%83%E6%A7%8D%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u7761\u8c9d\u9283\u69cd\u30de\u30a4\u30c8\u30e9\u30b9<\/a><small> (190 \/ \u7761\u7720 20)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:15%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-165\">\u30ce\u30f4\u30a1\u30af\u30ea\u30b9\u30bf\u30eb<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-149\">\u30de\u30af\u30e9\u30b5\u30ab\u30ac\u30a4<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-353\">\u8c4a\u6c83\u306a\u30c9\u30ed<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30b9\u30e9\u30c3\u30b7\u30e5\u30a2\u30c3\u30af\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-994><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E9%9B%AA%E6%97%8F%E3%81%AE%E5%89%A3%E6%96%A7%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u96ea\u65cf\u306e\u5263\u65a7\u2162<\/a><small> (140 \/ \u7761\u7720 20)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-168\">\u30ab\u30d6\u30ec\u30e9\u30a4\u30c8\u9271\u77f3<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-279\">\u30d0\u30ae\u30a3\u306e\u4e0a\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-292\">\u7720\u72d7\u7adc\u306e\u4e0a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5f13<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1345><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%83%90%E3%82%AE%E3%82%A3%E3%83%9C%E3%82%A6%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30c9\u30ed\u30fc\u30ba\u30f4\u30a7\u30ed\u30fc\u30b9<\/a><small> (160)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><p>\u66f2\u5c04 : \u8010\u885d\u578b<\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap;\"><p style=\"width:50%; padding:2px 0;\"\">\u63a5\u6483\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u5f37\u6483\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u6bd2\u30d3\u30f3<\/p><p style=\"color:rgb(235, 96, 96); width:50%; padding:2px 0;\"><strong>\u7761\u7720\u30d3\u30f3<\/strong><\/p><p style=\"width:50%; padding:2px 0;\"\">\u7206\u7834\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u6e1b\u6c17\u30d3\u30f3<\/p><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-279\">\u30d0\u30ae\u30a3\u306e\u4e0a\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-292\">\u7720\u72d7\u7adc\u306e\u4e0a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-206\">\u9ce5\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5927\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-34><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%83%A1%E3%83%AD%E3%82%A6%E3%83%89%E3%83%AD%E3%82%A6%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30e1\u30ed\u30a6\u30c9\u30ed\u30a6\u2161<\/a><small> (120 \/ \u7761\u7720 19)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:10%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:10%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#81B034;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-294\">\u7720\u72d7\u7adc\u306e\u5c16\u722a<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\">\u4eba\u9b5a\u7adc\u7d20\u6750<\/p><p class=\"table-weapon-right\">8 pts<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u7247\u624b\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-174><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%83%AC%E3%83%A0%E3%83%8A%E3%82%A4%E3%83%95%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30ec\u30e0\u30aa\u30eb\u30cb\u30b9\u30ca\u30a4\u30d5<\/a><small> (140 \/ \u7761\u7720 26)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-292\">\u7720\u72d7\u7adc\u306e\u4e0a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-294\">\u7720\u72d7\u7adc\u306e\u5c16\u722a<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-206\">\u9ce5\u7adc\u7389<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30ac\u30f3\u30e9\u30f3\u30b9<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-869><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%83%90%E3%82%AE%E3%82%A3%E3%82%AC%E3%83%B3%E3%83%A9%E3%83%B3%E3%82%B9%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30d0\u30ae\u30a3\u30ac\u30f3\u30e9\u30f3\u30b9\u2162<\/a><small> (140 \/ \u7761\u7720 25)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:25%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:17.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:12.5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-163\">\u30b0\u30e9\u30b7\u30b9\u30e1\u30bf\u30eb<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-279\">\u30d0\u30ae\u30a3\u306e\u4e0a\u9c57<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u53cc\u5263<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-346><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E5%BF%8D%E5%9B%A3%E5%AD%90%E3%80%90%E7%9D%A1%E8%9C%9C%E7%8E%89%E3%80%91%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u5fcd\u56e3\u5b50\u3010\u7761\u871c\u7389\u3011\u2161<\/a><small> (190 \/ \u7761\u7720 5)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><div style=\"margin:6px auto; padding:3px 6px; width:142px; background-color:rgba(0, 0, 0, 0.21); border:1px solid rgba(0, 0, 0, 0.30); box-shadow(rgba(0, 0, 0, .15) 0 0 2px);\"><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#BE3843; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><div style=\"padding:7px 0px; flex-basis:15%; background-color:#81B034; border-bottom:1px solid rgba(0, 0, 0, 0.31);\"><\/div><\/div><div style=\"display:flex; flex-wrap:nowrap;\"><div style=\"padding:7px 0px; flex-basis:27.5%; background-color:#BE3843;\"><\/div><div style=\"padding:7px 0px; flex-basis:7.5%; background-color:#D3673D;\"><\/div><div style=\"padding:7px 0px; flex-basis:25%; background-color:#C9B232;\"><\/div><div style=\"padding:7px 0px; flex-basis:22.5%; background-color:#81B034;\"><\/div><div style=\"padding:7px 0px; flex-basis:5%; background-color:#3A58D7;\"><\/div><\/div><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-108\">\u30c9\u30ad\u30c9\u30ad\u30ce\u30b3<\/a><\/p><p class=\"table-weapon-right\">x 5<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-231\">\u5782\u76ae\u7adc\u306e\u4e0a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5f13<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1385><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%82%B9%E3%82%A2%E3%83%AB%E3%82%AF%E3%83%94%E3%82%A6%E3%82%B9%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30b9\u30a2\u30eb\u30af\u30d4\u30a6\u30b9\u2161<\/a><small> (150)<\/small><br><p>\u66f2\u5c04 : \u4f1a\u5fc3\u578b<\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap;\"><p style=\"width:50%; padding:2px 0;\"\">\u63a5\u6483\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u5f37\u6483\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u6bd2\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u9ebb\u75fa\u30d3\u30f3<\/p><p style=\"color:rgb(235, 96, 96); width:50%; padding:2px 0;\"><strong>\u7761\u7720\u30d3\u30f3<\/strong><\/p><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-263\">\u4e0a\u8cea\u306a\u8179\u888b<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-150\">\u6bd2\u30af\u30e2\u30ea<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-255\">\u81e3\u8718\u86db\u306e\u7cf8<\/a><\/p><p class=\"table-weapon-right\">x 4<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u30e9\u30a4\u30c8\u30dc\u30a6\u30ac\u30f3<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1578><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E6%9C%A8%E5%BD%AB%E7%8A%AC%E9%8A%83%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u6728\u5f6b\u72ac\u9283\u2161<\/a><small> (140)<\/small><br><p style=\"padding:2px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; margin:0 auto; width:80%;\"><p style=\"width:48%; padding:2px 0;\">\u30d6\u30ec<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u5de6\u53f3\/\u5c0f<\/p><p style=\"width:48%; padding:2px 0;\">\u53cd\u52d5<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u4e2d<\/p><p style=\"width:48%; padding:2px 0;\">\u30ea\u30ed\u30fc\u30c9<\/p><p style=\"width:4%; padding:2px 0;\">:<\/p><p style=\"width:48%; padding:2px 0;\">\u3084\u3084\u9045\u3044<\/p><\/div><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); padding-top:5px; margin:4px auto;\">\u5f37\u5316<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-596\">\u30aa\u30c8\u30e2\u30c1\u30b1\u30c3\u30c8<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-305\">\u6bd2\u72d7\u7adc\u306e\u4e0a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-292\">\u7720\u72d7\u7adc\u306e\u4e0a\u76ae<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><p style=\"text-align:left\"><span class=\"label label-default\">\u5f13<\/span><\/p><a href=https:\/\/gamepedia.jp\/mh-rise\/weapon\/weapon-1372><div><img decoding=\"async\" class=\"img-thumbnail\" style=\"max-width:110px; margin:4px;\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/weapon\/%E3%82%AB%E3%82%B8%E3%82%AD%E5%BC%93%E3%80%90%E7%B2%97%E3%80%91%E2%85%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div>\u30ab\u30b8\u30ad\u5f13\u3010\u7c97\u3011\u2160<\/a><small> (160)<\/small><br><p>\u66f2\u5c04 : \u4f1a\u5fc3\u578b<\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap;\"><p style=\"width:50%; padding:2px 0;\"\">\u63a5\u6483\u30d3\u30f3<\/p><p style=\"width:50%; padding:2px 0;\"\">\u5f37\u6483\u30d3\u30f3<\/p><p style=\"color:rgb(235, 96, 96); width:50%; padding:2px 0;\"><strong>\u9ebb\u75fa\u30d3\u30f3<\/strong><\/p><p style=\"color:rgb(235, 96, 96); width:50%; padding:2px 0;\"><strong>\u7761\u7720\u30d3\u30f3<\/strong><\/p><\/td><td><div style=\"width:88%; border-bottom:1px solid rgba(0, 0, 0, 0.23); margin:4px auto;\">\u751f\u7523<\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-156\">\u30ab\u30b8\u30ad\u30de\u30b0\u30ed<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-128\">\u30c9\u30b9\u30c1\u30e3\u30c3\u30ab\u30c4\u30aa<\/a><\/p><p class=\"table-weapon-right\">x 1<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-177\">\u306d\u3058\u308c\u305f\u5805\u602a\u9aa8<\/a><\/p><p class=\"table-weapon-right\">x 3<\/p><\/div><div class=\"table-weapon-cell\"><p class=\"table-weapon-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-weapon-right\">x 2<\/p><\/div><\/td><\/tr><\/tbody><\/table><style>\n    .table-weapon-cell{\n        display:flex;\n        flex-wrap:nowrap;\n        width:90%;\n        margin:0 auto;\n    }\n    .table-weapon-left{\n        margin:0px;\n        padding:2px;\n        width:80%;\n    }\n    .table-weapon-right{\n        margin:0px;\n        padding:2px;\n        text-align:left;\n        width:10%;\n        white-space:nowrap;\n    }\n    <\/style><h2>\u9632\u5177\u751f\u7523\u30fb\u5f37\u5316\u306b\u4f7f\u7528<\/h2><table class=\"mhrise-table\" style=\"max-width:600px; margin:0 auto;\"><thead>\n                <th style=\"width:50%;\">\u540d\u524d <small>(\u9632\u5fa1\u529b)<\/small><\/th>\n                <th style=\"width:50%;\">\u751f\u7523\u7d20\u6750<\/th>\n            <\/thead><tbody><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-841><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #B426B4);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/chest.png\" \/>\u30a4\u30bd\u30cdX\u30e1\u30a4\u30eb<\/a> <small>(116)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_3.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-19>\u7761\u7720\u5c5e\u6027\u5f37\u5316<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-50>\u88c5\u586b\u62e1\u5f35<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1164\">\u4eba\u9b5a\u7adc\u306e\u3086\u3081\u307f\u7c89<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1163\">\u4eba\u9b5a\u7adc\u306e\u8352\u9aea\u30d2\u30ec<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1161\">\u4eba\u9b5a\u7adc\u306e\u91cd\u6bbb<\/a><\/p><p class=\"table-armor-right\">x 4<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-460><div style=\"display:flex; flex-wrap:nowrap; justify-content: space-around; width:100%; margin:14px 0px;\"><div style=\"width:45%;\"><img decoding=\"async\" class=\"img-thumbnail\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/armor\/man\/%E3%83%90%E3%82%AE%E3%82%A3S%E3%82%A2%E3%83%BC%E3%83%A0.jpg?crop=54%2C22%2C20%2C24&resize=380%2C250\" \/><\/div><div style=\"width:45%;\"><img decoding=\"async\" class=\"img-thumbnail\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/armor\/woman\/%E3%83%90%E3%82%AE%E3%82%A3S%E3%82%A2%E3%83%BC%E3%83%A0.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div><\/div><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #10DE10);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/arm.png\" \/>\u30d0\u30ae\u30a3S\u30a2\u30fc\u30e0<\/a> <small>(36)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-14>\u6c37\u5c5e\u6027\u653b\u6483\u5f37\u5316<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-74>\u7761\u7720\u8010\u6027<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-279\">\u30d0\u30ae\u30a3\u306e\u4e0a\u9c57<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-294\">\u7720\u72d7\u7adc\u306e\u5c16\u722a<\/a><\/p><p class=\"table-armor-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-738><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #B426B4);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/arm.png\" \/>\u30d0\u30ae\u30a3X\u30a2\u30fc\u30e0<\/a> <small>(114)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_4.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-19>\u7761\u7720\u5c5e\u6027\u5f37\u5316<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-74>\u7761\u7720\u8010\u6027<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-279\">\u30d0\u30ae\u30a3\u306e\u4e0a\u9c57<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-294\">\u7720\u72d7\u7adc\u306e\u5c16\u722a<\/a><\/p><p class=\"table-armor-right\">x 3<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-462><div style=\"display:flex; flex-wrap:nowrap; justify-content: space-around; width:100%; margin:14px 0px;\"><div style=\"width:45%;\"><img decoding=\"async\" class=\"img-thumbnail\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/armor\/man\/%E3%83%90%E3%82%AE%E3%82%A3S%E3%82%B0%E3%83%AA%E3%83%BC%E3%83%B4.jpg?crop=54%2C22%2C20%2C24&resize=380%2C250\" \/><\/div><div style=\"width:45%;\"><img decoding=\"async\" class=\"img-thumbnail\" src=\"https:\/\/i2.wp.com\/storage.googleapis.com\/images.gamepedia.jp\/mh-rise\/armor\/woman\/%E3%83%90%E3%82%AE%E3%82%A3S%E3%82%B0%E3%83%AA%E3%83%BC%E3%83%B4.jpg?crop=54%2C21%2C22%2C25&resize=380%2C250\" \/><\/div><\/div><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #10DE10);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/leg.png\" \/>\u30d0\u30ae\u30a3S\u30b0\u30ea\u30fc\u30f4<\/a> <small>(36)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-1>\u653b\u6483<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 1<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-163\">\u30b0\u30e9\u30b7\u30b9\u30e1\u30bf\u30eb<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-215\">\u660f\u7761\u888b<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-294\">\u7720\u72d7\u7adc\u306e\u5c16\u722a<\/a><\/p><p class=\"table-armor-right\">x 3<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-269\">\u7ffc\u86c7\u7adc\u306e\u4e0a\u76ae<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><\/td><\/tr><tr><td style=\"text-align:center;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/armor-1113><img decoding=\"async\" style=\"width:20px; -webkit-filter: drop-shadow(0 0 0.1px #B426B4);\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/armor\/leg.png\" \/>\u30d0\u30ae\u30a3X\u30b0\u30ea\u30fc\u30f4<\/a> <small>(114)<\/small><p style=\"margin:5px 0;\"><span style=\"box-shadow:rgba(0, 0, 0, .35) 0 0 2px;\"><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_1.png\" \/><img decoding=\"async\" style=\"width:20px;\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=20,h=20,fit=pad,f=webp\/images.gamepedia.jp\/mh-rise\/decoration\/decoration_2.png\" \/><\/span><\/p><hr style=\"margin:5px;\"><div style=\"display:flex; flex-wrap:wrap; text-align:left; margin:8px auto; width:80%;\"><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-1>\u653b\u6483<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><p style=\"width:80%; padding:2px 0;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-68>\u6c37\u8010\u6027<\/a><\/p><p style=\"width:20%; padding:2px 0;\"><small>Lv 2<\/small><\/p><\/div><\/td><td><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1419\">\u30d5\u30ed\u30b7\u30b9\u30e1\u30bf\u30eb<\/a><\/p><p class=\"table-armor-right\">x 1<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1285\">\u30e9\u30f3\u30dd\u30b9\u306e\u539a\u76ae<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-1323\">\u5352\u5012\u660f\u7761\u888b<\/a><\/p><p class=\"table-armor-right\">x 2<\/p><\/div><div class=\"table-armor-cell\"><p class=\"table-armor-left\"><a href=\"https:\/\/gamepedia.jp\/mh-rise\/item\/item-294\">\u7720\u72d7\u7adc\u306e\u5c16\u722a<\/a><\/p><p class=\"table-armor-right\">x 3<\/p><\/div><\/td><\/tr><\/tbody><\/table><style>\n    .table-armor-cell{\n        display:flex;\n        flex-wrap:nowrap;\n        width:90%;\n        margin:0 auto;\n    }\n    .table-armor-left{\n        margin:0px;\n        padding:2px;\n        width:80%;\n    }\n    .table-armor-right{\n        margin:0px;\n        padding:2px;\n        text-align:left;\n        width:10%;\n        white-space:nowrap;\n    }\n    <\/style><h2>\u88c5\u98fe\u54c1\u306e\u751f\u7523\u306b\u4f7f\u7528<\/h2><table class=\"mhrise-table\" style=\"text-align:center; margin-bottom:-1px; width:100%;\"><thead><tr><th>\u540d\u524d<\/th><th>\u30b9\u30ad\u30eb<\/th><\/tr><\/thead><tbody><tr><td style=\"width:50%;\"><a href=https:\/\/gamepedia.jp\/mh-rise\/decoration\/decoration-93>\u7761\u7720\u73e0\u3010\uff12\u3011<\/a><\/td><td><a href=https:\/\/gamepedia.jp\/mh-rise\/skill\/skill-19>\u7761\u7720\u5c5e\u6027\u5f37\u5316<small style=\"padding-left:5px;\">Lv 1<\/small><\/td><\/tr><\/tbody><\/table>\n<h2  class=\"\">\u660f\u7761\u888b\u306e\u52d5\u753b<\/h2>\n\n<ul class=\"media-list image-grid row\">\n  <div>\n\n<div>\n  <a class=\"\" data-video-id=\"JpyyIqIN39A\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=JpyyIqIN39A\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/JpyyIqIN39A\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3000\u660f\u7761\u888b\u306e\u5165\u624b\u65b9\u6cd5\u306f\uff1f\u3000\u3010MHRISE\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"evLLpfJwUU8\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=evLLpfJwUU8\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/evLLpfJwUU8\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3000\u7761\u7720\u888b\u306e\u5165\u624b\u65b9\u6cd5\u306f\uff1f\u3000\u3010MHRISE\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"oRg9nG_c5QM\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=oRg9nG_c5QM\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/oRg9nG_c5QM\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u30e2\u30f3\u30cf\u30f3\u3011\u9006\u9c572000\u500b\u51fa\u305f\u53cb\u9054\u3010\u30e9\u30a4\u30ba\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"VsqGjNvQUbQ\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=VsqGjNvQUbQ\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/VsqGjNvQUbQ\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u6b66\u5668\u30b3\u30f3\u30d7\u52e2\u3042\u308b\u3042\u308b\u3010\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\uff1a\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011#\u30e2\u30f3\u30cf\u30f3 #\u30b5\u30f3\u30d6\u30ec\u30a4\u30af #\u6d77\u5916\u30df\u30fc\u30e0 #memes #shorts        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n    <\/div>\n    <div class=\"nav-more\" style=\"margin-top:10px;\">\n        <a class=\"btn btn-nav-more hide-me\" data-toggle=\"collapse\" href=\"#collapse-video-list-413095712\">\u3082\u3063\u3068\u898b\u308b<\/a>\n    <\/div>\n    <div id=\"collapse-video-list-413095712\" class=\"collapse\">\n\n<div>\n  <a class=\"\" data-video-id=\"jG-4mhqFV-k\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=jG-4mhqFV-k\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/jG-4mhqFV-k\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30e2\u30f3\u30cf\u30f3\u306e\u592a\u5200\u3092\u73fe\u5b9f\u3067\u4f5c\u308b\u7537\u3010\u30e2\u30f3\u30cf\u30f3\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"MdPioT5UrmI\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=MdPioT5UrmI\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/MdPioT5UrmI\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u5352\u5012\u660f\u7761\u888b\u3092\u63a2\u3059\u65c5        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"hhs_jdatyoA\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=hhs_jdatyoA\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/hhs_jdatyoA\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u30e2\u30f3\u30cf\u30f3\u3011\u7686\u304c\u601d\u3046\u6700\u5f37\u306e\u5080\u7570\u514b\u670d\u30e2\u30f3\u30b9\u30bf\u30fcTOP3\u3010\u30a2\u30f3\u30b1\u30fc\u30c8\u3011\u3010\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"GSJIvjOCNc8\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=GSJIvjOCNc8\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/GSJIvjOCNc8\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3000\u53cc\u5263\u30fb\u5fcd\u56e3\u5b50\u3010\u7761\u871c\u7389\u3011\u7d76\u3078\u5f37\u5316\u3002\u8db3\u308a\u306a\u3044\u7d20\u6750\u3092\u3082\u3089\u3044\u306b\u884c\u3063\u3066\u304d\u307e\u3059\u3002        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"3QM5STRXyXI\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=3QM5STRXyXI\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/3QM5STRXyXI\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          2000\u6642\u9593\u8cbb\u3084\u3057\u305f\u6700\u5f37\u592a\u5200\u88c5\u5099\u3092\u7d39\u4ecb\u3057\u3088\u3046#shorts \u3010\u30e2\u30f3\u30cf\u30f3\u3011\u3010\u30a2\u30a4\u30b9\u30dc\u30fc\u30f3\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"dH6oo-OPH4I\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=dH6oo-OPH4I\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/dH6oo-OPH4I\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u3011\u3053\u308c\u3092\u898b\u308c\u3070\u307e\u308b\u308f\u304b\u308a\uff01\u672a\u5165\u624b\u7d20\u6750\u3092\u52b9\u7387\u7684\u306b\u96c6\u3081\u3088\u3046\uff01\u30cf\u30f3\u30bf\u30fc\u30ce\u30fc\u30c8\u5168\u96c6        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"O6fQWrlvkXQ\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=O6fQWrlvkXQ\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/O6fQWrlvkXQ\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010\u30e2\u30f3\u30cf\u30f3\u3011\u30a2\u30a4\u30b9\u30dc\u30fc\u30f3\u3067\u6700\u3082\u4e71\u7372\u3055\u308c\u305f\u30e2\u30f3\u30b9\u30bf\u30fc\u90545\u9078#shorts \u3010MHWI\u3011        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"5V3RuTYgbSk\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=5V3RuTYgbSk\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/5V3RuTYgbSk\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u624b\u653e\u305b\u306a\u3044!!\u4fbf\u5229\u3059\u304e\u308b\u5f37\u529b\u30a2\u30a4\u30c6\u30e0\u30924\u9078\u7d39\u4ecb\u3057\u307e\u3059\uff01#\u30a2\u30a4\u30b9\u30dc\u30fc\u30f3 #shorts #short        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"FSm3_Ly7HbU\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=FSm3_Ly7HbU\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/FSm3_Ly7HbU\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          \u3010MHW\u3011\u7279\u6b8a\u95d8\u6280\u5834\uff1a\u98db\u96fb\u7adc\u4e0a\u4f4d\u7de8 \u30c8\u30d3\u30ab\u30ac\u30c1\u72e9\u731f \u96fb\u6483\u888b\u5927\u91cfGET!!(^^) \u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\uff1a\u30ef\u30fc\u30eb\u30c9 #43        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div>\n  <a class=\"\" data-video-id=\"xExTzUpXJlQ\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=xExTzUpXJlQ\">\n  <div class=\"col-xs-12 col-sm-6\">\n    <div class=\"media media-square\">\n      <div class=\"media-object\">\n        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/xExTzUpXJlQ\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/>\n      <\/div>\n      <div class=\"media-body\">\n        <div class=\"media-heading\">\n          [MHW:I]\u4f1d\u7d71\u306e\u6226\u8853\u3001\u7761\u7720\u7206\u7834\u306e\u30c0\u30e1\u30fc\u30b8\u691c\u8a3c*[\u30e2\u30f3\u30cf\u30f3]        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n  <\/a>\n<\/div>\n\n\n<\/div>\n<\/ul>\n\n<p class=\"text-center text-ss text-weak\">YouTube DATA API\u3067\u81ea\u52d5\u53d6\u5f97\u3057\u305f\u52d5\u753b\u3092\u8868\u793a\u3057\u3066\u3044\u307e\u3059<\/p><p>Twitter\u306e\u691c\u7d22\u7d50\u679c\u306f\u4ee5\u4e0b\u306eURL\u304b\u3089\u3054\u89a7\u304f\u3060\u3055\u3044\u3002<br><div class=\"nav-more\">\n<a class=\"btn btn-nav-more \" href=\"https:\/\/twitter.com\/search?q=%E3%83%A2%E3%83%B3%E3%83%8F%E3%83%B3%E3%83%A9%E3%82%A4%E3%82%BA+%E6%98%8F%E7%9D%A1%E8%A2%8B\" target=\"\" >\n    \u30c4\u30a4\u30fc\u30c8\u691c\u7d22\u7d50\u679c\u3078<\/a>\n<\/div>\n\n<\/p>\n<div  class=\"cv-link cv-event cv-regist-btn reg-btn-red\"  data-cv_category=\"cv-link\"  data-cv_action=\"click\"  data-cv_url=\"https:\/\/gamepedia.jp\/mh-rise\/items\"  data-cv_label=\"\u30a2\u30a4\u30c6\u30e0\u30fb\u7d20\u6750\u691c\u7d22\u30c4\u30fc\u30eb\u3078\"  >\n  <a href=\"https:\/\/gamepedia.jp\/mh-rise\/items\" rel=\"\" target=\"\" >\n  <img loading=\"lazy\" decoding=\"async\" style=\"width:0; height:1px;\" src=\"https:\/\/images.gamepedia.jp\/common\/beacon.png?url=https%3A%2F%2Fgamepedia.jp%2Fmh-rise%2Fitems\" border=\"0\" width=\"0\" height=\"1\" \/>  \u30a2\u30a4\u30c6\u30e0\u30fb\u7d20\u6750\u691c\u7d22\u30c4\u30fc\u30eb\u3078  <\/a>\n<\/div>\n<\/div>","protected":false},"author":2,"featured_media":0,"menu_order":215,"comment_status":"open","ping_status":"closed","template":"","meta":{"event_start_date":[],"event_end_date":[],"external_thumbnail_url":"","redirect":"","last_comment_date":"","footnotes":""},"item_maps":"","item_category":"\u7d20\u6750","class_list":["post-9895","item","type-item","status-publish","hentry","item_category-290"],"long_title":"\u3010\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba\u3011\u660f\u7761\u888b\u306e\u4f7f\u3044\u9053\u30fb\u5165\u624b\u65b9\u6cd5\u3010\u30b5\u30f3\u30d6\u30ec\u30a4\u30af\u3011","user":"hiro","str_count":0,"category_name":"","tag_name":"","is_pr":false,"pr_mode":null,"hide_ad":false,"comment_count":0,"original_content":"","site_name":"\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30e9\u30a4\u30ba","is_valid_post_type":true,"is_password_required":false,"thumbnail_url":"https:\/\/i0.wp.com\/s3-ap-northeast-1.amazonaws.com\/media.gamepedia\/gamepedia\/wp-content\/uploads\/2019\/12\/29124928\/no_img-480x267.png?resize=200%2C200&ssl=1","_links":{"self":[{"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/items\/9895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/items"}],"about":[{"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/types\/item"}],"author":[{"embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/comments?post=9895"}],"version-history":[{"count":1,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/items\/9895\/revisions"}],"predecessor-version":[{"id":12128,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/items\/9895\/revisions\/12128"}],"wp:attachment":[{"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/media?parent=9895"}],"wp:term":[{"taxonomy":"item_maps","embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/item_maps?post=9895"},{"taxonomy":"item_category","embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-rise\/wp-json\/wp\/v2\/item_category?post=9895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}