{"id":5096,"date":"2025-03-01T05:00:20","date_gmt":"2025-02-28T20:00:20","guid":{"rendered":"https:\/\/gamepedia.jp\/mh-wilds\/item\/5096"},"modified":"2025-03-13T15:06:41","modified_gmt":"2025-03-13T06:06:41","slug":"item-material-125","status":"publish","type":"item","link":"https:\/\/gamepedia.jp\/mh-wilds\/item\/5096","title":{"rendered":"\u3010\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba\u3011\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8\u306e\u4f7f\u3044\u9053\u30fb\u5165\u624b\u65b9\u6cd5\u3010\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u3011"},"content":{"rendered":"\n<p>\u300e\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30ef\u30a4\u30eb\u30ba\u300f\u306b\u767b\u5834\u3059\u308b\u30a2\u30a4\u30c6\u30e0\u300c\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8\u300d\u306e\u5165\u624b\u65b9\u6cd5\u3001\u4f7f\u3044\u9053\u306a\u3069\u306e\u653b\u7565\u60c5\u5831\u3092\u4ee5\u4e0b\u3067\u89e3\u8aac\u3057\u3066\u3044\u307e\u3059\u3002<\/p><h2>\u300c\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8\u300d\u306e\u8a73\u7d30<\/h2>    <table><tbody>\n        <tr><th class=\"tw-w-1\/3\">\u540d\u524d<\/th><td><img decoding=\"async\" class=\"icon-20\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/item_icon\/180.png\"\/>\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/td><\/tr>\n        <tr><th>\u3088\u307f\u304c\u306a<\/th><td>\u3057\u304b\u304f\u3082\u306e\u3073\u304d\u3087\u304f<\/td><\/tr>\n        <tr><th>\u30ab\u30c6\u30b4\u30ea<\/th><td>\n\n<a class=\"btn   btn-terms btn-item_category btn-item_category-\u88c5\u5099\u7d20\u6750\" href=\"https:\/\/gamepedia.jp\/mh-wilds\/items?item_category=%e8%a3%85%e5%82%99%e7%b4%a0%e6%9d%90\">\u88c5\u5099\u7d20\u6750<\/a>\n<\/td><\/tr>\n        \n        \n        <tr><th>\u30ec\u30a2\u30ea\u30c6\u30a3<\/th><td>4<\/td><\/tr>\n        <tr><th>\u8cfc\u5165\u4fa1\u683c<\/th><td>5500<\/td><\/tr>\n        <tr><th>\u58f2\u5374\u4fa1\u683c<\/th><td>550<\/td><\/tr>\n        <tr><th>\u6700\u5927\u6240\u6301\u6570<\/th><td>99<\/td><\/tr>\n            <tr><th>\u6982\u8981<\/th><td class=\"text-s\">\u30e9\u30d0\u30e9\u30fb\u30d0\u30ea\u30ca\u306e\u5c3e\u68d8\u3002\u5263\u306e\u5207\u3063\u5148\u306e\u3088\u3046\u306b\u92ed\u304f\u5c16\u3063\u3066\u3044\u308b\u3002\u4e00\u7a81\u304d\u3067\u7372\u7269\u3092\u4ed5\u7559\u3081\u308b\u3002<\/td><\/tr>\n    <\/tbody><\/table><h2>\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8\u306e\u5165\u624b\u65b9\u6cd5<\/h2><h3>\u30e2\u30f3\u30b9\u30bf\u30fc\u304b\u3089\u5165\u624b<\/h3><div class=\"wilds-more-toggle-wrapper tw-select-none\">\n    \n    \n    <div class=\"wilds-toggle-list\"><div class=\"tw-divide-solid tw-divide-y tw-divide-gray-200 wild-odd-bg\"><div class=\"tw-flex tw-items-center\">\n    <div class=\"tw-pt-1 tw-pb-1 tw-m-1 tw-bg-gray-600 tw-w-1\/4 tw-text-sm tw-font-extralight tw-text-center tw-text-white tw-rounded-sm\">\u7d20\u6750<\/div>\n    <div class=\"tw-pt-1 tw-pb-1 tw-m-1 tw-bg-gray-600 tw-w-3\/4 tw-text-sm tw-font-extralight tw-text-center tw-text-white tw-rounded-sm\">\u5165\u624b\u65b9\u6cd5<\/div>\n<\/div><div class=\"tw-flex tw-items-center\">\n    <div class=\"tw-pt-1 tw-pb-1 tw-m-1 tw-w-full tw-text-sm tw-text-white tw-font-extralight tw-text-center tw-rounded-md tw-border-solid tw-border tw-border-gray-200 tw-bg-green-600\">\u30e9\u30d0\u30e9\u30fb\u30d0\u30ea\u30ca\u304b\u3089\u30c9\u30ed\u30c3\u30d7<\/div>\n<\/div><div class=\"tw-mr-1 tw-ml-1 tw-pt-2 tw-pb-2 tw-flex tw-items-center wilds-toggle-items\" data-filter=\"\u4e0b\u4f4d\">\n    <div class=\"tw-w-1\/4 tw-text-sm tw-font-extralight tw-text-left tw-pr-2 \"><a class=\"tw-text-blue-500 md:tw-text-sm tw-text-xs\" href=https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125>\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><div class=\"tw-grid tw-grid-cols-2 tw-gap-1\"><div class=\"tw-text-xs tw-bg-indigo-100 tw-rounded-md tw-text-center tw-font-bold tw-border-solid tw-border tw-border-gray-200 tw-tracking-widest\">\u4e0b\u4f4d<\/div><\/div><\/div>\n    <div class=\"tw-w-3\/4 tw-flex tw-items-center\">\n        <div class=\"tw-w-full tw-grid tw-grid-cols-2 tw-gap-1\"><div class=\"tw-text-xs\">\n    \u25cf\u5265\u304e\u53d6\u308a<span class=\"tw-pl-1 tw-text-red-600 tw-inline-block\">[11%]<\/span>\n<\/div><div class=\"tw-text-xs\">\n    \u25cf\u90e8\u4f4d\u7834\u58ca\u5831\u916c\uff08\u82b1\u5f01\u72b6\u90e8\uff09<span class=\"tw-pl-1 tw-text-red-600 tw-inline-block\">[100%]<\/span>\n<\/div><div class=\"tw-text-xs\">\n    \u25cf\u72e9\u731f\u5831\u916c<span class=\"tw-pl-1 tw-text-red-600 tw-inline-block\">[8%]<\/span>\n<\/div><\/div><\/div><\/div><\/div>    <\/div>\n<\/div><h3>\u95a2\u9023\u30e2\u30f3\u30b9\u30bf\u30fc<\/h3><div class=\"wilds-more-toggle-wrapper tw-select-none\">\n    \n<div class=\"tw-p-1 tw-border-solid tw-border tw-border-gray-200 tw-rounded-sm tw-divide-solid tw-divide-y tw-divide-gray-300 wilds-toggle-list\">\n<div class=\"tw-flex\">\n    <div class=\"tw-py-1 tw-w-1\/5 \">\n    <\/div>\n    <div class=\"tw-py-1 tw-w-4\/5 tw-grid tw-grid-cols-5 tw-divide-solid tw-divide-x tw-divide-gray-200\">\n        <div class=\"tw-text-center\">\n            <div class=\"tw-text-xs tw-bg-red-500 tw-px-1 tw-text-white tw-whitespace-nowrap tw-pt-1 tw-pb-1 tw-font-semibold\">\u706b<\/div>\n        <\/div>\n        <div class=\"tw-text-center\">\n            <div class=\"tw-text-xs tw-bg-blue-500 tw-px-1 tw-text-white tw-whitespace-nowrap tw-pt-1 tw-pb-1 tw-font-semibold\">\u6c34<\/div>\n        <\/div>\n        <div class=\"tw-text-center\">\n            <div class=\"tw-text-xs tw-bg-yellow-500 tw-px-1 tw-text-white tw-whitespace-nowrap tw-pt-1 tw-pb-1 tw-font-semibold\">\u96f7<\/div>\n        <\/div>\n        <div class=\"tw-text-center\">\n            <div class=\"tw-text-xs tw-bg-blue-600 tw-px-1 tw-text-white tw-whitespace-nowrap tw-pt-1 tw-pb-1 tw-font-semibold\">\u6c37<\/div>\n        <\/div>\n        <div class=\"tw-text-center\">\n            <div class=\"tw-text-xs tw-bg-green-500 tw-px-1 tw-text-white tw-whitespace-nowrap tw-pt-1 tw-pb-1 tw-font-semibold\">\u9f8d<\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"tw-py-1 wilds-toggle-items\"><div class=\"tw-flex tw-bg-gray-100 tw-items-center tw-overflow-hidden tw-border-solid tw-border-l-8 tw-border-indigo-400\">\n    <div class=\"tw-w-1\/4 tw-h-10\"><div class=\"tw-mr-4 tw-bg-cover tw-h-full tw-object-cover tw-bg-center tw-bg-no-repeat\" style=\"transform: scale(1.1); background-image:url(https:\/\/images.gamepedia.jp\/mh-wilds\/monster_header\/5.png)\"><\/div><\/div><div class=\"tw-text-sm tw-py-3 tw-pl-2\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/monster\/monster-5\">\u30e9\u30d0\u30e9\u30fb\u30d0\u30ea\u30ca<\/a><\/div><\/div><div class=\"tw-grid tw-grid-cols-1 tw-divide-solid tw-divide-y tw-divide-gray-300 \">\n    <div class=\"tw-flex tw-items-center tw-items-stretch\">\n        <div class=\"tw-w-1\/5 tw-text-xs md:tw-text-sm tw-bg-gray-600 tw-mr-1 tw-px-1 tw-text-white tw-rounded-sm tw-px-1 tw-h-full tw-flex tw-items-center tw-justify-center\">\u5f31\u70b9\u5c5e\u6027<\/div>\n<div class=\"tw-w-4\/5 tw-grid tw-grid-cols-5 tw-divide-solid tw-divide-x tw-divide-gray-200\">\n    <div class=\"tw-text-center\">\n        <div class=\"tw-font-bold tw-bg-white tw-bg-opacity-60 tw-bg-red-50 tw-text-black tw-p-2\">\u25ce<\/div>\n    <\/div>\n    <div class=\"tw-text-center\">\n        <div class=\"tw-font-bold tw-bg-white tw-bg-opacity-60 tw-bg-blue-50 tw-text-black tw-p-2 \">\u00d7<\/div>\n    <\/div>\n    <div class=\"tw-text-center\">\n        <div class=\"tw-font-bold tw-bg-white tw-bg-opacity-60 tw-bg-yellow-50 tw-text-black tw-p-2 \">\u25cb<\/div>\n    <\/div>\n    <div class=\"tw-text-center\">\n        <div class=\"tw-font-bold tw-bg-white tw-bg-opacity-60 tw-bg-blue-100 tw-text-black tw-p-2 \">\u25b3<\/div>\n    <\/div>\n    <div class=\"tw-text-center\">\n        <div class=\"tw-font-bold tw-bg-white tw-bg-opacity-60 tw-bg-green-50 tw-text-black tw-p-2 \">\u00d7<\/div>\n    <\/div>\n\n<\/div>\n    <\/div>\n        <div class=\"tw-text-center tw-flex tw-items-stretch\">\n        <div class=\"tw-w-1\/5 tw-text-xs md:tw-text-sm tw-bg-gray-600 tw-mr-1 tw-px-1 tw-text-white tw-rounded-sm tw-px-1 tw-h-full tw-flex tw-items-center tw-justify-center\">\u5207\u65ad<\/div>\n        <div class=\"tw-w-4\/5 tw-text-sm tw-text-left tw-text-black tw-p-2 tw-bg-white tw-bg-opacity-60\">\n            <div>\u982d\u3001\u5c3b\u5c3e\u3001\u82b1\u5f01\u72b6\u90e8<\/div>\n        <\/div>\n    <\/div>\n    <div class=\"tw-text-center tw-flex tw-items-stretch\">\n        <div class=\"tw-w-1\/5 tw-text-xs md:tw-text-sm tw-bg-gray-600 tw-mr-1 tw-px-1 tw-text-white tw-rounded-sm tw-px-1 tw-h-full tw-flex tw-items-center tw-justify-center\">\u6253\u6483<\/div>\n        <div class=\"tw-w-4\/5 tw-text-sm tw-text-left tw-text-black tw-p-2 tw-bg-white tw-bg-opacity-60\">\n            <div>\u982d\u3001\u5c3b\u5c3e\u3001\u82b1\u5f01\u72b6\u90e8<\/div>\n        <\/div>\n    <\/div>\n    <div class=\"tw-text-center tw-flex tw-items-stretch\">\n        <div class=\"tw-w-1\/5 tw-text-xs md:tw-text-sm tw-bg-gray-600 tw-mr-1 tw-px-1 tw-text-white tw-rounded-sm tw-px-1 tw-h-full tw-flex tw-items-center tw-justify-center\">\u5f3e<\/div>\n        <div class=\"tw-w-4\/5 tw-text-sm tw-text-left tw-text-black tw-p-2 tw-bg-white tw-bg-opacity-60\">\n            <div>\u982d\u3001\u5c3b\u5c3e\u3001\u82b1\u5f01\u72b6\u90e8<\/div>\n        <\/div>\n    <\/div>\n    <div class=\"tw-flex tw-items-center\">\n        <div class=\"tw-w-1\/5 tw-text-xs md:tw-text-sm tw-bg-gray-600 tw-mr-1 tw-px-1 tw-text-white tw-rounded-sm tw-px-1 tw-h-full tw-flex tw-items-center tw-justify-center\"><div class=\"text-center\">\u6709\u52b9\u306a\u7f60<span class=\"tw-inline-block\">\u30a2\u30a4\u30c6\u30e0<\/span><\/div><\/div>\n        <div class=\"tw-w-4\/5 tw-grid tw-grid-cols-4 tw-gap-2 tw-py-1\">\n                <div class=\"tw-text-center\">\n        <div class=\"tw-text-xs tw-bg-gray-600 tw-rounded-t-sm tw-px-1 tw-text-white tw-whitespace-nowrap tw-pt-1 tw-pb-1\">\u843d\u3068\u3057\u7a74<\/div>\n        <div class=\"tw-text-sm tw-rounded-b-sm tw-bg-white tw-bg-opacity-60 tw-text-black tw-p-2 tw-border-solid tw-border tw-border-gray-200 tw-whitespace-nowrap\">\u25cb<\/div>\n    <\/div>    <div class=\"tw-text-center\">\n        <div class=\"tw-text-xs tw-bg-gray-600 tw-rounded-t-sm tw-px-1 tw-text-white tw-whitespace-nowrap tw-pt-1 tw-pb-1\">\u30b7\u30d3\u30ec\u7f60<\/div>\n        <div class=\"tw-text-sm tw-rounded-b-sm tw-bg-white tw-bg-opacity-60 tw-text-black tw-p-2 tw-border-solid tw-border tw-border-gray-200 tw-whitespace-nowrap\">\u25cb<\/div>\n    <\/div>    <div class=\"tw-text-center\">\n        <div class=\"tw-text-xs tw-bg-gray-600 tw-rounded-t-sm tw-px-1 tw-text-white tw-whitespace-nowrap tw-pt-1 tw-pb-1\">\u9583\u5149\u7389<\/div>\n        <div class=\"tw-text-sm tw-rounded-b-sm tw-bg-white tw-bg-opacity-60 tw-text-black tw-p-2 tw-border-solid tw-border tw-border-gray-200 tw-whitespace-nowrap\">\u25cb<\/div>\n    <\/div>    <div class=\"tw-text-center\">\n        <div class=\"tw-text-xs tw-bg-gray-600 tw-rounded-t-sm tw-px-1 tw-text-white tw-whitespace-nowrap tw-pt-1 tw-pb-1\">\u97f3\u7206\u5f3e<\/div>\n        <div class=\"tw-text-sm tw-rounded-b-sm tw-bg-white tw-bg-opacity-60 tw-text-black tw-p-2 tw-border-solid tw-border tw-border-gray-200 tw-whitespace-nowrap\">\u00d7<\/div>\n    <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div>    <\/div>\n<\/div><h2>\u7d20\u6750\u306e\u4f7f\u3044\u9053<\/h2><h3>\u6b66\u5668\u751f\u7523\u3001\u5f37\u5316\u306b\u4f7f\u7528<\/h3><h4>\u6b66\u5668\u306e\u6027\u80fd<\/h4><div class=\"wilds-more-toggle-wrapper tw-select-none\">\n        <div class=\"tw-flex tw-items-center tw-space-x-2\">\n    <input type=\"text\"\n            placeholder=\"\u30ad\u30fc\u30ef\u30fc\u30c9\u691c\u7d22\"\n            class=\"wilds-search-input tw-border tw-rounded tw-px-3 tw-py-2 tw-w-full\">\n    <\/div>\n        <div class=\"tw-grid md:tw-grid-cols-7 tw-grid-cols-5 tw-gap-2 wilds-filter wilds-filter-lim-1 tw-p-2\">\n            <div class=\"wilds-filter-item-0 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u5927\u5263\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/0.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-1 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u592a\u5200\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/1.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-2 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u7247\u624b\u5263\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/2.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-3 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u53cc\u5263\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/3.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-4 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u30cf\u30f3\u30de\u30fc\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/4.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-5 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u72e9\u731f\u7b1b\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/5.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-6 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u30e9\u30f3\u30b9\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/6.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-7 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u30ac\u30f3\u30e9\u30f3\u30b9\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/7.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-8 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u30b9\u30e9\u30c3\u30b7\u30e5\u30a2\u30c3\u30af\u30b9\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/8.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-9 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u30c1\u30e3\u30fc\u30b8\u30a2\u30c3\u30af\u30b9\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/9.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-10 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u64cd\u866b\u68cd\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/10.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-11 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u30e9\u30a4\u30c8\u30dc\u30a6\u30ac\u30f3\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/11.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-12 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u30d8\u30d3\u30a3\u30dc\u30a6\u30ac\u30f3\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/12.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>    <div class=\"wilds-filter-item-13 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u5f13\">\n        <div class=\"wilds-weapon-icon tw-w-1\/2 tw-h-full\">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/13.webp\" alt=\"Icon\">\n<\/div>\n    <\/div>\n    <\/div>\n<div class=\"tw-p-1 tw-rounded-sm tw-divide-solid tw-divide-y tw-divide-gray-200 tw-border-solid tw-border tw-border-gray-200 wilds-toggle-list wilds-sorter\">\n    <div class=\"tw-flex tw-items-center\"><div class=\"tw-w-2\/5 md:tw-w-1\/2 \"><\/div><div class=\"tw-w-3\/5 md:tw-w-1\/2 tw-text-center tw-text-xs\">\u653b\u6483\u529b\u30fb\u9632\u5fa1\u529b\u306a\u3069\u3092\u30bf\u30c3\u30d7\u3057\u3066\u30bd\u30fc\u30c8<\/div><\/div>\n<div class=\"tw-p-2 tw-bg-gray-50 tw-border-solid tw-border-t-2 tw-border-l-2 tw-border-r-2 tw-border-gray-200 tw-rounded-t-sm tw-flex tw-items-center\">\n    <div class=\"tw-w-2\/5 md:tw-w-1\/2 tw-text-sm tw-font-extralight tw-text-left\">\u540d\u524d<div class=\"tw-text-xs\">\u25cf\u30b9\u30ad\u30eb<\/div><div class=\"tw-text-xs\"><span class=\"tw-text-red-600 tw-px-1\">\u25a0<\/span>\u56fa\u6709\u52b9\u679c<\/div><\/div>\n    <div class=\"tw-w-3\/5 md:tw-w-1\/2\">\n        <div class=\"tw-flex tw-items-center tw-gap-2\">\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-xs tw-text-center tw-text-white tw-bg-gray-600 tw-rounded-md tw-whitespace-nowrap tw-cursor-pointer wilds-sorter-h-1 wilds-sorter-data-int\">\u30b9\u30ed<\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-xs tw-text-center tw-text-white tw-bg-gray-600 tw-rounded-md tw-whitespace-nowrap tw-cursor-pointer wilds-sorter-h-2 wilds-sorter-int wilds-sort-desc\">\u653b\u6483\u529b<\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-xs tw-text-center tw-text-white tw-bg-gray-600 tw-rounded-md tw-whitespace-nowrap tw-cursor-pointer wilds-sorter-h-3 wilds-sorter-int\">\u9632\u5fa1\u529b<\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-xs tw-text-center tw-text-white tw-bg-gray-600 tw-rounded-md tw-whitespace-nowrap tw-cursor-pointer wilds-sorter-h-4 wilds-sorter-int\">\u5c5e\u6027<\/div>\n        <\/div>\n        <div class=\"tw-text-center tw-mt-1 tw-p-1 tw-text-xs tw-rounded-md tw-border-solid tw-border tw-border-indigo-200 \">\u5207\u308c\u5473\/\u30d3\u30f3<\/div>\n        <div class=\"tw-grid tw-grid-cols-4 tw-gap-1 tw-py-1\">\n            <div class=\"tw-text-xs tw-border tw-border-solid tw-border-indigo-600 tw-rounded-md tw-text-center\">\u901f\u5c04<\/div>\n            <div class=\"tw-text-xs tw-border tw-border-solid tw-border-gray-300 tw-rounded-md tw-text-center tw-bg-white\">Lv 1<\/div>\n            <div class=\"tw-text-xs tw-border tw-border-solid tw-border-gray-300 tw-rounded-md tw-text-center tw-bg-green-50\">Lv 2<\/div>\n            <div class=\"tw-text-xs tw-border tw-border-solid tw-border-gray-300 tw-rounded-md tw-text-center tw-bg-red-50\">Lv 3<\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"tw-py-1 tw-flex tw-items-center  wilds-toggle-items wilds-sorder-tr\" data-filter=\"\u30b8\u30a7\u30a4\u30eb\u30cf\u30f3\u30de\u30fc\u2161,\u30cf\u30f3\u30de\u30fc\">\n    <div class=\"tw-w-2\/5 md:tw-w-1\/2 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-pl-2\">\n        <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/4.webp\" alt=\"Icon\">\n<\/div><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-328\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u9ebb\u75fa\u5c5e\u6027\u6d3e\u751f<\/div>\u30b8\u30a7\u30a4\u30eb\u30cf\u30f3\u30de\u30fc\u2161<\/a>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u6e1b\u6c17\u5a01\u529b1.3\u500d\">\u30b9\u30bf\u30df\u30ca\u596a\u53d6+2<\/span><\/div><\/div><\/div>\n        \n    <\/div>\n    <div class=\"tw-w-3\/5 md:tw-w-1\/2 tw-h-full\">\n        <div class=\"tw-text-center tw-flex tw-items-center tw-items-stretch tw-divide-solid tw-divide-x tw-divide-gray-300 tw-gap-y-2 tw-py-1\">\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black tw-whitespace-nowrap wilds-sorter-t-1\" data-filter-int=\"000\"><div class=\"tw-whitespace-nowrap\"><\/div><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-2\">\n                <div class=\"tw-h-full tw-flex tw-flex-wrap tw-items-center tw-justify-center tw-text-sm tw-text-black\"><div class=\"tw-leading-3\">728<div class=\"tw-text-xs tw-text-green-800\">(140)<\/div><\/div><\/div>\n\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-3\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black\"><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-4\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-black tw-whitespace-nowrap\"><div class=\"md:tw-text-sm tw-text-xs\">\u9ebb\u75fa17<\/div><\/div>\n            <\/div>\n        <\/div>\n        <div class=\"tw-px-1\">\n            \n            <div class=\"tw-bg-gray-300 tw-p-1 tw-mt-1 tw-rounded-md tw-border-solid tw-border tw-border-gray-100\">\n    <div class=\"tw-rounded-sm tw-overflow-hidden\">\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 15%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 15%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 15%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 15%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 15%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 27.5%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n    <\/div>\n<\/div>\n            \n        <\/div>\n    <\/div>\n\n<\/div><div class=\"tw-py-1 tw-flex tw-items-center  wilds-toggle-items wilds-sorder-tr\" data-filter=\"\u30d1\u30eb\u30b8\u30fc\u30d6\u30ec\u30a4\u30c9\u2161,\u5927\u5263\">\n    <div class=\"tw-w-2\/5 md:tw-w-1\/2 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-pl-2\">\n        <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/0.webp\" alt=\"Icon\">\n<\/div><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-186\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u9ebb\u75fa\u5c5e\u6027\u6d3e\u751f<\/div>\u30d1\u30eb\u30b8\u30fc\u30d6\u30ec\u30a4\u30c9\u2161<\/a>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u7814\u304e\u52d5\u4f5c\u30922\u56de\u7701\u7565\">\u7825\u77f3\u4f7f\u7528\u9ad8\u901f\u5316+2<\/span><\/div><\/div><\/div>\n        \n    <\/div>\n    <div class=\"tw-w-3\/5 md:tw-w-1\/2 tw-h-full\">\n        <div class=\"tw-text-center tw-flex tw-items-center tw-items-stretch tw-divide-solid tw-divide-x tw-divide-gray-300 tw-gap-y-2 tw-py-1\">\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black tw-whitespace-nowrap wilds-sorter-t-1\" data-filter-int=\"000\"><div class=\"tw-whitespace-nowrap\"><\/div><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-2\">\n                <div class=\"tw-h-full tw-flex tw-flex-wrap tw-items-center tw-justify-center tw-text-sm tw-text-black\"><div class=\"tw-leading-3\">576<div class=\"tw-text-xs tw-text-green-800\">(120)<\/div><\/div><\/div>\n\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-3\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black\"><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-4\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-black tw-whitespace-nowrap\"><div class=\"md:tw-text-sm tw-text-xs\">\u9ebb\u75fa31<\/div><\/div>\n            <\/div>\n        <\/div>\n        <div class=\"tw-px-1\">\n            \n            <div class=\"tw-bg-gray-300 tw-p-1 tw-mt-1 tw-rounded-md tw-border-solid tw-border tw-border-gray-100\">\n    <div class=\"tw-rounded-sm tw-overflow-hidden\">\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 15%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 20%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 25%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 2.5%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 15%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 20%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 25%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 15%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n    <\/div>\n<\/div>\n            \n        <\/div>\n    <\/div>\n\n<\/div><div class=\"tw-py-1 tw-flex tw-items-center  wilds-toggle-items wilds-sorder-tr\" data-filter=\"\u30e9\u30d0\u30e9\u30fb\u30d6\u30ad\u30ea\u30a8\u2161,\u30c1\u30e3\u30fc\u30b8\u30a2\u30c3\u30af\u30b9\">\n    <div class=\"tw-w-2\/5 md:tw-w-1\/2 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-pl-2\">\n        <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/9.webp\" alt=\"Icon\">\n<\/div><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-67\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30d6\u30ad\u30ea\u30a8\u2161<\/a>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><div class=\"tw-w-full tw-font-light\">    <div class=\"tw-text-xs\">\n        <span class=\"tw-text-red-600 tw-px-1\">\u25a0<\/span>\u69b4\u5f3e\u30d3\u30f3\n    <\/div><\/div><\/div><\/div>\n        \n    <\/div>\n    <div class=\"tw-w-3\/5 md:tw-w-1\/2 tw-h-full\">\n        <div class=\"tw-text-center tw-flex tw-items-center tw-items-stretch tw-divide-solid tw-divide-x tw-divide-gray-300 tw-gap-y-2 tw-py-1\">\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black tw-whitespace-nowrap wilds-sorter-t-1\" data-filter-int=\"000\"><div class=\"tw-whitespace-nowrap\"><\/div><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-2\">\n                <div class=\"tw-h-full tw-flex tw-flex-wrap tw-items-center tw-justify-center tw-text-sm tw-text-black\"><div class=\"tw-leading-3\">432<div class=\"tw-text-xs tw-text-green-800\">(120)<\/div><\/div><span class=\"tw-text-xs tw-text-red-700 tw-whitespace-nowrap\"><img decoding=\"async\" class=\"tw-w-3.5 md:tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/status_icon\/aff.png\">10%<\/span><\/div>\n\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-3\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black\"><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-4\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-black tw-whitespace-nowrap\"><div class=\"md:tw-text-sm tw-text-xs\">\u9ebb\u75fa13<\/div><\/div>\n            <\/div>\n        <\/div>\n        <div class=\"tw-px-1\">\n            \n            <div class=\"tw-bg-gray-300 tw-p-1 tw-mt-1 tw-rounded-md tw-border-solid tw-border tw-border-gray-100\">\n    <div class=\"tw-rounded-sm tw-overflow-hidden\">\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 12.5%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 25%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 12.5%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 37.5%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n    <\/div>\n<\/div>\n            \n        <\/div>\n    <\/div>\n\n<\/div><div class=\"tw-py-1 tw-flex tw-items-center  wilds-toggle-items wilds-sorder-tr\" data-filter=\"\u30e9\u30d0\u30e9\u30fb\u30a2\u30c3\u30b7\u30a7\u2161,\u30b9\u30e9\u30c3\u30b7\u30e5\u30a2\u30c3\u30af\u30b9\">\n    <div class=\"tw-w-2\/5 md:tw-w-1\/2 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-pl-2\">\n        <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/8.webp\" alt=\"Icon\">\n<\/div><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-723\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30a2\u30c3\u30b7\u30a7\u2161<\/a>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><div class=\"tw-w-full tw-font-light\">    <div class=\"tw-text-xs\">\n        <span class=\"tw-text-red-600 tw-px-1\">\u25a0<\/span>\u5f37\u6483\u30d3\u30f3\n    <\/div><\/div><\/div><\/div>\n        \n    <\/div>\n    <div class=\"tw-w-3\/5 md:tw-w-1\/2 tw-h-full\">\n        <div class=\"tw-text-center tw-flex tw-items-center tw-items-stretch tw-divide-solid tw-divide-x tw-divide-gray-300 tw-gap-y-2 tw-py-1\">\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black tw-whitespace-nowrap wilds-sorter-t-1\" data-filter-int=\"000\"><div class=\"tw-whitespace-nowrap\"><\/div><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-2\">\n                <div class=\"tw-h-full tw-flex tw-flex-wrap tw-items-center tw-justify-center tw-text-sm tw-text-black\"><div class=\"tw-leading-3\">420<div class=\"tw-text-xs tw-text-green-800\">(120)<\/div><\/div><span class=\"tw-text-xs tw-text-red-700 tw-whitespace-nowrap\"><img decoding=\"async\" class=\"tw-w-3.5 md:tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/status_icon\/aff.png\">10%<\/span><\/div>\n\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-3\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black\"><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-4\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-black tw-whitespace-nowrap\"><div class=\"md:tw-text-sm tw-text-xs\">\u9ebb\u75fa12<\/div><\/div>\n            <\/div>\n        <\/div>\n        <div class=\"tw-px-1\">\n            \n            <div class=\"tw-bg-gray-300 tw-p-1 tw-mt-1 tw-rounded-md tw-border-solid tw-border tw-border-gray-100\">\n    <div class=\"tw-rounded-sm tw-overflow-hidden\">\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 10%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 27.5%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 10%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 40%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n    <\/div>\n<\/div>\n            \n        <\/div>\n    <\/div>\n\n<\/div><div class=\"tw-py-1 tw-flex tw-items-center  wilds-toggle-items wilds-sorder-tr\" data-filter=\"\u30e9\u30d0\u30e9\u30fb\u30b0\u30ec\u30d6\u2161,\u592a\u5200\">\n    <div class=\"tw-w-2\/5 md:tw-w-1\/2 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-pl-2\">\n        <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/1.webp\" alt=\"Icon\">\n<\/div><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-653\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30b0\u30ec\u30d6\u2161<\/a>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><\/div><\/div>\n        \n    <\/div>\n    <div class=\"tw-w-3\/5 md:tw-w-1\/2 tw-h-full\">\n        <div class=\"tw-text-center tw-flex tw-items-center tw-items-stretch tw-divide-solid tw-divide-x tw-divide-gray-300 tw-gap-y-2 tw-py-1\">\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black tw-whitespace-nowrap wilds-sorter-t-1\" data-filter-int=\"000\"><div class=\"tw-whitespace-nowrap\"><\/div><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-2\">\n                <div class=\"tw-h-full tw-flex tw-flex-wrap tw-items-center tw-justify-center tw-text-sm tw-text-black\"><div class=\"tw-leading-3\">396<div class=\"tw-text-xs tw-text-green-800\">(120)<\/div><\/div><span class=\"tw-text-xs tw-text-red-700 tw-whitespace-nowrap\"><img decoding=\"async\" class=\"tw-w-3.5 md:tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/status_icon\/aff.png\">10%<\/span><\/div>\n\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-3\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black\"><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-4\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-black tw-whitespace-nowrap\"><div class=\"md:tw-text-sm tw-text-xs\">\u9ebb\u75fa13<\/div><\/div>\n            <\/div>\n        <\/div>\n        <div class=\"tw-px-1\">\n            \n            <div class=\"tw-bg-gray-300 tw-p-1 tw-mt-1 tw-rounded-md tw-border-solid tw-border tw-border-gray-100\">\n    <div class=\"tw-rounded-sm tw-overflow-hidden\">\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 12.5%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 25%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 12.5%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 37.5%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n    <\/div>\n<\/div>\n            \n        <\/div>\n    <\/div>\n\n<\/div><div class=\"tw-py-1 tw-flex tw-items-center  wilds-toggle-items wilds-sorder-tr\" data-filter=\"\u30e9\u30d0\u30e9\u30fb\u30a2\u30d5\u30d7\u30cb\u2161,\u64cd\u866b\u68cd\">\n    <div class=\"tw-w-2\/5 md:tw-w-1\/2 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-pl-2\">\n        <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/10.webp\" alt=\"Icon\">\n<\/div><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-500\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30a2\u30d5\u30d7\u30cb\u2161<\/a>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><div class=\"tw-w-full tw-font-light\">    <div class=\"tw-text-xs\">\n        <span class=\"tw-text-red-600 tw-px-1\">\u25a0<\/span>\u731f\u866b Lv 4\n    <\/div><\/div><\/div><\/div>\n        \n    <\/div>\n    <div class=\"tw-w-3\/5 md:tw-w-1\/2 tw-h-full\">\n        <div class=\"tw-text-center tw-flex tw-items-center tw-items-stretch tw-divide-solid tw-divide-x tw-divide-gray-300 tw-gap-y-2 tw-py-1\">\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black tw-whitespace-nowrap wilds-sorter-t-1\" data-filter-int=\"000\"><div class=\"tw-whitespace-nowrap\"><\/div><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-2\">\n                <div class=\"tw-h-full tw-flex tw-flex-wrap tw-items-center tw-justify-center tw-text-sm tw-text-black\"><div class=\"tw-leading-3\">372<div class=\"tw-text-xs tw-text-green-800\">(120)<\/div><\/div><span class=\"tw-text-xs tw-text-red-700 tw-whitespace-nowrap\"><img decoding=\"async\" class=\"tw-w-3.5 md:tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/status_icon\/aff.png\">10%<\/span><\/div>\n\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-3\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black\"><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-4\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-black tw-whitespace-nowrap\"><div class=\"md:tw-text-sm tw-text-xs\">\u9ebb\u75fa12<\/div><\/div>\n            <\/div>\n        <\/div>\n        <div class=\"tw-px-1\">\n            \n            <div class=\"tw-bg-gray-300 tw-p-1 tw-mt-1 tw-rounded-md tw-border-solid tw-border tw-border-gray-100\">\n    <div class=\"tw-rounded-sm tw-overflow-hidden\">\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 10%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 27.5%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 10%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 40%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n    <\/div>\n<\/div>\n            \n        <\/div>\n    <\/div>\n\n<\/div><div class=\"tw-py-1 tw-flex tw-items-center  wilds-toggle-items wilds-sorder-tr\" data-filter=\"\u30d1\u30eb\u30b8\u30fc\u30ac\u30f3\u30e9\u30f3\u30b9\u2161,\u30ac\u30f3\u30e9\u30f3\u30b9\">\n    <div class=\"tw-w-2\/5 md:tw-w-1\/2 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-pl-2\">\n        <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/7.webp\" alt=\"Icon\">\n<\/div><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-264\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u9ebb\u75fa\u5c5e\u6027\u6d3e\u751f<\/div>\u30d1\u30eb\u30b8\u30fc\u30ac\u30f3\u30e9\u30f3\u30b9\u2161<\/a>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u30b9\u30ad\u30eb\u767a\u52d5\u4e2d\u3001\u653b\u6483\u529b1.1\u500d\">\u653b\u3081\u306e\u5b88\u52e2+2<\/span><\/div><div class=\"tw-w-full tw-font-light\">    <div class=\"tw-text-xs\">\n        <span class=\"tw-text-red-600 tw-px-1\">\u25a0<\/span>\u901a\u5e38\u578b\n    <\/div><\/div><\/div><\/div>\n        \n    <\/div>\n    <div class=\"tw-w-3\/5 md:tw-w-1\/2 tw-h-full\">\n        <div class=\"tw-text-center tw-flex tw-items-center tw-items-stretch tw-divide-solid tw-divide-x tw-divide-gray-300 tw-gap-y-2 tw-py-1\">\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black tw-whitespace-nowrap wilds-sorter-t-1\" data-filter-int=\"000\"><div class=\"tw-whitespace-nowrap\"><\/div><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-2\">\n                <div class=\"tw-h-full tw-flex tw-flex-wrap tw-items-center tw-justify-center tw-text-sm tw-text-black\"><div class=\"tw-leading-3\">299<div class=\"tw-text-xs tw-text-green-800\">(130)<\/div><\/div><\/div>\n\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-3\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black\"><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-4\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-black tw-whitespace-nowrap\"><div class=\"md:tw-text-sm tw-text-xs\">\u9ebb\u75fa21<\/div><\/div>\n            <\/div>\n        <\/div>\n        <div class=\"tw-px-1\">\n            \n            <div class=\"tw-bg-gray-300 tw-p-1 tw-mt-1 tw-rounded-md tw-border-solid tw-border tw-border-gray-100\">\n    <div class=\"tw-rounded-sm tw-overflow-hidden\">\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 12.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 20%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 20%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 10%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 12.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 20%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 20%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 22.5%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n    <\/div>\n<\/div>\n            \n        <\/div>\n    <\/div>\n\n<\/div><div class=\"tw-py-1 tw-flex tw-items-center  wilds-toggle-items wilds-sorder-tr\" data-filter=\"\u30e9\u30d0\u30e9\u30fb\u30ed\u30f3\u30b9\u2161,\u30e9\u30f3\u30b9\">\n    <div class=\"tw-w-2\/5 md:tw-w-1\/2 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-pl-2\">\n        <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/6.webp\" alt=\"Icon\">\n<\/div><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-586\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30ed\u30f3\u30b9\u2161<\/a>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><\/div><\/div>\n        \n    <\/div>\n    <div class=\"tw-w-3\/5 md:tw-w-1\/2 tw-h-full\">\n        <div class=\"tw-text-center tw-flex tw-items-center tw-items-stretch tw-divide-solid tw-divide-x tw-divide-gray-300 tw-gap-y-2 tw-py-1\">\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black tw-whitespace-nowrap wilds-sorter-t-1\" data-filter-int=\"000\"><div class=\"tw-whitespace-nowrap\"><\/div><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-2\">\n                <div class=\"tw-h-full tw-flex tw-flex-wrap tw-items-center tw-justify-center tw-text-sm tw-text-black\"><div class=\"tw-leading-3\">276<div class=\"tw-text-xs tw-text-green-800\">(120)<\/div><\/div><span class=\"tw-text-xs tw-text-red-700 tw-whitespace-nowrap\"><img decoding=\"async\" class=\"tw-w-3.5 md:tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/status_icon\/aff.png\">10%<\/span><\/div>\n\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-3\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black\"><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-4\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-black tw-whitespace-nowrap\"><div class=\"md:tw-text-sm tw-text-xs\">\u9ebb\u75fa13<\/div><\/div>\n            <\/div>\n        <\/div>\n        <div class=\"tw-px-1\">\n            \n            <div class=\"tw-bg-gray-300 tw-p-1 tw-mt-1 tw-rounded-md tw-border-solid tw-border tw-border-gray-100\">\n    <div class=\"tw-rounded-sm tw-overflow-hidden\">\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 12.5%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 25%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 12.5%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 37.5%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n    <\/div>\n<\/div>\n            \n        <\/div>\n    <\/div>\n\n<\/div><div class=\"tw-py-1 tw-flex tw-items-center  wilds-toggle-items wilds-sorder-tr\" data-filter=\"\u30e9\u30d0\u30e9\u30fb\u30d5\u30fc\u30b7\u30a7\u2161,\u53cc\u5263\">\n    <div class=\"tw-w-2\/5 md:tw-w-1\/2 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-pl-2\">\n        <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/3.webp\" alt=\"Icon\">\n<\/div><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-142\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30d5\u30fc\u30b7\u30a7\u2161<\/a>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><\/div><\/div>\n        \n    <\/div>\n    <div class=\"tw-w-3\/5 md:tw-w-1\/2 tw-h-full\">\n        <div class=\"tw-text-center tw-flex tw-items-center tw-items-stretch tw-divide-solid tw-divide-x tw-divide-gray-300 tw-gap-y-2 tw-py-1\">\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black tw-whitespace-nowrap wilds-sorter-t-1\" data-filter-int=\"000\"><div class=\"tw-whitespace-nowrap\"><\/div><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-2\">\n                <div class=\"tw-h-full tw-flex tw-flex-wrap tw-items-center tw-justify-center tw-text-sm tw-text-black\"><div class=\"tw-leading-3\">168<div class=\"tw-text-xs tw-text-green-800\">(120)<\/div><\/div><span class=\"tw-text-xs tw-text-red-700 tw-whitespace-nowrap\"><img decoding=\"async\" class=\"tw-w-3.5 md:tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/status_icon\/aff.png\">10%<\/span><\/div>\n\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-3\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black\"><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-4\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-black tw-whitespace-nowrap\"><div class=\"md:tw-text-sm tw-text-xs\">\u9ebb\u75fa8<\/div><\/div>\n            <\/div>\n        <\/div>\n        <div class=\"tw-px-1\">\n            \n            <div class=\"tw-bg-gray-300 tw-p-1 tw-mt-1 tw-rounded-md tw-border-solid tw-border tw-border-gray-100\">\n    <div class=\"tw-rounded-sm tw-overflow-hidden\">\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 7.5%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 30%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 7.5%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 42.5%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n    <\/div>\n<\/div>\n            \n        <\/div>\n    <\/div>\n\n<\/div><div class=\"tw-py-1 tw-flex tw-items-center  wilds-toggle-items wilds-sorder-tr\" data-filter=\"\u30e9\u30d0\u30e9\u30fb\u30c0\u30fc\u30b2\u2161,\u7247\u624b\u5263\">\n    <div class=\"tw-w-2\/5 md:tw-w-1\/2 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-pl-2\">\n        <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/2.webp\" alt=\"Icon\">\n<\/div><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-790\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30c0\u30fc\u30b2\u2161<\/a>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><\/div><\/div>\n        \n    <\/div>\n    <div class=\"tw-w-3\/5 md:tw-w-1\/2 tw-h-full\">\n        <div class=\"tw-text-center tw-flex tw-items-center tw-items-stretch tw-divide-solid tw-divide-x tw-divide-gray-300 tw-gap-y-2 tw-py-1\">\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black tw-whitespace-nowrap wilds-sorter-t-1\" data-filter-int=\"000\"><div class=\"tw-whitespace-nowrap\"><\/div><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-2\">\n                <div class=\"tw-h-full tw-flex tw-flex-wrap tw-items-center tw-justify-center tw-text-sm tw-text-black\"><div class=\"tw-leading-3\">168<div class=\"tw-text-xs tw-text-green-800\">(120)<\/div><\/div><span class=\"tw-text-xs tw-text-red-700 tw-whitespace-nowrap\"><img decoding=\"async\" class=\"tw-w-3.5 md:tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/status_icon\/aff.png\">10%<\/span><\/div>\n\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-3\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-sm tw-text-black\"><\/div>\n            <\/div>\n            <div class=\"tw-w-1\/4 tw-p-1 tw-text-center wilds-sorter-t-4\">\n                <div class=\"tw-h-full tw-flex tw-items-center tw-justify-center tw-text-black tw-whitespace-nowrap\"><div class=\"md:tw-text-sm tw-text-xs\">\u9ebb\u75fa12<\/div><\/div>\n            <\/div>\n        <\/div>\n        <div class=\"tw-px-1\">\n            \n            <div class=\"tw-bg-gray-300 tw-p-1 tw-mt-1 tw-rounded-md tw-border-solid tw-border tw-border-gray-100\">\n    <div class=\"tw-rounded-sm tw-overflow-hidden\">\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 10%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 27.5%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n        <div class=\"tw-text-center tw-flex tw-items-stretch tw-h-2\">\n            <div class=\"tw-bg-red-500\" style=\"width: 17.5%;\"><\/div> <!-- \u8d64 -->\n            <div class=\"tw-bg-orange-800\" style=\"width: 10%;\"><\/div> <!-- \u6a59 -->\n            <div class=\"tw-bg-yellow-300\" style=\"width: 7.5%;\"><\/div> <!-- \u9ec4 -->\n            <div class=\"tw-bg-green-500\" style=\"width: 40%;\"><\/div> <!-- \u7dd1 -->\n            <div class=\"tw-bg-blue-500\" style=\"width: 0%;\"><\/div> <!-- \u9752 -->\n            <div class=\"tw-bg-white\" style=\"width: 0%;\"><\/div> <!-- \u767d -->\n            <div class=\"tw-bg-purple-500\" style=\"width: 0%;\"><\/div> <!-- \u7d2b -->\n        <\/div>\n    <\/div>\n<\/div>\n            \n        <\/div>\n    <\/div>\n\n<\/div>    <div class=\"wilds-toggle-button tw-mt-6 tw-px-4 tw-text-sm tw-py-2 tw-text-center tw-bg-green-600 tw-text-white tw-rounded-b tw-cursor-pointer\">\n    <div class=\" \">\u3082\u3063\u3068\u898b\u308b<\/div>\n<\/div>\n    <\/div>\n<\/div><h4>\u6b66\u5668\u751f\u7523\u3001\u5f37\u5316\u306b\u5fc5\u8981\u306a\u7d20\u6750<\/h4><div class=\"wilds-more-toggle-wrapper\">\n<div class=\"tw-p-1 wilds-toggle-list tw-rounded-sm tw-divide-solid tw-divide-y tw-divide-gray-200 tw-border-solid tw-border tw-border-gray-200 tw-select-none\">\n<div class=\"tw-py-2 tw-bg-gray-50 tw-border-solid tw-border-t-2 tw-border-l-2 tw-border-r-2 tw-border-gray-200 tw-rounded-t-sm md:tw-flex tw-items-center\">\n    <div class=\"md:tw-block tw-hidden tw-w-1\/3 tw-text-xs tw-font-extralight tw-text-left tw-pl-2\">\u540d\u524d<\/div>\n    <div class=\"md:tw-w-2\/3 tw-w-full\">\n        <div class=\"tw-flex tw-items-center tw-gap-1\">\n            <div class=\"tw-w-2\/6\">\n                <div class=\"tw-w-full tw-p-1 tw-text-xs tw-text-center tw-text-white tw-rounded-md tw-border-solid tw-border tw-border-gray-200 tw-bg-green-700 tw-p-1\">\u751f\u7523\u7d20\u6750<\/div>\n            <\/div>\n            <div class=\"tw-w-1\/6\">\n                <div class=\"tw-w-full tw-p-1 tw-text-xs tw-text-center tw-text-white tw-bg-gray-600 tw-rounded-md tw-whitespace-nowrap\">\u500b\u6570<\/div>\n            <\/div>\n            <div class=\"tw-w-2\/6\">\n                <div class=\"tw-w-full tw-p-1 tw-text-xs tw-text-center tw-text-white tw-rounded-md tw-border-solid tw-border tw-border-gray-200 tw-bg-red-700 tw-p-1\">\u5f37\u5316\u7d20\u6750<\/div>\n            <\/div>\n            <div class=\"tw-w-1\/6\">\n                <div class=\"tw-w-full tw-p-1 tw-text-xs tw-text-center tw-text-white tw-bg-gray-600 tw-rounded-md tw-whitespace-nowrap\">\u500b\u6570<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-items\">\n    <div class=\"md:tw-hidden tw-flex tw-bg-gray-100 tw-items-center tw-justify-between tw-text-xs tw-font-extralight tw-text-left tw-py-2\">\n        <div class=\"tw-pl-2 tw-flex tw-items-center  \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/4.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-328\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u9ebb\u75fa\u5c5e\u6027\u6d3e\u751f<\/div>\u30b8\u30a7\u30a4\u30eb\u30cf\u30f3\u30de\u30fc\u2161<\/a><\/div>\n        <div class=\"tw-px-2\">    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u6e1b\u6c17\u5a01\u529b1.3\u500d\">\u30b9\u30bf\u30df\u30ca\u596a\u53d6+2<\/span><\/div><\/div>\n            <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n    <\/div>\n    <div class=\"tw-pl-2 tw-flex tw-items-center \">\n        <div class=\"md:tw-block tw-hidden tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left\">\n            <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/4.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-328\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u9ebb\u75fa\u5c5e\u6027\u6d3e\u751f<\/div>\u30b8\u30a7\u30a4\u30eb\u30cf\u30f3\u30de\u30fc\u2161<\/a><\/div>\n                <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u6e1b\u6c17\u5a01\u529b1.3\u500d\">\u30b9\u30bf\u30df\u30ca\u596a\u53d6+2<\/span><\/div>\n                <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n        <\/div>\n        <div class=\"md:tw-w-2\/3 tw-w-full\">\n            <div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-296\">\u5f71\u8718\u86db\u306e\u722a<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-127\">\u523a\u82b1\u8718\u86db\u306e\u7dbf\u6bdb<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>3\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-items\">\n    <div class=\"md:tw-hidden tw-flex tw-bg-gray-100 tw-items-center tw-justify-between tw-text-xs tw-font-extralight tw-text-left tw-py-2\">\n        <div class=\"tw-pl-2 tw-flex tw-items-center  \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/0.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-186\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u9ebb\u75fa\u5c5e\u6027\u6d3e\u751f<\/div>\u30d1\u30eb\u30b8\u30fc\u30d6\u30ec\u30a4\u30c9\u2161<\/a><\/div>\n        <div class=\"tw-px-2\">    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u7814\u304e\u52d5\u4f5c\u30922\u56de\u7701\u7565\">\u7825\u77f3\u4f7f\u7528\u9ad8\u901f\u5316+2<\/span><\/div><\/div>\n            <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n    <\/div>\n    <div class=\"tw-pl-2 tw-flex tw-items-center \">\n        <div class=\"md:tw-block tw-hidden tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left\">\n            <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/0.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-186\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u9ebb\u75fa\u5c5e\u6027\u6d3e\u751f<\/div>\u30d1\u30eb\u30b8\u30fc\u30d6\u30ec\u30a4\u30c9\u2161<\/a><\/div>\n                <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u7814\u304e\u52d5\u4f5c\u30922\u56de\u7701\u7565\">\u7825\u77f3\u4f7f\u7528\u9ad8\u901f\u5316+2<\/span><\/div>\n                <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n        <\/div>\n        <div class=\"md:tw-w-2\/3 tw-w-full\">\n            <div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-296\">\u5f71\u8718\u86db\u306e\u722a<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-127\">\u523a\u82b1\u8718\u86db\u306e\u7dbf\u6bdb<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>3\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-items\">\n    <div class=\"md:tw-hidden tw-flex tw-bg-gray-100 tw-items-center tw-justify-between tw-text-xs tw-font-extralight tw-text-left tw-py-2\">\n        <div class=\"tw-pl-2 tw-flex tw-items-center  \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/9.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-67\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30d6\u30ad\u30ea\u30a8\u2161<\/a><\/div>\n        <div class=\"tw-px-2\">    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><\/div>\n            <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n    <\/div>\n    <div class=\"tw-pl-2 tw-flex tw-items-center \">\n        <div class=\"md:tw-block tw-hidden tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left\">\n            <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/9.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-67\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30d6\u30ad\u30ea\u30a8\u2161<\/a><\/div>\n                <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div>\n                <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n        <\/div>\n        <div class=\"md:tw-w-2\/3 tw-w-full\">\n            <div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-296\">\u5f71\u8718\u86db\u306e\u722a<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-127\">\u523a\u82b1\u8718\u86db\u306e\u7dbf\u6bdb<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>2\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-items\">\n    <div class=\"md:tw-hidden tw-flex tw-bg-gray-100 tw-items-center tw-justify-between tw-text-xs tw-font-extralight tw-text-left tw-py-2\">\n        <div class=\"tw-pl-2 tw-flex tw-items-center  \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/8.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-723\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30a2\u30c3\u30b7\u30a7\u2161<\/a><\/div>\n        <div class=\"tw-px-2\">    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><\/div>\n            <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n    <\/div>\n    <div class=\"tw-pl-2 tw-flex tw-items-center \">\n        <div class=\"md:tw-block tw-hidden tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left\">\n            <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/8.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-723\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30a2\u30c3\u30b7\u30a7\u2161<\/a><\/div>\n                <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div>\n                <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n        <\/div>\n        <div class=\"md:tw-w-2\/3 tw-w-full\">\n            <div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-296\">\u5f71\u8718\u86db\u306e\u722a<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-127\">\u523a\u82b1\u8718\u86db\u306e\u7dbf\u6bdb<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>2\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-items\">\n    <div class=\"md:tw-hidden tw-flex tw-bg-gray-100 tw-items-center tw-justify-between tw-text-xs tw-font-extralight tw-text-left tw-py-2\">\n        <div class=\"tw-pl-2 tw-flex tw-items-center  \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/1.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-653\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30b0\u30ec\u30d6\u2161<\/a><\/div>\n        <div class=\"tw-px-2\">    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><\/div>\n            <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n    <\/div>\n    <div class=\"tw-pl-2 tw-flex tw-items-center \">\n        <div class=\"md:tw-block tw-hidden tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left\">\n            <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/1.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-653\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30b0\u30ec\u30d6\u2161<\/a><\/div>\n                <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div>\n                <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n        <\/div>\n        <div class=\"md:tw-w-2\/3 tw-w-full\">\n            <div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-296\">\u5f71\u8718\u86db\u306e\u722a<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-127\">\u523a\u82b1\u8718\u86db\u306e\u7dbf\u6bdb<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>2\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-items\">\n    <div class=\"md:tw-hidden tw-flex tw-bg-gray-100 tw-items-center tw-justify-between tw-text-xs tw-font-extralight tw-text-left tw-py-2\">\n        <div class=\"tw-pl-2 tw-flex tw-items-center  \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/10.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-500\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30a2\u30d5\u30d7\u30cb\u2161<\/a><\/div>\n        <div class=\"tw-px-2\">    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><\/div>\n            <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n    <\/div>\n    <div class=\"tw-pl-2 tw-flex tw-items-center \">\n        <div class=\"md:tw-block tw-hidden tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left\">\n            <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/10.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-500\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30a2\u30d5\u30d7\u30cb\u2161<\/a><\/div>\n                <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div>\n                <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n        <\/div>\n        <div class=\"md:tw-w-2\/3 tw-w-full\">\n            <div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-296\">\u5f71\u8718\u86db\u306e\u722a<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-127\">\u523a\u82b1\u8718\u86db\u306e\u7dbf\u6bdb<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>2\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-items\">\n    <div class=\"md:tw-hidden tw-flex tw-bg-gray-100 tw-items-center tw-justify-between tw-text-xs tw-font-extralight tw-text-left tw-py-2\">\n        <div class=\"tw-pl-2 tw-flex tw-items-center  \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/7.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-264\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u9ebb\u75fa\u5c5e\u6027\u6d3e\u751f<\/div>\u30d1\u30eb\u30b8\u30fc\u30ac\u30f3\u30e9\u30f3\u30b9\u2161<\/a><\/div>\n        <div class=\"tw-px-2\">    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u30b9\u30ad\u30eb\u767a\u52d5\u4e2d\u3001\u653b\u6483\u529b1.1\u500d\">\u653b\u3081\u306e\u5b88\u52e2+2<\/span><\/div><\/div>\n            <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n    <\/div>\n    <div class=\"tw-pl-2 tw-flex tw-items-center \">\n        <div class=\"md:tw-block tw-hidden tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left\">\n            <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/7.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-264\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u9ebb\u75fa\u5c5e\u6027\u6d3e\u751f<\/div>\u30d1\u30eb\u30b8\u30fc\u30ac\u30f3\u30e9\u30f3\u30b9\u2161<\/a><\/div>\n                <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u30b9\u30ad\u30eb\u767a\u52d5\u4e2d\u3001\u653b\u6483\u529b1.1\u500d\">\u653b\u3081\u306e\u5b88\u52e2+2<\/span><\/div>\n                <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n        <\/div>\n        <div class=\"md:tw-w-2\/3 tw-w-full\">\n            <div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-296\">\u5f71\u8718\u86db\u306e\u722a<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-127\">\u523a\u82b1\u8718\u86db\u306e\u7dbf\u6bdb<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>3\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-items\">\n    <div class=\"md:tw-hidden tw-flex tw-bg-gray-100 tw-items-center tw-justify-between tw-text-xs tw-font-extralight tw-text-left tw-py-2\">\n        <div class=\"tw-pl-2 tw-flex tw-items-center  \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/6.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-586\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30ed\u30f3\u30b9\u2161<\/a><\/div>\n        <div class=\"tw-px-2\">    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><\/div>\n            <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n    <\/div>\n    <div class=\"tw-pl-2 tw-flex tw-items-center \">\n        <div class=\"md:tw-block tw-hidden tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left\">\n            <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/6.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-586\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30ed\u30f3\u30b9\u2161<\/a><\/div>\n                <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div>\n                <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n        <\/div>\n        <div class=\"md:tw-w-2\/3 tw-w-full\">\n            <div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-296\">\u5f71\u8718\u86db\u306e\u722a<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-127\">\u523a\u82b1\u8718\u86db\u306e\u7dbf\u6bdb<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>2\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-items\">\n    <div class=\"md:tw-hidden tw-flex tw-bg-gray-100 tw-items-center tw-justify-between tw-text-xs tw-font-extralight tw-text-left tw-py-2\">\n        <div class=\"tw-pl-2 tw-flex tw-items-center  \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/3.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-142\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30d5\u30fc\u30b7\u30a7\u2161<\/a><\/div>\n        <div class=\"tw-px-2\">    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><\/div>\n            <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n    <\/div>\n    <div class=\"tw-pl-2 tw-flex tw-items-center \">\n        <div class=\"md:tw-block tw-hidden tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left\">\n            <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/3.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-142\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30d5\u30fc\u30b7\u30a7\u2161<\/a><\/div>\n                <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div>\n                <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n        <\/div>\n        <div class=\"md:tw-w-2\/3 tw-w-full\">\n            <div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-296\">\u5f71\u8718\u86db\u306e\u722a<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-127\">\u523a\u82b1\u8718\u86db\u306e\u7dbf\u6bdb<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>2\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-items\">\n    <div class=\"md:tw-hidden tw-flex tw-bg-gray-100 tw-items-center tw-justify-between tw-text-xs tw-font-extralight tw-text-left tw-py-2\">\n        <div class=\"tw-pl-2 tw-flex tw-items-center  \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/2.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-790\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30c0\u30fc\u30b2\u2161<\/a><\/div>\n        <div class=\"tw-px-2\">    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div><\/div>\n            <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n    <\/div>\n    <div class=\"tw-pl-2 tw-flex tw-items-center \">\n        <div class=\"md:tw-block tw-hidden tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left\">\n            <div class=\"tw-flex tw-items-center \"><div class=\"wilds-weapon-icon \">\n    <img decoding=\"async\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/2.webp\" alt=\"Icon\">\n<\/div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/weapon\/weapon-790\"><div class=\"wilds-text-xxs tw-text-gray-600 tw-font-normal\">\u523a\u82b1\u8718\u86db\u6d3e\u751f<\/div>\u30e9\u30d0\u30e9\u30fb\u30c0\u30fc\u30b2\u2161<\/a><\/div>\n                <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u4f1a\u5fc3\u7387+50\uff05\">\u629c\u5200\u8853\u3010\u6280\u3011+1<\/span><\/div>    <div class=\"tw-px-1 tw-pt-1 tw-text-xs\" >\u25cf<span class=\"tw-border-dotted tw-border-b tw-border-blue-500\"  data-tippy-content=\"\u653b\u6483\u3067\u4f1a\u5fc3\u304c\u767a\u751f\u3057\u305f\u969b\u306b\u3001\u4e0e\u3048\u308b\u72b6\u614b\u7570\u5e38\u5024\u304c\u308f\u305a\u304b\u306b\u4e0a\u6607\">\u4f1a\u5fc3\u6483\u3010\u7279\u6b8a\u3011+1<\/span><\/div>\n                <div class=\"tw-px-2 tw-text-gray-500\">    <div class=\"tw-text-xs tw-text-center tw-pl-1\">\u5f37\u5316\u8cbb\u7528:<span class=\"tw-px-1\">1500<\/span>z<\/div><\/div>\n        <\/div>\n        <div class=\"md:tw-w-2\/3 tw-w-full\">\n            <div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-296\">\u5f71\u8718\u86db\u306e\u722a<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-127\">\u523a\u82b1\u8718\u86db\u306e\u7dbf\u6bdb<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>2\n    <\/div><\/div><\/div><div class=\"tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\"><div class=\"tw-w-2\/6\"><\/div><div class=\"tw-w-1\/6\"><\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right tw-border-l tw-border-solid tw-border-gray-200\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-button tw-mt-6 tw-px-4 tw-text-sm tw-py-2 tw-text-center tw-bg-green-600 tw-text-white tw-rounded-b tw-cursor-pointer\">\n    <div class=\" \">\u3082\u3063\u3068\u898b\u308b<\/div>\n<\/div>\n    <\/div>\n<\/div><h3>\u9632\u5177\u751f\u7523\u3001\u5f37\u5316\u306b\u4f7f\u7528<\/h3><h4>\u9632\u5177\u306e\u6027\u80fd<\/h4><div class=\"wilds-more-toggle-wrapper tw-select-none\">\n    <div class=\"tw-flex tw-items-center tw-space-x-2\">\n    <input type=\"text\"\n            placeholder=\"\u30ad\u30fc\u30ef\u30fc\u30c9\u691c\u7d22\"\n            class=\"wilds-search-input tw-border tw-rounded tw-px-3 tw-py-2 tw-w-full\">\n    <\/div>\n<div class=\"tw-flex tw-justify-center tw-flex-wrap wilds-filter\">\n    <div class=\"md:tw-max-w-sm tw-max-w-full tw-grid tw-grid-cols-5 tw-gap-2 tw-p-2 wilds-filter-group-lim-5\">\n            <div class=\"wilds-filter-item-0 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u982d\">\n        <div class=\"tw-w-1\/2 tw-h-full\"><img decoding=\"async\" class=\"tw-w-full\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/armor_icon\/0.png\" \/><\/div>\n    <\/div>    <div class=\"wilds-filter-item-1 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u80f4\">\n        <div class=\"tw-w-1\/2 tw-h-full\"><img decoding=\"async\" class=\"tw-w-full\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/armor_icon\/1.png\" \/><\/div>\n    <\/div>    <div class=\"wilds-filter-item-2 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u8155\">\n        <div class=\"tw-w-1\/2 tw-h-full\"><img decoding=\"async\" class=\"tw-w-full\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/armor_icon\/2.png\" \/><\/div>\n    <\/div>    <div class=\"wilds-filter-item-3 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u8170\">\n        <div class=\"tw-w-1\/2 tw-h-full\"><img decoding=\"async\" class=\"tw-w-full\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/armor_icon\/3.png\" \/><\/div>\n    <\/div>    <div class=\"wilds-filter-item-4 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"or\" data-filter-select=\"\u811a\">\n        <div class=\"tw-w-1\/2 tw-h-full\"><img decoding=\"async\" class=\"tw-w-full\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/armor_icon\/4.png\" \/><\/div>\n    <\/div>\n    <\/div>\n        <div class=\"tw-grid tw-grid-cols-3 tw-gap-2 md:tw-max-w-sm tw-max-w-full tw-w-full tw-px-2 tw-pb-2 wilds-filter-group-lim-1\">\n        <div class=\"wilds-filter-item-5 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"and\">\u4e0b\u4f4d<\/div>\n        <div class=\"wilds-filter-item-6 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"and\">\u4e0a\u4f4d<\/div>\n        <div class=\"wilds-filter-item-7 tw-cursor-pointer tw-text-center tw-text-sm tw-border tw-border-solid tw-border-gray-200 tw-rounded tw-p-1 tw-flex tw-items-center tw-justify-center\" data-filter-order=\"and\">MR<\/div>\n    <\/div>\n<\/div>\n<div class=\"tw-p-1 tw-rounded-sm tw-divide-solid tw-divide-y tw-divide-gray-200 tw-border-solid tw-border tw-border-gray-200 wilds-toggle-list wilds-sorter\">\n\n<div class=\"tw-py-2 tw-bg-gray-50 tw-border-solid tw-border-t-2 tw-border-l-2 tw-border-r-2 tw-border-gray-200 tw-rounded-t-sm tw-flex tw-items-center\">\n    <div class=\"tw-w-1\/3 md:tw-block tw-hidden tw-text-xs tw-text-center tw-font-extralight tw-text-left tw-p-1 wilds-sorter-h-7 tw-text-white tw-bg-gray-600 tw-rounded-md tw-whitespace-nowrap tw-cursor-pointer wilds-sorter-data-int\">\u540d\u524d(\u30b9\u30ed\u30c3\u30c8)<\/div>\n    <div class=\"tw-w-full md:tw-w-2\/3\">\n        <div class=\"tw-flex tw-items-center tw-items-stretch\">\n            <div class=\"tw-w-1\/3 tw-py-1 tw-ml-1 tw-text-xs tw-text-center tw-text-white tw-bg-gray-600 tw-rounded-md tw-whitespace-nowrap tw-cursor-pointer wilds-sorter-h-1 wilds-sorter-data-int\"><img decoding=\"async\" class=\"icon-20\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/type\/6.png\" alt=\"\u9632\u5fa1\u529b\"\\>\u9632\u5fa1\u529b<\/div>\n            <div class=\"tw-w-1\/6 tw-py-1 tw-ml-1 tw-text-xs tw-text-center tw-text-white tw-box-border tw-border tw-border-solid tw-border-gray-400 tw-bg-gray-200 tw-rounded-md tw-whitespace-nowrap tw-cursor-pointer wilds-sorter-h-2 wilds-sorter-int\"><img decoding=\"async\" class=\"icon-20\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/type\/0.png\" alt=\"\u708e\"\\><\/div>\n            <div class=\"tw-w-1\/6 tw-py-1 tw-ml-1 tw-text-xs tw-text-center tw-text-white tw-box-border tw-border tw-border-solid tw-border-gray-400 tw-bg-gray-200 tw-rounded-md tw-whitespace-nowrap tw-cursor-pointer wilds-sorter-h-3 wilds-sorter-int\"><img decoding=\"async\" class=\"icon-20\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/type\/1.png\" alt=\"\u6c34\"\\><\/div>\n            <div class=\"tw-w-1\/6 tw-py-1 tw-ml-1 tw-text-xs tw-text-center tw-text-white tw-box-border tw-border tw-border-solid tw-border-gray-400 tw-bg-gray-200 tw-rounded-md tw-whitespace-nowrap tw-cursor-pointer wilds-sorter-h-4 wilds-sorter-int\"><img decoding=\"async\" class=\"icon-20\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/type\/2.png\" alt=\"\u96f7\"\\><\/div>\n            <div class=\"tw-w-1\/6 tw-py-1 tw-ml-1 tw-text-xs tw-text-center tw-text-white tw-box-border tw-border tw-border-solid tw-border-gray-400 tw-bg-gray-200 tw-rounded-md tw-whitespace-nowrap tw-cursor-pointer wilds-sorter-h-5 wilds-sorter-int\"><img decoding=\"async\" class=\"icon-20\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/type\/3.png\" alt=\"\u6c37\"\\><\/div>\n            <div class=\"tw-w-1\/6 tw-py-1 tw-ml-1 tw-text-xs tw-text-center tw-text-white tw-box-border tw-border tw-border-solid tw-border-gray-400 tw-bg-gray-200 tw-rounded-md tw-whitespace-nowrap tw-cursor-pointer wilds-sorter-h-6 wilds-sorter-int\"><img decoding=\"async\" class=\"icon-20\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/type\/4.png\" alt=\"\u9f8d\"\\><\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-items wilds-sorder-tr\" data-filter=\"\u30e9\u30d0\u30e9\u30e1\u30a4\u30eb,\u80f4,\u4e0b\u4f4d\">\n    <div class=\"md:tw-hidden tw-flex tw-justify-between tw-w-full tw-py-2 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-bg-gray-100\">\n        <div class=\"tw-flex tw-items-center tw-pl-1\"><img decoding=\"async\" class=\"md:tw-w-6 tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/armor_icon\/1.png\" \/><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/armor\/armor-46\">\u30e9\u30d0\u30e9\u30e1\u30a4\u30eb<\/a><\/div><\/div>\n        <div>\n            \n            <div>    <div class=\"tw-text-xs tw-px-2 tw-inline-block\">\n        <span class=\"tw-border-dotted tw-border-b tw-border-blue-500 \" data-tippy-content=\"\u9ebb\u75fa\u72b6\u614b\u306e\u6642\u9593\u309230\uff05\u6e1b\u3089\u3059\">\u9ebb\u75fa\u8010\u6027+1<\/span>\n    <\/div><\/div>\n        <\/div>\n\n    <\/div>\n    <div class=\"tw-flex tw-items-center tw-items-stretch\">\n        <div class=\"md:tw-flex tw-items-center tw-hidden tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-py-2\">\n            <div>\n                <div class=\"tw-flex tw-items-center tw-pl-1 wilds-sorter-t-7\" data-filter-int=\"000\"><img decoding=\"async\" class=\"md:tw-w-6 tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/armor_icon\/1.png\" \/><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/armor\/armor-46\">\u30e9\u30d0\u30e9\u30e1\u30a4\u30eb<\/a><\/div><\/div>\n                <div class=\"tw-px-1\"><\/div>\n                    <div class=\"tw-text-xs tw-px-2 tw-inline-block\">\n        <span class=\"tw-border-dotted tw-border-b tw-border-blue-500 \" data-tippy-content=\"\u9ebb\u75fa\u72b6\u614b\u306e\u6642\u9593\u309230\uff05\u6e1b\u3089\u3059\">\u9ebb\u75fa\u8010\u6027+1<\/span>\n    <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"tw-w-full md:tw-w-2\/3 \">\n            <div class=\"tw-text-center tw-flex tw-items-center tw-items-stretch tw-divide-solid tw-divide-x tw-divide-gray-300 tw-h-full\">\n                <div class=\"tw-w-1\/3 tw-py-2 tw-flex tw-items-center tw-justify-center\">\n                    <div class=\"tw-text-sm tw-text-black tw-whitespace-nowrap wilds-sorter-t-1\" data-filter-int=\"36\">    <div><div class=\"wilds-text-xxs\">8<\/div><div class=\"wilds-text-sm\">28<\/div><\/div><\/div>\n                <\/div>\n                <div class=\"tw-w-1\/6 tw-py-2 tw-flex tw-items-center tw-justify-center tw-text-center wilds-sorter-t-2\">\n                    <div class=\"tw-text-sm tw-text-black\" data-filter-int=\"-3\">-3<\/div>\n                <\/div>\n                <div class=\"tw-w-1\/6 tw-py-2 tw-flex tw-items-center tw-justify-center tw-text-center wilds-sorter-t-3\">\n                    <div class=\"tw-text-sm tw-text-black\" data-filter-int=\"3\">+3<\/div>\n                <\/div>\n                <div class=\"tw-w-1\/6 tw-py-2 tw-flex tw-items-center tw-justify-center tw-text-center wilds-sorter-t-4\">\n                    <div class=\"tw-text-sm tw-text-black\" data-filter-int=\"0\">0<\/div>\n                <\/div>\n                <div class=\"tw-w-1\/6 tw-py-2 tw-flex tw-items-center tw-justify-center tw-text-center wilds-sorter-t-5\">\n                    <div class=\"tw-text-sm tw-text-black\" data-filter-int=\"0\">0<\/div>\n                <\/div>\n                <div class=\"tw-w-1\/6 tw-py-2 tw-flex tw-items-center tw-justify-center tw-text-center wilds-sorter-t-6\">\n                    <div class=\"tw-text-sm tw-text-black\" data-filter-int=\"3\">+3<\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-items wilds-sorder-tr\" data-filter=\"\u30e9\u30d0\u30e9\u30b3\u30a4\u30eb,\u8170,\u4e0b\u4f4d\">\n    <div class=\"md:tw-hidden tw-flex tw-justify-between tw-w-full tw-py-2 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-bg-gray-100\">\n        <div class=\"tw-flex tw-items-center tw-pl-1\"><img decoding=\"async\" class=\"md:tw-w-6 tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/armor_icon\/3.png\" \/><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/armor\/armor-48\">\u30e9\u30d0\u30e9\u30b3\u30a4\u30eb<\/a><\/div><\/div>\n        <div>\n            \n            <div>    <div class=\"tw-text-xs tw-px-2 tw-inline-block\">\n        <span class=\"tw-border-dotted tw-border-b tw-border-blue-500 \" data-tippy-content=\"\u56de\u5fa9\u91cf\u304c\u308f\u305a\u304b\u306b\u5897\u52a0\u3059\u308b\">\u4f53\u529b\u56de\u5fa9\u91cf\uff35\uff30+1<\/span>\n    <\/div><\/div>\n        <\/div>\n\n    <\/div>\n    <div class=\"tw-flex tw-items-center tw-items-stretch\">\n        <div class=\"md:tw-flex tw-items-center tw-hidden tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left tw-py-2\">\n            <div>\n                <div class=\"tw-flex tw-items-center tw-pl-1 wilds-sorter-t-7\" data-filter-int=\"000\"><img decoding=\"async\" class=\"md:tw-w-6 tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/armor_icon\/3.png\" \/><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/armor\/armor-48\">\u30e9\u30d0\u30e9\u30b3\u30a4\u30eb<\/a><\/div><\/div>\n                <div class=\"tw-px-1\"><\/div>\n                    <div class=\"tw-text-xs tw-px-2 tw-inline-block\">\n        <span class=\"tw-border-dotted tw-border-b tw-border-blue-500 \" data-tippy-content=\"\u56de\u5fa9\u91cf\u304c\u308f\u305a\u304b\u306b\u5897\u52a0\u3059\u308b\">\u4f53\u529b\u56de\u5fa9\u91cf\uff35\uff30+1<\/span>\n    <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"tw-w-full md:tw-w-2\/3 \">\n            <div class=\"tw-text-center tw-flex tw-items-center tw-items-stretch tw-divide-solid tw-divide-x tw-divide-gray-300 tw-h-full\">\n                <div class=\"tw-w-1\/3 tw-py-2 tw-flex tw-items-center tw-justify-center\">\n                    <div class=\"tw-text-sm tw-text-black tw-whitespace-nowrap wilds-sorter-t-1\" data-filter-int=\"36\">    <div><div class=\"wilds-text-xxs\">8<\/div><div class=\"wilds-text-sm\">28<\/div><\/div><\/div>\n                <\/div>\n                <div class=\"tw-w-1\/6 tw-py-2 tw-flex tw-items-center tw-justify-center tw-text-center wilds-sorter-t-2\">\n                    <div class=\"tw-text-sm tw-text-black\" data-filter-int=\"-3\">-3<\/div>\n                <\/div>\n                <div class=\"tw-w-1\/6 tw-py-2 tw-flex tw-items-center tw-justify-center tw-text-center wilds-sorter-t-3\">\n                    <div class=\"tw-text-sm tw-text-black\" data-filter-int=\"3\">+3<\/div>\n                <\/div>\n                <div class=\"tw-w-1\/6 tw-py-2 tw-flex tw-items-center tw-justify-center tw-text-center wilds-sorter-t-4\">\n                    <div class=\"tw-text-sm tw-text-black\" data-filter-int=\"0\">0<\/div>\n                <\/div>\n                <div class=\"tw-w-1\/6 tw-py-2 tw-flex tw-items-center tw-justify-center tw-text-center wilds-sorter-t-5\">\n                    <div class=\"tw-text-sm tw-text-black\" data-filter-int=\"0\">0<\/div>\n                <\/div>\n                <div class=\"tw-w-1\/6 tw-py-2 tw-flex tw-items-center tw-justify-center tw-text-center wilds-sorter-t-6\">\n                    <div class=\"tw-text-sm tw-text-black\" data-filter-int=\"3\">+3<\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-button tw-mt-6 tw-px-4 tw-text-sm tw-py-2 tw-text-center tw-bg-green-600 tw-text-white tw-rounded-b tw-cursor-pointer\">\n    <div class=\" \">\u3082\u3063\u3068\u898b\u308b<\/div>\n<\/div>\n    <\/div>\n<\/div><h4>\u9632\u5177\u751f\u7523\u306b\u5fc5\u8981\u306a\u7d20\u6750<\/h4><div class=\"wilds-more-toggle-wrapper\">\n<div class=\"tw-p-1 wilds-toggle-list tw-rounded-sm tw-divide-solid tw-divide-y tw-divide-gray-200 tw-border-solid tw-border tw-border-gray-200 tw-select-none\">\n<div class=\"tw-p-2 tw-bg-gray-50 tw-border-solid tw-border-t-2 tw-border-l-2 tw-border-r-2 tw-border-gray-200 tw-rounded-t-sm tw-flex tw-items-center md:tw-hidden\">\n    <div class=\"tw-w-1\/3 tw-text-xs tw-font-extralight tw-text-left\">\u540d\u524d<\/div>\n    <div class=\"tw-w-2\/3\">\n        <div class=\"tw-flex tw-items-center tw-gap-2\">\n            <div class=\"tw-w-4\/5 \">\n                <div class=\"tw-w-full tw-p-1 tw-text-xs tw-text-center tw-text-white tw-bg-gray-600 tw-rounded-md\">\u751f\u7523\u7d20\u6750<\/div>\n            <\/div>\n            <div class=\"tw-w-1\/5\">\n                <div class=\"tw-w-full tw-p-1 tw-text-xs tw-text-center tw-text-white tw-bg-gray-600 tw-rounded-md tw-whitespace-nowrap\">\u500b\u6570<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"tw-hidden tw-py-2 tw-bg-gray-50 tw-border-solid tw-border-t-2 tw-border-l-2 tw-border-r-2 tw-border-gray-200 tw-rounded-t-sm md:tw-flex tw-items-center\">\n    <div class=\"tw-w-1\/3 tw-text-xs tw-font-extralight tw-text-left tw-pl-2\">\u540d\u524d<\/div>\n    <div class=\"tw-w-2\/3\">\n        <div class=\"tw-flex tw-items-center tw-gap-1\">\n            <div class=\"tw-w-2\/6\">\n                <div class=\"tw-w-full tw-p-1 tw-text-xs tw-text-center tw-text-white tw-rounded-md tw-border-solid tw-border tw-border-gray-200 tw-bg-green-700 tw-p-1\">\u7d20\u6750<\/div>\n            <\/div>\n            <div class=\"tw-w-1\/6\">\n                <div class=\"tw-w-full tw-p-1 tw-text-xs tw-text-center tw-text-white tw-bg-gray-600 tw-rounded-md tw-whitespace-nowrap\">\u500b\u6570<\/div>\n            <\/div>\n            <div class=\"tw-w-2\/6\">\n                <div class=\"tw-w-full tw-p-1 tw-text-xs tw-text-center tw-text-white tw-rounded-md tw-border-solid tw-border tw-border-gray-200 tw-bg-green-700 tw-p-1\">\u7d20\u6750<\/div>\n            <\/div>\n            <div class=\"tw-w-1\/6\">\n                <div class=\"tw-w-full tw-p-1 tw-text-xs tw-text-center tw-text-white tw-bg-gray-600 tw-rounded-md tw-whitespace-nowrap\">\u500b\u6570<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"tw-flex tw-items-center wilds-toggle-items\">\n    <div class=\"tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left\">\n        <div class=\"tw-flex tw-items-center tw-pl-1 tw-pt-1\"><img decoding=\"async\" class=\"md:tw-w-6 tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/armor_icon\/1.png\" \/><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/armor\/armor-46\">\u30e9\u30d0\u30e9\u30e1\u30a4\u30eb<\/a><\/div><\/div>\n        <div class=\"tw-text-xs tw-px-2 tw-py-1\">\n    <span class=\"tw-border-dotted tw-border-b tw-border-blue-500 \" data-tippy-content=\"\u9ebb\u75fa\u72b6\u614b\u306e\u6642\u9593\u309230\uff05\u6e1b\u3089\u3059\">\u9ebb\u75fa\u8010\u6027+1<\/span>\n<\/div>\n            <div class=\"wilds-text-xxs tw-text-center tw-text-gray-500 tw-pl-1\">\u751f\u7523\u8cbb\u7528:<span class=\"tw-px-1 tw-text-xs\">200<\/span>z<\/div>\n    <\/div>\n    <div class=\"tw-w-2\/3\">\n        <div class=\"md:tw-hidden tw-m-1\">\n    <div class=\"md:tw-hidden tw-grid tw-grid-cols-1\">\n<div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\">\n    <div class=\"tw-w-4\/5 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-1 tw-pr-1 tw-text-right\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-127\">\u523a\u82b1\u8718\u86db\u306e\u7dbf\u6bdb<\/a><\/div>\n    <div class=\"tw-w-1\/5 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-1\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>2\n    <\/div>\n<\/div>\n<\/div><div class=\"md:tw-hidden tw-grid tw-grid-cols-1\">\n<div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\">\n    <div class=\"tw-w-4\/5 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-1 tw-pr-1 tw-text-right\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-123\">\u523a\u82b1\u8718\u86db\u306e\u7532\u6bbb<\/a><\/div>\n    <div class=\"tw-w-1\/5 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-1\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>2\n    <\/div>\n<\/div>\n<\/div><div class=\"md:tw-hidden tw-grid tw-grid-cols-1\">\n<div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\">\n    <div class=\"tw-w-4\/5 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-1 tw-pr-1 tw-text-right\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/5 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-1\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"tw-hidden md:tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\">    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-127\">\u523a\u82b1\u8718\u86db\u306e\u7dbf\u6bdb<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>2\n    <\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-123\">\u523a\u82b1\u8718\u86db\u306e\u7532\u6bbb<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>2\n    <\/div><\/div><\/div><div class=\"tw-hidden md:tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\">    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"tw-flex tw-items-center wilds-toggle-items\">\n    <div class=\"tw-w-1\/3 md:tw-text-sm tw-text-xs tw-font-extralight tw-text-left\">\n        <div class=\"tw-flex tw-items-center tw-pl-1 tw-pt-1\"><img decoding=\"async\" class=\"md:tw-w-6 tw-w-5\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/armor_icon\/3.png\" \/><div><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/armor\/armor-48\">\u30e9\u30d0\u30e9\u30b3\u30a4\u30eb<\/a><\/div><\/div>\n        <div class=\"tw-text-xs tw-px-2 tw-py-1\">\n    <span class=\"tw-border-dotted tw-border-b tw-border-blue-500 \" data-tippy-content=\"\u56de\u5fa9\u91cf\u304c\u308f\u305a\u304b\u306b\u5897\u52a0\u3059\u308b\">\u4f53\u529b\u56de\u5fa9\u91cf\uff35\uff30+1<\/span>\n<\/div>\n            <div class=\"wilds-text-xxs tw-text-center tw-text-gray-500 tw-pl-1\">\u751f\u7523\u8cbb\u7528:<span class=\"tw-px-1 tw-text-xs\">200<\/span>z<\/div>\n    <\/div>\n    <div class=\"tw-w-2\/3\">\n        <div class=\"md:tw-hidden tw-m-1\">\n    <div class=\"md:tw-hidden tw-grid tw-grid-cols-1\">\n<div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\">\n    <div class=\"tw-w-4\/5 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-1 tw-pr-1 tw-text-right\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-365\">\u523a\u82b1\u8718\u86db\u306e\u7c98\u6db2<\/a><\/div>\n    <div class=\"tw-w-1\/5 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-1\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div>\n<\/div>\n<\/div><div class=\"md:tw-hidden tw-grid tw-grid-cols-1\">\n<div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\">\n    <div class=\"tw-w-4\/5 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-1 tw-pr-1 tw-text-right\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-124\">\u523a\u82b1\u8718\u86db\u306e\u722a<\/a><\/div>\n    <div class=\"tw-w-1\/5 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-1\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div>\n<\/div>\n<\/div><div class=\"md:tw-hidden tw-grid tw-grid-cols-1\">\n<div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\">\n    <div class=\"tw-w-4\/5 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-1 tw-pr-1 tw-text-right\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/5 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-1\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"tw-hidden md:tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\">    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-365\">\u523a\u82b1\u8718\u86db\u306e\u7c98\u6db2<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div>    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-124\">\u523a\u82b1\u8718\u86db\u306e\u722a<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div><div class=\"tw-hidden md:tw-grid tw-grid-cols-1\"><div class=\"tw-text-center tw-flex tw-items-stretch tw-items-center\">    <div class=\"tw-w-2\/6 tw-text-xs tw-h-full tw-flex tw-items-center tw-justify-end tw-py-2 tw-text-right\"><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/item\/item-material-125\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8<\/a><\/div>\n    <div class=\"tw-w-1\/6 tw-text-xs tw-text-center tw-text-black tw-whitespace-nowrap tw-py-2\">\n        <span class=\"tw-text-gray-500 tw-p-1\">x<\/span>1\n    <\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"wilds-toggle-button tw-mt-6 tw-px-4 tw-text-sm tw-py-2 tw-text-center tw-bg-green-600 tw-text-white tw-rounded-b tw-cursor-pointer\">\n    <div class=\" \">\u3082\u3063\u3068\u898b\u308b<\/div>\n<\/div>\n    <\/div>\n<\/div><div class=\"\" style=\"\"><h2>\u88c5\u5099\u95a2\u9023\u306e\u30c7\u30fc\u30bf<\/h2>\r\n        <div class=\"tw-grid md:tw-grid-cols-7 tw-grid-cols-6 tw-gap-1 tw-py-1\">\r\n            <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/bundle_wilds_armor\" class=\"tw-w-full tw-text-center tw-border tw-bg-gray-50 tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/header_icon\/armor.png\" alt=\"Icon\">\r\n                <div class=\"wilds-text-xxs tw-p-0\">\u9632\u5177\u4e00\u89a7<\/div>\r\n            <\/a>\r\n            <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/bundle_wilds_deco\" class=\"tw-w-full tw-text-center tw-border tw-bg-gray-50 tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/header_icon\/deco.png\" alt=\"Icon\">\r\n                <div class=\"wilds-text-xxs tw-p-0\">\u88c5\u98fe\u54c1\u4e00\u89a7<\/div>\r\n            <\/a>\r\n        <\/div>\r\n        <h2>\u6b66\u5668\u95a2\u9023\u306e\u30c7\u30fc\u30bf<\/h2>\r\n        <div class=\"tw-text-center tw-text-white tw-text-xs tw-bg-gray-600 tw-rounded-md tw-py-1\" >\u6b66\u5668\u6d3e\u751f\u4e00\u89a7<\/div>\r\n            <div class=\"tw-grid md:tw-grid-cols-7 tw-grid-cols-6 tw-gap-1 tw-py-1\">\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_0\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1 tw-rounded-sm\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/0.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u5927\u5263<\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_1\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/1.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u592a\u5200<\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_2\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/2.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u7247\u624b\u5263<\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_3\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/3.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u53cc\u5263<\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_4\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/4.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u30cf\u30f3\u30de\u30fc<\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_5\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/5.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u72e9\u731f\u7b1b<\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_6\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/6.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u30e9\u30f3\u30b9<\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_7\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/7.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u30ac\u30f3\u30e9\u30f3\u30b9<\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_8\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/8.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u30b9\u30e9\u30c3\u30b7\u30e5<span class=\"tw-inline-block\">\u30a2\u30c3\u30af\u30b9<\/span><\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_9\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/9.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u30c1\u30e3\u30fc\u30b8<span class=\"tw-inline-block\">\u30a2\u30c3\u30af\u30b9<\/span><\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_10\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/10.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u64cd\u866b\u68cd<\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_11\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/11.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u30e9\u30a4\u30c8<span class=\"tw-inline-block\">\u30dc\u30a6\u30ac\u30f3<\/span><\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_12\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/12.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u30d8\u30f4\u30a3<span class=\"tw-inline-block\">\u30dc\u30a6\u30ac\u30f3<\/span><\/div>\r\n                <\/a>\r\n                <a href=\"https:\/\/gamepedia.jp\/mh-wilds\/wp_tree_arc_13\" class=\"tw-w-full tw-text-center tw-bg-gray-50 tw-rounded-sm tw-border tw-border-solid tw-border-gray-300 tw-p-1\">\r\n                    <img decoding=\"async\" class=\"tw-w-3\/5 tw-p-0\" src=\"https:\/\/images.gamepedia.jp\/mh-wilds\/weapon_icon\/large\/13.png\" alt=\"Icon\">\r\n                    <div class=\"wilds-text-xxs tw-p-0\">\u5f13<\/div>\r\n                <\/a>\r\n            <\/div><\/div>\n\n<h2  class=\"\">\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8\u306e\u52d5\u753b<\/h2>\n\n<div class=\"youtube-area\">\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"ddx-svDzC58\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=ddx-svDzC58\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/ddx-svDzC58\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba\u3000\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8\u306e\u5165\u624b\u5834\u6240\u306f\uff1f\u3000\u6b66\u5668\u30fb\u9632\u5177\u7d20\u6750\u96c6\u3081\u5165\u624b\u65b9\u6cd5\u3000\uff03\uff12\uff12\uff18\u3000\u3010\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30ef\u30a4\u30eb\u30ba\u3011<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"DMZA-XmQoKI\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=DMZA-XmQoKI\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/DMZA-XmQoKI\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u3010\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba\u3011\u30e9\u30d0\u30e9\u30fb\u30d0\u30ea\u30ca\u6226\u3001\u8718\u86db\u6050\u6016\u75c7\u5bfe\u7b56\u30e2\u30fc\u30c9\u306a\u3089\u30ad\u30e2\u304f\u306a\u3044\u8aac<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"8yzIVMe8Y2w\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=8yzIVMe8Y2w\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/8yzIVMe8Y2w\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u8718\u86db\u5bfe\u7b56\u30e2\u30fc\u30c9\u3092\u30aa\u30f3\u306b\u3059\u308b\u3068\u30b9\u30e9\u30a4\u30e0\u304c\u30a8\u30ed\u3059\u304e\u308b\u4ef6\uff57\u3010\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30ef\u30a4\u30eb\u30ba\u3011<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"DbMte0MRouA\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=DbMte0MRouA\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/DbMte0MRouA\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u3010\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba\u3011\u8718\u86db\u6050\u6016\u75c7\u5bfe\u7b56\u30e2\u30fc\u30c9 \u6bd4\u8f03\u3010MHW\u3011<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n<\/div><!-- youtube-area -->\n<a class=\"nav-more-open-button hide-me\" data-toggle=\"collapse\" href=\"#collapse-video-list-1956187646\">\u3082\u3063\u3068\u898b\u308b<\/a>\n<div id=\"collapse-video-list-1956187646\" class=\"youtube-area collapse\">\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"9gLxg9LkWJc\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=9gLxg9LkWJc\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/9gLxg9LkWJc\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u3010\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba\u3011\u306f\u3058\u3081\u3066\u306e\u30cd\u30eb\u30b9\u30ad\u30e5\u30e9\u6226\u3067\u8718\u86db\u6050\u6016\u75c7\u5bfe\u7b56ON\u306b\u3057\u305f\u307e\u307e\u6c17\u3065\u304b\u305a\u6226\u3063\u305f\u6642\u306e\u53cd\u5fdc<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"SwvdUeVDJAM\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=SwvdUeVDJAM\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/SwvdUeVDJAM\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u3010\u8718\u86db\u6ce8\u610f\u3011\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba\u306e\u8718\u86db\u306b\u53eb\u3073\u6563\u3089\u304b\u3059Vtuber\u3010\u5929\u785d\u8def\u308d\u307e\u3093\/StellArt.\u3011#\u65b0\u4ebavtuber #vtuber #\u5207\u308a\u629c\u304d #\u30e2\u30f3\u30cf\u30f3 #\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba #\u30d0\u30ba\u308c<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"hGvnX5YHmQg\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=hGvnX5YHmQg\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/hGvnX5YHmQg\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u8718\u86db\u5acc\u3044\u306b\u306f\u8f9b\u3044\u4e16\u754c\u3010\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30ef\u30a4\u30eb\u30ba\u3011 #shorts<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"TQgeIrZpPT4\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=TQgeIrZpPT4\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/TQgeIrZpPT4\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u300e\u523a\u82b1\u8718\u86db\u30e9\u30d0\u30e9\u30fb\u30d0\u30ea\u30ca\u300f\u3055\u3093\u3001\u8987\u6a29\u30ac\u30f3\u30e9\u30f3\u30b9\u306e\u524d\u306b\u6563\u308b\u3002\u3010\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba\u3011<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"NYf-VNSNz4k\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=NYf-VNSNz4k\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/NYf-VNSNz4k\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u8718\u86db\u306e\u898b\u305f\u76ee\u3092\u30b9\u30e9\u30a4\u30e0\u306b\u3059\u308b\u8a2d\u5b9a\u304c\u30e4\u30d0\u3059\u304e\u308b\uff57\uff57\uff57\u3010\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30ef\u30a4\u30eb\u30ba\u3011<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"c5Go2VLy4zc\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=c5Go2VLy4zc\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/c5Go2VLy4zc\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u8718\u86db\u6050\u6016\u75c7\u6bba\u3057\u3059\u304e\u308b\u7121\u6570\u306e\u8718\u86db\u3010Monster Hunter Wilds(\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30ef\u30a4\u30eb\u30ba)\u3011#shorts<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"u8Q2wXHJHDs\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=u8Q2wXHJHDs\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/u8Q2wXHJHDs\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u866b\u5acc\u3044\u767a\u72c2\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba\u3010\u73e0\u4e43\u4e95\u30ca\u30ca \/ \u306b\u3058\u3055\u3093\u3058\u3011#shorts #\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"FdG0zNZ-VzM\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=FdG0zNZ-VzM\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/FdG0zNZ-VzM\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u307e\u3068\u3082\u306b\u899a\u3048\u3089\u308c\u3066\u306a\u3044\u30ab\u30bf\u30ab\u30ca\u30e2\u30f3\u30b9\u30bf\u30fc\u9054 #shorts #\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"-AjV8_jNYZg\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=-AjV8_jNYZg\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/-AjV8_jNYZg\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u30e2\u30f3\u30cf\u30f3\u30e9\u30a4\u30ba1000\u6642\u9593\u3084\u3063\u3066\u521d\u3081\u3066\u6c17\u3065\u3044\u305f\u4ed5\u69d8 #shorts<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"fFKkPizA5kU\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=fFKkPizA5kU\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/fFKkPizA5kU\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u3010\u30cd\u30bf\u30d0\u30ec\u6ce8\u610f\uff01\u3011\u7e04\u5f35\u308a\u306b\u4fb5\u5165\u3059\u308b\u3079\u304b\u3089\u305a\u3010\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30ef\u30a4\u30eb\u30ba\u3011\u3010MHWilds\u30112\u72e9\u308a\u76ee<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"Cwp4nWUp7LE\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=Cwp4nWUp7LE\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/Cwp4nWUp7LE\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u30ca\u30eb\u30ac\u30af\u30eb\u30ac\u5e0c\u5c11\u7a2e\u3068\u5bfe\u5cd9\u3059\u308b\u30e6\u30af\u30e2\u6751\u306e\u82f1\u96c4\u3002\u3010MHR:SB\u3011#shorts<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"6wGq1qHPAM4\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=6wGq1qHPAM4\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/6wGq1qHPAM4\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u3010\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba\u3011\u82e6\u624b\u306a\u30e2\u30f3\u30b9\u30bf\u30fc\u3067\u7d76\u53eb\u3057\u3066\u308b\u73e0\u4e43\u4e95\u30ca\u30ca\u307e\u3068\u3081\u3010\u306b\u3058\u3055\u3093\u3058\u5207\u308a\u629c\u304d\uff0f\u73e0\u4e43\u4e95\u30ca\u30ca\u3011\u3010\u30b3\u30e1\u30f3\u30c8\u3042\u308a\u3011<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n\n<div class=\"youtube-set\">\n  <a class=\"\" data-video-id=\"VXFU3Af5Dcc\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=VXFU3Af5Dcc\">\n    <span><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/i.ytimg.com\/vi\/VXFU3Af5Dcc\/hqdefault.jpg\" width=\"480\" height=\"360\" loading=\"lazy\"\/><\/span>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba  \u30be\u30b7\u30a2  \u5bfe\u7b56 \u88c5\u5099  \u5263\u58eb\u7528 \u30d2\u30fc\u30e9\u30fc\u3000\u65e9\u98df\u3044 \u5e83\u57df\u5316 \u6e80\u8db3\u611f \u3067\u30d1\u30fc\u30c6\u30a3\u3092\u30b5\u30dd\u30fc\u30c8! \u3000\u30b9\u30e9\u30a2\u30af\u3082\uff2f\uff2b\u266a\u518d\u751f\u306e \u88c5\u8863\u3000\u7b2c\u4e00\u5f3e\u3000\u30a2\u30d7\u30c7\u3000\u30be\u30fb\u30b7\u30a2 \u653b\u7565\u7528\u3000\u592a\u5200\u3000\u5927\u5263\u3000\u30ac\u30f3\u30e9\u30f3\u30b9<\/div>\n    <\/div>\n  <\/a>\n<\/div>\n\n\n<\/div>\n<p class=\"text-center text-ss text-weak\">YouTube DATA API\u3067\u81ea\u52d5\u53d6\u5f97\u3057\u305f\u52d5\u753b\u3092\u8868\u793a\u3057\u3066\u3044\u307e\u3059<\/p><div class=\"text-center\"><div class=\"btn-base btn-rounded btn-fill btn-lightblue btn-s btn-full  btn-icon-right fa-arrow-right\" ><a href=\"https:\/\/gamepedia.jp\/mh-wilds\/items\" data-no-auto-affiliate=\"1\">\u30a2\u30a4\u30c6\u30e0\u30fb\u7d20\u6750\u691c\u7d22\u30c4\u30fc\u30eb\u3078<\/a><\/div><\/div>","protected":false},"author":37,"featured_media":0,"menu_order":5125,"comment_status":"open","ping_status":"closed","template":"","meta":{"event_start_date":[""],"event_end_date":[""],"external_thumbnail_url":"https:\/\/images.gamepedia.jp\/mh-wilds\/item_icon\/180.png","redirect":"","last_comment_date":"","footnotes":""},"item_maps":"","item_category":"\u88c5\u5099\u7d20\u6750","item_category_2":"","class_list":["post-5096","item","type-item","status-publish","hentry","item_category-131"],"long_title":"\u3010\u30e2\u30f3\u30cf\u30f3\u30ef\u30a4\u30eb\u30ba\u3011\u523a\u82b1\u8718\u86db\u306e\u5c3e\u68d8\u306e\u4f7f\u3044\u9053\u30fb\u5165\u624b\u65b9\u6cd5\u3010\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u3011","user":"qaasession","str_count":0,"category_name":"","tag_name":"","is_pr":false,"pr_mode":null,"hide_ad":false,"comment_count":0,"original_content":"","site_name":"\u30e2\u30f3\u30b9\u30bf\u30fc\u30cf\u30f3\u30bf\u30fc\u30ef\u30a4\u30eb\u30ba","is_valid_post_type":true,"is_password_required":false,"thumbnail_url":"https:\/\/images.gamepedia.jp\/mh-wilds\/item_icon\/180.png","_links":{"self":[{"href":"https:\/\/gamepedia.jp\/mh-wilds\/wp-json\/wp\/v2\/items\/5096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gamepedia.jp\/mh-wilds\/wp-json\/wp\/v2\/items"}],"about":[{"href":"https:\/\/gamepedia.jp\/mh-wilds\/wp-json\/wp\/v2\/types\/item"}],"author":[{"embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-wilds\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-wilds\/wp-json\/wp\/v2\/comments?post=5096"}],"version-history":[{"count":1,"href":"https:\/\/gamepedia.jp\/mh-wilds\/wp-json\/wp\/v2\/items\/5096\/revisions"}],"predecessor-version":[{"id":9459,"href":"https:\/\/gamepedia.jp\/mh-wilds\/wp-json\/wp\/v2\/items\/5096\/revisions\/9459"}],"wp:attachment":[{"href":"https:\/\/gamepedia.jp\/mh-wilds\/wp-json\/wp\/v2\/media?parent=5096"}],"wp:term":[{"taxonomy":"item_maps","embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-wilds\/wp-json\/wp\/v2\/item_maps?post=5096"},{"taxonomy":"item_category","embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-wilds\/wp-json\/wp\/v2\/item_category?post=5096"},{"taxonomy":"item_category_2","embeddable":true,"href":"https:\/\/gamepedia.jp\/mh-wilds\/wp-json\/wp\/v2\/item_category_2?post=5096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}