{"id":13609,"date":"2018-11-09T17:06:48","date_gmt":"2018-11-09T08:06:48","guid":{"rendered":"https:\/\/gamepedia.jp\/splatoon2\/gears\/13609"},"modified":"2018-11-09T17:06:48","modified_gmt":"2018-11-09T08:06:48","slug":"%e3%81%b2%e3%82%8c%e3%81%8a%e3%81%8f%e3%82%93%e3%81%ae%e3%81%a6","status":"publish","type":"gear","link":"https:\/\/gamepedia.jp\/splatoon2\/gears\/13609","title":{"rendered":"\u3010\u30b9\u30d7\u30e9\u30c8\u30a5\u30fc\u30f32\u3011\u300c\u3072\u308c\u304a\u304f\u3093\u306e\u3066\u300d\u306e\u5165\u624b\u65b9\u6cd5\u3001\u7279\u5fb4\u3001\u30ae\u30a2\u30d1\u30ef\u30fc"},"content":{"rendered":"<div class=\"row\"><div class=\"col-sm-4\">\n\n<img decoding=\"async\" class=\"\" style=\"max-width:200px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2018\/11\/11231848\/82BA4C06-935E-42B9-A065-14D8AC0A3B39.jpeg\" width=\"\" height=\"\" loading=\"lazy\"\/>\n<\/div><div class=\"col-sm-8\">\n\n<h3  class=\"\">\u3072\u308c\u304a\u304f\u3093\u306e\u3066<\/h3>\n<div><small>\u5206\u985e<\/small>\n\n<a class=\"btn btn-terms-link  btn-terms btn-gear_type btn-gear_type-\u30d5\u30af\" href=\"https:\/\/gamepedia.jp\/splatoon2\/gears?gear_type=%e3%83%95%e3%82%af\">\u30d5\u30af<\/a>\n<\/div><div><small><i class=\"fa fa-star\"><\/i>\u30e9\u30f3\u30af<\/small> 2<\/div><\/div><\/div><hr class=\"spacer-5\"><div class=\"\" style=\"\"><\/div>\n\n<h2  class=\"headline\">\u3072\u308c\u304a\u304f\u3093\u306e\u3066\u306e\u30ae\u30a2\u30d1\u30ef\u30fc<\/h2>\n<ul class=\"media-list image-list \">\n  <div>\n<a href=\"https:\/\/gamepedia.jp\/splatoon2\/abilities\/1437\">\n  <div class=\"media media-ability\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234941\/ability-10.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2017\u5e747\u670810\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\u30d1\u30ef\u30fc\">\u30ae\u30a2\u30d1\u30ef\u30fc<\/span>\n                \n\n\n        \n\n      <\/div>\n            <div class=\"media-desc\">\n        <div class=\"note-white\">\u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u306e\u6642\u9593\u304c\u77ed\u304f\u306a\u308a\u307e\u3059\u3002<\/div>      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n  <\/div>\n<\/ul>\n\n\n<h3  class=\"\">\u3072\u308c\u304a\u304f\u3093\u306e\u3066\u306e\u30d6\u30e9\u30f3\u30c9<\/h3>\n<ul class=\"media-list image-list \">\n  <div>\n<a href=\"https:\/\/gamepedia.jp\/splatoon2\/brands\/2312\">\n  <div class=\"media media-brand\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234803\/2017072119275100-C616B031331154665D639EF16DA76BC0-2.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        amiibo      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2017\u5e747\u670822\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u30d6\u30e9\u30f3\u30c9\">\u30d6\u30e9\u30f3\u30c9<\/span>\n                \n\n\n        \n\n      <\/div>\n            <div class=\"media-desc\">\n        <div class=\"note-white\"><div class=\"margin-bottom-5\"><small>\u3064\u304d\u3084\u3059\u3044<\/small> \u306a\u3057<\/div><div><small>\u3064\u304d\u306b\u304f\u3044<\/small> \u306a\u3057<\/div><\/div>      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n  <\/div>\n<\/ul>\n\n<h2  class=\"headline\">\u3072\u308c\u304a\u304f\u3093\u306e\u3066\u306e\u5165\u624b\u65b9\u6cd5<\/h2>\n<div class=\"note-white\"><strong>amiibo<\/strong><div><\/div><\/div>\n\n<h3  class=\"headline\"><span class=\"hidden-xs\">\u3072\u308c\u304a\u304f\u3093\u306e\u3066\u306e<\/span>\u95a2\u9023\u8a18\u4e8b<\/h3>\n<ul class=\"media-list image-list \">\n  <div>\n<a href=\"https:\/\/gamepedia.jp\/splatoon2\/archives\/2159\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234834\/2017072023064400-C616B031331154665D639EF16DA76BC0-480x270.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30a2\u30df\u30fc\u30dcamiibo\u3067\u3082\u3089\u3048\u308b\u30ae\u30a2\u307e\u3068\u3081\uff01\uff12\u3064\u76ee\u4ee5\u964d\u306e\u3082\u3089\u3044\u65b9\u3082\u89e3\u8aac      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2022\u5e747\u670821\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u304a\u5f79\u7acb\u3061\">\u304a\u5f79\u7acb\u3061<\/span>\n                <span class=\"label label-default label-category label-category-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-amiibo\">amiibo<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u30b9\u30d7\u30e9\u30c8\u30a5\u30fc\u30f32\u3067\u5bfe\u5fdc\u3057\u3066\u3044\u308bamiibo\u3092\u30b2\u30fc\u30e0\u4e2d\u3067\u8aad\u307f\u8fbc\u3080\u3068\u30aa\u30ea\u30b8\u30ca\u30eb\u30ae\u30a2\u3092\u3082\u3089...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/gamepedia.jp\/splatoon2\/archives\/10464\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2018\/06\/11233219\/DfhcmfmU8AA_Pqm-large-480x270.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        amiibo\u30b9\u30d7\u30e9\u30c8\u30a5\u30fc\u30f3\u30b7\u30ea\u30fc\u30ba\u306b3\u7a2e\u306e\u30bf\u30b3\u65b0\u4f5c\u304c\u767b\u5834\uff01\u3055\u3089\u306b\u6c17\u306b\u306a\u308b\u30a4\u30f3\u30af\u30ea\u30f3\u30b0\u3082\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2018\u5e747\u670821\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30cb\u30e5\u30fc\u30b9\">\u30cb\u30e5\u30fc\u30b9<\/span>\n                <span class=\"label label-default label-category label-category-\u95a2\u9023\u30b0\u30c3\u30ba\">\u95a2\u9023\u30b0\u30c3\u30ba<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-amiibo\">amiibo<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        amiibo\u306e\u30b9\u30d7\u30e9\u30c8\u30a5\u30fc\u30f3\u30b7\u30ea\u30fc\u30ba\u304b\u3089\u65b0\u4f5c\u306e\u767a\u58f2\u304c\u6c7a\u5b9a\u3057\u307e\u3057\u305f\uff01\r\n\u8a18\u4e8b\uff1achiro\r\n\u30aa...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n    <\/div>\n    <div class=\"nav-more\" style=\"margin-top:10px;\">\n        <a class=\"btn btn-nav-more hide-me\" data-toggle=\"collapse\" href=\"#collapse-image-list-image-list-727952185\">\u3082\u3063\u3068\u898b\u308b<\/a>\n    <\/div>\n    <div id=\"collapse-image-list-image-list-727952185\" class=\"collapse\">\n<a href=\"https:\/\/gamepedia.jp\/splatoon2\/archives\/11328\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2018\/07\/11232830\/1A50D9DB-090B-401C-9570-83409E270E8B-426x480.jpeg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30c6\u30f3\u30bf\u30af\u30eb\u30ba(\u30a4\u30a4\u30c0\u30fb\u30d2\u30e1)\u306eamiibo\u3067\u3067\u304d\u308b\u3053\u3068\uff01\u9650\u5b9a\u30ae\u30a2\u306e\u8cb0\u3044\u65b9\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2018\u5e747\u670815\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u304a\u5f79\u7acb\u3061\">\u304a\u5f79\u7acb\u3061<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-amiibo\">amiibo<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        7\u670813\u65e5\u306b\u767a\u58f2\u3055\u308c\u305f\u30c6\u30f3\u30bf\u30af\u30eb\u30ba(\u30d2\u30e1\u30fb\u30a4\u30a4\u30c0)\u306eamiibo\u306b\u306f\u697d\u3057\u3044\u6a5f\u80fd\u304c\u305f\u304f\u3055\u3093...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/gamepedia.jp\/splatoon2\/archives\/9786\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2018\/03\/11233531\/6ED877D3-78EB-4085-8C75-72CFC035291C-480x270.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        Ver3.0\u8ffd\u52a0\u306e\u65b0\u30ae\u30a2\u4e00\u89a7\uff01\u5168113\u7a2e\u3092\u4e00\u6319\u306b\u7d39\u4ecb\uff01\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2018\u5e744\u670825\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30a2\u30c3\u30d7\u30c7\u30fc\u30c8\">\u30a2\u30c3\u30d7\u30c7\u30fc\u30c8<\/span>\n                <span class=\"label label-default label-category label-category-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                <span class=\"label label-default label-post_tag label-post_tag-\u30a2\u30c3\u30d7\u30c7\u30fc\u30c8Ver3.0\">\u30a2\u30c3\u30d7\u30c7\u30fc\u30c8Ver3.0<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u30a2\u30c3\u30d7\u30c7\u30fc\u30c8Ver3.0\u3067\u8ffd\u52a0\u3055\u308c\u305f\u65b0\u30ae\u30a2\u4e00\u89a7\u3067\u3059\uff01\r\n\r\n\u5168\u90e8\u3067113\u7a2e\u304c\u78ba\u8a8d\u3055\u308c\u3066\u3044\u307e...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/gamepedia.jp\/splatoon2\/archives\/8554\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2018\/02\/11233601\/6F059C06-F747-4B36-B0D5-B0EE605BFA8C-480x270.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30c6\u30f3\u30bf\u30af\u30eb\u30ba(\u30d2\u30e1\/\u30a4\u30a4\u30c0)\u306eamiibo\u4e88\u7d04\u958b\u59cb\uff01\u767a\u58f2\u65e5\u306a\u3069\u8a73\u7d30\u306f\uff1f      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2018\u5e743\u67089\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30cb\u30e5\u30fc\u30b9\">\u30cb\u30e5\u30fc\u30b9<\/span>\n                <span class=\"label label-default label-category label-category-\u95a2\u9023\u30b0\u30c3\u30ba\">\u95a2\u9023\u30b0\u30c3\u30ba<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-amiibo\">amiibo<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u30d5\u30a1\u30f3\u5f85\u671b\u306eamiibo\u304c\u767a\u58f2\u6c7a\u5b9a\u3067\u3059\uff01\r\n\r\n\r\n\u9b45\u60d1\u306e\u66f2\u7dda\u7f8e\uff01\r\n\u6570\u3042\u308bamiibom\u306e\u4e2d\u3067\u3082...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/gamepedia.jp\/splatoon2\/archives\/6920\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/11\/11233841\/28BE25F5-55C1-448D-AFD0-3DE5BAEA45C6-433x480.jpeg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30b3\u30ed\u30b3\u30ed1\u6708\u53f7\u4e88\u544a\u52d5\u753b\u304c\u516c\u958b\uff01\u9650\u5b9a\u30a8\u30f3\u30da\u30e9\u30fc\u30ae\u30a2\u304c\u3082\u3089\u3048\u308b\u30b7\u30ea\u30a2\u30eb\u30b3\u30fc\u30c9\u3092\u5165\u624b\u3057\u3088\u3046\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2017\u5e7412\u67089\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30cb\u30e5\u30fc\u30b9\">\u30cb\u30e5\u30fc\u30b9<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u30aa\u30ea\u30b8\u30ca\u30eb\u30ae\u30a2\">\u30aa\u30ea\u30b8\u30ca\u30eb\u30ae\u30a2<\/span>\n                <span class=\"label label-default label-post_tag label-post_tag-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                <span class=\"label label-default label-post_tag label-post_tag-\u30b3\u30ed\u30b3\u30ed\">\u30b3\u30ed\u30b3\u30ed<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u30b3\u30ed\u30b3\u30ed\uff11\uff12\u6708\u53f7\u3067\u30b9\u30d7\u30e9\u30c8\u30a5\u30fc\u30f3\uff12\u306e\u9650\u5b9a\u30ae\u30a2\u306b\u95a2\u3059\u308b\u60c5\u5831\u304c\u516c\u958b\u3055\u308c\u307e\u3057\u305f\u3002\r\n...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/gamepedia.jp\/splatoon2\/archives\/6494\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/10\/11233917\/IMG_2295-480x270.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30b9\u30d1\u30a4\u30ad\u30fc\u306e\u4e0a\u624b\u306a\u4f7f\u3044\u65b9\uff01\u6ce8\u6587\u3068\u8cb7\u3044\u306e\u30b3\u30c4\u3092\u77e5\u3063\u3066\u76ee\u6307\u305b\u6700\u5f37\u30ae\u30a2\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2017\u5e7410\u670822\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u304a\u5f79\u7acb\u3061\">\u304a\u5f79\u7acb\u3061<\/span>\n                <span class=\"label label-default label-category label-category-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u30ae\u30a2\u30d1\u30ef\u30fc\">\u30ae\u30a2\u30d1\u30ef\u30fc<\/span>\n                <span class=\"label label-default label-post_tag label-post_tag-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                <span class=\"label label-default label-post_tag label-post_tag-\u30b9\u30d1\u30a4\u30ad\u30fc\">\u30b9\u30d1\u30a4\u30ad\u30fc<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u5e83\u5834\u306b\u3044\u308b\u30b9\u30d1\u30a4\u30ad\u30fc\u3001\u3057\u3063\u304b\u308a\u3068\u4f7f\u3048\u3066\u3044\u307e\u3059\u304b\uff1f\r\n\u540c\u3058\u304f\u5e83\u5834\u306b\u3044\u308b\u30a4\u30ab\u305f\u3061\u304c...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/gamepedia.jp\/splatoon2\/archives\/2611\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234702\/IMG_1297-480x270.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30ae\u30a2\u30d1\u30ef\u30fc\u3068\u306f\uff1f\u30b9\u30ed\u30c3\u30c8\u306e\u89e3\u653e\u6761\u4ef6\u306f\uff1f\u30b9\u30d1\u30a4\u30ad\u30fc\u306e\u304a\u5e97\u3067\u51fa\u6765\u308b\u3053\u3068\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2017\u5e749\u67084\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u304a\u5f79\u7acb\u3061\">\u304a\u5f79\u7acb\u3061<\/span>\n                <span class=\"label label-default label-category label-category-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u30ae\u30a2\u30d1\u30ef\u30fc\">\u30ae\u30a2\u30d1\u30ef\u30fc<\/span>\n                <span class=\"label label-default label-post_tag label-post_tag-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                <span class=\"label label-default label-post_tag label-post_tag-\u30b9\u30d1\u30a4\u30ad\u30fc\">\u30b9\u30d1\u30a4\u30ad\u30fc<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u307f\u306a\u3055\u3093\u3053\u3093\u306b\u3061\u306f\uff01\u30e9\u30a4\u30bf\u30fcchiro\u3067\u3059(^ ^)\r\n\u3053\u308c\u3092\u66f8\u3044\u3066\u3044\u308b\u6642\u70b9\u3067\u3084\u3063\u3068\u30e9\u30f3...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/gamepedia.jp\/splatoon2\/archives\/4768\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/08\/11234220\/DH2bdmCUMAEthYb-480x270.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        S+\u9054\u6210\u3057\u305f\u7b46\u8005\u306e\u304a\u3059\u3059\u3081\u30ae\u30a2\u69cb\u6210\u3092\u7d39\u4ecb\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2017\u5e748\u670827\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u304a\u5f79\u7acb\u3061\">\u304a\u5f79\u7acb\u3061<\/span>\n                <span class=\"label label-default label-category label-category-\u30a6\u30c7\u30de\u30a8X\u653b\u7565\">\u30a6\u30c7\u30de\u30a8X\u653b\u7565<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u30ae\u30a2\u30d1\u30ef\u30fc\">\u30ae\u30a2\u30d1\u30ef\u30fc<\/span>\n                <span class=\"label label-default label-post_tag label-post_tag-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u30ac\u30c1\u30de\u30c3\u30c1S+\u306b\u5230\u9054\u3057\u305f\u7b46\u8005\u304c\u3001\u30ac\u30c1\u30de\u30c3\u30c1\u3067\u6d3b\u7528\u3057\u3066\u3044\u308b\u30ae\u30a2\u306e\u7d39\u4ecb\u3067\u3059\uff01\u53c2\u8003\u7a0b...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/gamepedia.jp\/splatoon2\/archives\/4034\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/08\/11234334\/IMG_0201-480x270.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30ae\u30a2\u3092\u53b3\u9078\u3057\u3088\u3046\uff01\u597d\u307f\u306e\u30ae\u30a2\u30d1\u30ef\u30fc\u69cb\u6210\u3092\u4f5c\u308b\u65b9\u6cd5\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2017\u5e748\u67081\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u304a\u5f79\u7acb\u3061\">\u304a\u5f79\u7acb\u3061<\/span>\n                <span class=\"label label-default label-category label-category-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u30ae\u30a2\u30d1\u30ef\u30fc\">\u30ae\u30a2\u30d1\u30ef\u30fc<\/span>\n                <span class=\"label label-default label-post_tag label-post_tag-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                <span class=\"label label-default label-post_tag label-post_tag-\u30ae\u30a2\u30d1\u30ef\u30fc\u306e\u304b\u3051\u3089\">\u30ae\u30a2\u30d1\u30ef\u30fc\u306e\u304b\u3051\u3089<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u30a2\u30bf\u30de\u3001\u30d5\u30af\u3001\u30af\u30c4\u3068\uff13\u3064\u306b\u5206\u304b\u308c\u3066\u3044\u308b\u30ae\u30a2\u3002\r\n\u3053\u306e\u30ae\u30a2\u306b\u521d\u3081\u304b\u3089\u4ed8\u3044\u3066\u3044\u308b\u5927...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n  <\/div>\n<\/ul>\n\n<h2  class=\"headline\">\u305d\u306e\u4ed6\u306e\u30ae\u30a2<\/h2>\n\n\n<h3  class=\"\">\u30d5\u30af\u306e\u30ae\u30a2\u4e00\u89a7<\/h3>\n<ul class=\"media-list image-grid row embeds archive-list\">\n  <div>\n  \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/4646\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/08\/11234235\/2017081321114500-C616B031331154665D639EF16DA76BC0.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        FA-01\u30a6\u30e9              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234941\/ability-10.jpg\" \/> \u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11230301\/d50bb4418585e5fd9431efebd05f2c7d.png\" \/> \u30d5\u30a9\u30fc\u30ea\u30de<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/4149\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/08\/11234321\/2017072701494500-C616B031331154665D639EF16DA76BC0.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        FA-01\u30aa\u30e2\u30c6              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234942\/ability-3.jpg\" \/> \u30a4\u30f3\u30af\u56de\u5fa9\u529b\u30a2\u30c3\u30d7<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11230301\/d50bb4418585e5fd9431efebd05f2c7d.png\" \/> \u30d5\u30a9\u30fc\u30ea\u30de<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/4636\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/08\/11234237\/2017080701021800-C616B031331154665D639EF16DA76BC0.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        FC\u30ab\u30e9\u30b9\u30df              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11230301\/713cffe0edbdd1367ee0c22560bacc27.png\" \/> \u30e4\u30b3<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/5262\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2018\/04\/11233356\/2018040519552600-C616B031331154665D639EF16DA76BC0_result.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30a2\u30fc\u30d0\u30f3\u30d9\u30b9\u30c8 \u30a4\u30a8\u30ed\u30fc              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234939\/ability-20.jpg\" \/> \u30ea\u30d9\u30f3\u30b8<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234816\/IMG_5954.jpg\" \/> \u30db\u30c3\u30b3\u30ea\u30fc<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/2988\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234514\/gear-27.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30a2\u30fc\u30d0\u30f3\u30d9\u30b9\u30c8 \u30ca\u30a4\u30c8              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2019\/02\/11231509\/Unknown-2.jpeg\" \/> \u7206\u98a8\u30c0\u30e1\u30fc\u30b8\u8efd\u6e1b\u30fb\u6539<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234816\/IMG_5954.jpg\" \/> \u30db\u30c3\u30b3\u30ea\u30fc<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/3691\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234401\/2017072615004600-C616B031331154665D639EF16DA76BC0-1.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30a2\u30fc\u30de\u30fc\u30b8\u30e3\u30b1\u30c3\u30c8 \u30ec\u30d7\u30ea\u30ab              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234941\/ability-6.jpg\" \/> \u30b9\u30da\u30b7\u30e3\u30eb\u5897\u52a0\u91cf\u30a2\u30c3\u30d7<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234400\/4f63220a06faea5d58148b2c20521b5a.png\" \/> \u30a2\u30bf\u30ea\u30e1\u30a4\u30c9<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n            <div class=\"clearfix hidden-xs\" ><\/div>\n        <\/div>\n<\/ul>\n<hr class=\"spacer-5\" >\n<div class=\"nav-more\">\n<a class=\"btn btn-nav-more \" href=\"https:\/\/gamepedia.jp\/splatoon2\/gears?gear_type=%e3%83%95%e3%82%af\" target=\"\" >\n    \u30d5\u30af\u306e\u30ae\u30a2\u4e00\u89a7\u3092\u3082\u3063\u3068\u898b\u308b<\/a>\n<\/div>\n\n\n\n<h3  class=\"\">\u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e\u306e\u30ae\u30a2\u4e00\u89a7<\/h3>\n<ul class=\"media-list image-grid row embeds archive-list\">\n  <div>\n  \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/4180\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/08\/11234315\/2017080108165700-C616B031331154665D639EF16DA76BC0.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30a4\u30ab\u30f3\u30ab\u30f3              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234941\/ability-10.jpg\" \/> \u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234510\/70e1ed128fc368565ccfe336faba0488.png\" \/> \u30db\u30bf\u30c3\u30af\u30b9<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/2293\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234806\/2017072119270100-C616B031331154665D639EF16DA76BC0-1.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30b5\u30e0\u30e9\u30a4\u30d8\u30eb\u30e1\u30c3\u30c8              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234941\/ability-10.jpg\" \/> \u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234803\/2017072119275100-C616B031331154665D639EF16DA76BC0-2.jpg\" \/> amiibo<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/4175\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/08\/11234317\/2017073100585300-C616B031331154665D639EF16DA76BC0.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30dc\u30f3\u30dc\u30f3\u30cb\u30c3\u30c8              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234941\/ability-10.jpg\" \/> \u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11230301\/e19ee00b8f98788898e2c5e52619ad3f.png\" \/> \u30b8\u30e2\u30f3<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/4144\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/08\/11234322\/2017072701493500-C616B031331154665D639EF16DA76BC0.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30e4\u30b3\u30d0\u30a4\u30b6\u30fc              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234941\/ability-10.jpg\" \/> \u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11230301\/713cffe0edbdd1367ee0c22560bacc27.png\" \/> \u30e4\u30b3<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/4646\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/08\/11234235\/2017081321114500-C616B031331154665D639EF16DA76BC0.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        FA-01\u30a6\u30e9              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234941\/ability-10.jpg\" \/> \u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11230301\/d50bb4418585e5fd9431efebd05f2c7d.png\" \/> \u30d5\u30a9\u30fc\u30ea\u30de<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/4642\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/08\/11234235\/2017080918503800-C616B031331154665D639EF16DA76BC0.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30d0\u30cb\u30fc\u30dd\u30c3\u30d7 \u30d6\u30e9\u30c3\u30af              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234941\/ability-10.jpg\" \/> \u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234816\/IMG_5951.jpg\" \/> \u30a8\u30be\u30c3\u30b3<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n            <div class=\"clearfix hidden-xs\" ><\/div>\n        <\/div>\n<\/ul>\n<hr class=\"spacer-5\" >\n<div class=\"nav-more\">\n<a class=\"btn btn-nav-more \" href=\"https:\/\/gamepedia.jp\/splatoon2\/gears?gear_ability=%e3%82%b9%e3%83%bc%e3%83%91%e3%83%bc%e3%82%b8%e3%83%a3%e3%83%b3%e3%83%97%e6%99%82%e9%96%93%e7%9f%ad%e7%b8%ae\" target=\"\" >\n    \u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e\u306e\u30ae\u30a2\u4e00\u89a7\u3092\u3082\u3063\u3068\u898b\u308b<\/a>\n<\/div>\n\n\n\n<h3  class=\"\">amiibo\u306e\u30ae\u30a2\u4e00\u89a7<\/h3>\n<ul class=\"media-list image-grid row embeds archive-list\">\n  <div>\n  \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/2296\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234805\/2017072119271000-C616B031331154665D639EF16DA76BC0-1.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30a4\u30ab\u30ab\u30b2\u30de\u30b9\u30af              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234941\/ability-9.jpg\" \/> \u5fa9\u6d3b\u6642\u9593\u77ed\u7e2e<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234803\/2017072119275100-C616B031331154665D639EF16DA76BC0-2.jpg\" \/> amiibo<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/2292\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234806\/2017072119265800-C616B031331154665D639EF16DA76BC0-1.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30a4\u30ab\u30af\u30ea\u30c3\u30d7              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234939\/ability-15.jpg\" \/> \u30b9\u30bf\u30fc\u30c8\u30c0\u30c3\u30b7\u30e5<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234803\/2017072119275100-C616B031331154665D639EF16DA76BC0-2.jpg\" \/> amiibo<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/2297\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234805\/2017072119271400-C616B031331154665D639EF16DA76BC0-1.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30a4\u30ab\u30d1\u30c3\u30c1\u30f3              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234941\/ability-5.jpg\" \/> \u30a4\u30ab\u30c0\u30c3\u30b7\u30e5\u901f\u5ea6\u30a2\u30c3\u30d7<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234803\/2017072119275100-C616B031331154665D639EF16DA76BC0-2.jpg\" \/> amiibo<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/2293\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234806\/2017072119270100-C616B031331154665D639EF16DA76BC0-1.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30b5\u30e0\u30e9\u30a4\u30d8\u30eb\u30e1\u30c3\u30c8              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234941\/ability-10.jpg\" \/> \u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234803\/2017072119275100-C616B031331154665D639EF16DA76BC0-2.jpg\" \/> amiibo<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/2294\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234806\/2017072119270400-C616B031331154665D639EF16DA76BC0-1.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30d1\u30ef\u30fc\u30c9\u30de\u30b9\u30af              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234803\/2017072119275100-C616B031331154665D639EF16DA76BC0-2.jpg\" \/> amiibo<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\/2295\">\n    <div class=\"media media-gear media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234805\/2017072119270800-C616B031331154665D639EF16DA76BC0-1.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u30ae\u30a2\">\u30ae\u30a2<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30d1\u30ef\u30fc\u30c9\u30de\u30b9\u30af \u30aa\u30ea\u30b8\u30f3              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234940\/ability-12.jpg\" \/> \u76f8\u624b\u30a4\u30f3\u30af\u5f71\u97ff\u8efd\u6e1b<\/div><hr class=\"margin-5\"><div><img decoding=\"async\" style=\"width:30px;height:30px;\" src=\"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2017\/07\/11234803\/2017072119275100-C616B031331154665D639EF16DA76BC0-2.jpg\" \/> amiibo<\/div><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n            <div class=\"clearfix hidden-xs\" ><\/div>\n        <\/div>\n<\/ul>\n<hr class=\"spacer-5\" >\n<div class=\"nav-more\">\n<a class=\"btn btn-nav-more \" href=\"https:\/\/gamepedia.jp\/splatoon2\/gears?gear_brand=amiibo\" target=\"\" >\n    amiibo\u306e\u30ae\u30a2\u4e00\u89a7\u3092\u3082\u3063\u3068\u898b\u308b<\/a>\n<\/div>\n\n\n\n<h3  class=\"headline\">\u3082\u3063\u3068\u30d6\u30ad\u3092\u63a2\u3059<\/h3>\n<div class=\"menu-two-column\">\n<ul class=\"menu\">\n    <li class=\"menu-item menu-item-has-children\">\n    <ul class=\"sub-menu\" style=\"padding-left:0;\">\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/weapons?weapon_type=\u30b7\u30e5\u30fc\u30bf\u30fc\">\u30b7\u30e5\u30fc\u30bf\u30fc<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/weapons?weapon_type=\u30ed\u30fc\u30e9\u30fc\">\u30ed\u30fc\u30e9\u30fc<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/weapons?weapon_type=\u30c1\u30e3\u30fc\u30b8\u30e3\u30fc\">\u30c1\u30e3\u30fc\u30b8\u30e3\u30fc<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/weapons?weapon_type=\u30d6\u30e9\u30b9\u30bf\u30fc\">\u30d6\u30e9\u30b9\u30bf\u30fc<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/weapons?weapon_type=\u30b9\u30ed\u30c3\u30b7\u30e3\u30fc\">\u30b9\u30ed\u30c3\u30b7\u30e3\u30fc<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/weapons?weapon_type=\u30b9\u30d4\u30ca\u30fc\">\u30b9\u30d4\u30ca\u30fc<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/weapons?weapon_type=\u30d5\u30c7\">\u30d5\u30c7<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/weapons?weapon_type=\u30b7\u30a7\u30eb\u30bf\u30fc\">\u30b7\u30a7\u30eb\u30bf\u30fc<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/sub-weapons\">\u30b5\u30d6\u30a6\u30a7\u30dd\u30f3<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/special-weapons\">\u30b9\u30da\u30b7\u30e3\u30eb\u30a6\u30a7\u30dd\u30f3<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/gears\">\u30ae\u30a2<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/abilities\">\u30ae\u30a2\u30d1\u30ef\u30fc<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/brands\">\u30d6\u30e9\u30f3\u30c9<\/a><\/li>\n    <li class=\"menu-item\" ><a href=\"https:\/\/gamepedia.jp\/splatoon2\/stages\">\u30b9\u30c6\u30fc\u30b8<\/a><\/li>\n    <\/ul>\n    <\/li>\n<\/ul>\n<\/div>\n\n<div style=\"padding:5px 10px;\">\n  <h4>\u30c7\u30fc\u30bf\u3092\u691c\u7d22<\/h4>\n  <form action=\"https:\/\/gamepedia.jp\/splatoon2\/\" >\n    <div class=\"input-group\" >\n      <input type=\"hidden\" value=\"weapon\" name=\"post_type\">\n      <input type=\"search\" value=\"\" name=\"s\" class=\"search-field form-control\" placeholder=\"\u30ad\u30fc\u30ef\u30fc\u30c9\u691c\u7d22\" required=\"\">\n      <span class=\"input-group-btn\">\n        <button type=\"submit\" class=\"search-submit btn btn-search\">\u691c\u7d22<\/button>\n      <\/span>\n    <\/div>\n  <\/form>\n<\/div>\n\n","protected":false},"author":4,"featured_media":13582,"menu_order":527,"comment_status":"open","ping_status":"closed","template":"","meta":{"event_start_date":[],"event_end_date":[],"external_thumbnail_url":"","redirect":"","last_comment_date":"","footnotes":"","name":"\u3072\u308c\u304a\u304f\u3093\u306e\u3066","type":"\u30d5\u30af","brand":"amiibo","ability":"\u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e"},"gear_type":"\u30d5\u30af","gear_ability":"\u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e","gear_brand":"amiibo","gear_feature":"","gear_version":"","class_list":["post-13609","gear","type-gear","status-publish","has-post-thumbnail","hentry","gear_type-72","gear_ability-100","gear_brand-amiibo"],"long_title":"\u3010\u30b9\u30d7\u30e9\u30c8\u30a5\u30fc\u30f32\u3011\u300c\u3072\u308c\u304a\u304f\u3093\u306e\u3066\u300d\u306e\u5165\u624b\u65b9\u6cd5\u3001\u7279\u5fb4\u3001\u30ae\u30a2\u30d1\u30ef\u30fc","user":"chiro","str_count":0,"category_name":"","tag_name":"","is_pr":false,"pr_mode":null,"hide_ad":false,"comment_count":0,"original_content":"","site_name":"\u30b9\u30d7\u30e9\u30c8\u30a5\u30fc\u30f32","is_valid_post_type":true,"is_password_required":false,"thumbnail_url":"https:\/\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/sites\/48\/2018\/11\/11231848\/82BA4C06-935E-42B9-A065-14D8AC0A3B39.jpeg","name":"\u3072\u308c\u304a\u304f\u3093\u306e\u3066","meta_type":"","brand":"amiibo","ability":"\u30b9\u30fc\u30d1\u30fc\u30b8\u30e3\u30f3\u30d7\u6642\u9593\u77ed\u7e2e","_links":{"self":[{"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/gears\/13609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/gears"}],"about":[{"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/types\/gear"}],"author":[{"embeddable":true,"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/comments?post=13609"}],"version-history":[{"count":0,"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/gears\/13609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/media\/13582"}],"wp:attachment":[{"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/media?parent=13609"}],"wp:term":[{"taxonomy":"gear_type","embeddable":true,"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/gear_type?post=13609"},{"taxonomy":"gear_ability","embeddable":true,"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/gear_ability?post=13609"},{"taxonomy":"gear_brand","embeddable":true,"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/gear_brand?post=13609"},{"taxonomy":"gear_feature","embeddable":true,"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/gear_feature?post=13609"},{"taxonomy":"gear_version","embeddable":true,"href":"https:\/\/gamepedia.jp\/splatoon2\/wp-json\/wp\/v2\/gear_version?post=13609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}